{"id":13131,"date":"2026-04-27T13:39:03","date_gmt":"2026-04-27T18:39:03","guid":{"rendered":"https:\/\/www.repam.net\/es\/?p=13131"},"modified":"2026-04-27T13:39:05","modified_gmt":"2026-04-27T18:39:05","slug":"tres-principios-claves-en-la-transicion","status":"publish","type":"post","link":"https:\/\/www.repam.net\/es\/tres-principios-claves-en-la-transicion\/","title":{"rendered":"Soberan\u00eda, autonom\u00eda y justicia, tres principios claves en la transici\u00f3n energ\u00e9tica"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-27-at-1.22.45-PM-edited.jpeg\" alt=\"\" class=\"wp-image-13133\" srcset=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-27-at-1.22.45-PM-edited.jpeg 1280w, https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-27-at-1.22.45-PM-edited-300x169.jpeg 300w, https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-27-at-1.22.45-PM-edited-1024x576.jpeg 1024w, https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-27-at-1.22.45-PM-edited-768x432.jpeg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n<\/div>\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>Durante la Conferencia \u201cTerritorios Libres de Combustibles F\u00f3siles\u201d la Red Eclesial Panamaz\u00f3nica (REPAM) pudo manifestar su sentir y posici\u00f3n respecto al tema. Ximena Lombana, secretaria ejecutiva de la red, dej\u00f3 en claro una serie de principios a considerar en los procesos de transici\u00f3n energ\u00e9tica. Tener en cuenta estos principios y derechos de los pueblos es el punto de partida en este proceso tan necesario.<\/em><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Por: Equipo de Comunicaciones de REPAM<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el marco de la <em>I Conferencia Internacional para la Transici\u00f3n m\u00e1s all\u00e1 de los Combustibles F\u00f3siles, <\/em>se desarrollaron una serie de eventos en los que, instituciones de la sociedad civil, movimientos sociales, redes de trabajo y organismos eclesiales reflexionaron sobre una serie de aspectos a considerar en este tipo de escenarios. Por parte de la REPAM, se dej\u00f3 una posici\u00f3n firme sobre este proceso que se adelanta en varios sitios del planeta <em>\u201c\u2026como REPAM, consideramos que hay tres principios esenciales la autonom\u00eda, la soberan\u00eda y la justicia, para garantizar que la transici\u00f3n energ\u00e9tica no profundice desigualdades<\/em>\u201d, afirm\u00f3 Ximena Lombana, secretaria ejecutiva de REPAM, durante la conferencia <em>Territorios Libres de Combustibles F\u00f3siles.<\/em><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Contextos y derechos<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Dar pasos hacia la transici\u00f3n energ\u00e9tica conlleva una serie de responsabilidades por parte de los gobiernos, las poblaciones y las entidades involucradas. Desde la mirada de la REPAM, se entiende que, para hablar de un territorio libre de combustibles f\u00f3siles, no es solo referirse al petr\u00f3leo, sino de todas las din\u00e1micas, problem\u00e1ticas y potencias de los territorios. En palabras de la Secretaria Ejecutiva de REPAM: <em>\u201cEn la selva, siempre se habla desde la pobreza y como REPAM, consideramos que es un empobrecimiento realizado por parte del modelo que ha imperado y saqueado nuestra querida Amazon\u00eda\u201d. <\/em>A pesar de las cifras que pueden presentarse sobre el avance de la transici\u00f3n energ\u00e9tica, es v\u00e1lido argumentar que en la mayor\u00eda de los casos desconocen perspectivas y derechos propios de los pueblos, que resultan necesarios para la verdadera justicia e igualdad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, referirse a la autonom\u00eda, la soberan\u00eda y la justicia como principios claves de la transici\u00f3n energ\u00e9tica es fundamental en un proceso global que, bajo la bandera de la protecci\u00f3n del medio ambiente y la vida, sigue teniendo intereses econ\u00f3micos por encima de los derechos de los pueblos. Es v\u00e1lido resaltar que, desde la autonom\u00eda, los pueblos tienen derecho a decir <em>\u201cNo\u201d, <\/em>un principio que refuerza las condiciones de soberan\u00eda y justicia, realza el valor de procesos como la consulta previa y reivindica el derecho de los pueblos a decidir sobre el actuar dentro de un espacio con el que conviven y relacionan.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Hacia una mirada global<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Ximena Lombana, como portavoz de la REPAM dej\u00f3 un interrogante para analizar y considerar dentro del proceso de transici\u00f3n: <em>\u00bfC\u00f3mo desde un enfoque de cuencas, de biomas y de fronteras podr\u00edamos hacer planeaci\u00f3n regional territorial? y que los esfuerzos de todos los que tenemos trabajo en distintas partes del territorio, se unan en una sola mirada, de la Amazon\u00eda, de toda Am\u00e9rica Latina y el Caribe como territorios de agua. <\/em>Y es que, como bien se sabe, los proyectos de extracci\u00f3n de hidrocarburos e infraestructura regional tienden a ser transnacionales. Entonces, <em>\u201c\u00bfc\u00f3mo cambiamos nuestras l\u00f3gicas a esa mirada regional, amparada en los principios de autonom\u00eda y al derecho a decir No?\u201d, <\/em>pregunt\u00f3 la Secretaria Ejecutiva de REPAM a los presentes en el panel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A manera de conclusi\u00f3n y proyectando acciones necesarias, la REPAM propone ante el escenario de transici\u00f3n actual que: se reclamen instrumentos internacionales, jur\u00eddicamente vinculables que regulen la producci\u00f3n y suministro de combustibles f\u00f3siles, que determinen obligaciones y medios de sanci\u00f3n concretos, que regulen y estructuren la participaci\u00f3n y la toma de decisi\u00f3n de los pueblos, que permitan una eliminaci\u00f3n progresiva y planificada y que prevengan que los costos de los mismos recaigan sobre quienes no son responsables de los da\u00f1os y que resultan ser los m\u00e1s vulnerables. Adem\u00e1s, se deja en claro la necesidad de los mecanismos para la protecci\u00f3n de quienes cuidan y defienden la vida; y que, sin soberan\u00eda alimentaria, energ\u00e9tica e h\u00eddrica no podemos hablar de territorios libres de combustibles f\u00f3siles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la Conferencia \u201cTerritorios Libres de Combustibles F\u00f3siles\u201d la Red Eclesial Panamaz\u00f3nica (REPAM) pudo manifestar su sentir y posici\u00f3n respecto al tema. Ximena Lombana, secretaria ejecutiva de la red, dej\u00f3 en claro una serie de principios a considerar en los procesos de transici\u00f3n energ\u00e9tica. Tener en cuenta estos principios y derechos de los pueblos es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13133,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[4],"tags":[33,122,52,1016,9],"class_list":["post-13131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-amazonia","tag-colombia","tag-derechos-humanos","tag-ecologia-integral-2","tag-repam"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Soberan\u00eda, autonom\u00eda y justicia, tres principios claves en la transici\u00f3n energ\u00e9tica - REPAM<\/title>\n<meta name=\"description\" content=\"Durante la Conferencia \u201cTerritorios Libres de Combustibles F\u00f3siles\u201d la Red Eclesial Panamaz\u00f3nica (REPAM) pudo manifestar su sentir y posici\u00f3n respecto al tema. Ximena Lombana, secretaria ejecutiva de la red, dej\u00f3 en claro una serie de principios a considerar en los procesos de transici\u00f3n energ\u00e9tica. Tener en cuenta ciertos principios y derechos de los pueblos es el punto de partida en este proceso tan necesario.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repam.net\/es\/tres-principios-claves-en-la-transicion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soberan\u00eda, autonom\u00eda y justicia, tres principios claves en la transici\u00f3n energ\u00e9tica - REPAM\" \/>\n<meta property=\"og:description\" content=\"Durante la Conferencia \u201cTerritorios Libres de Combustibles F\u00f3siles\u201d la Red Eclesial Panamaz\u00f3nica (REPAM) pudo manifestar su sentir y posici\u00f3n respecto al tema. Ximena Lombana, secretaria ejecutiva de la red, dej\u00f3 en claro una serie de principios a considerar en los procesos de transici\u00f3n energ\u00e9tica. Tener en cuenta ciertos principios y derechos de los pueblos es el punto de partida en este proceso tan necesario.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repam.net\/es\/tres-principios-claves-en-la-transicion\/\" \/>\n<meta property=\"og:site_name\" content=\"REPAM\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-27T18:39:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T18:39:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-27-at-1.22.45-PM-edited.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"repam@adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repam@adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/tres-principios-claves-en-la-transicion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/tres-principios-claves-en-la-transicion\\\/\"},\"author\":{\"name\":\"repam@adm\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\"},\"headline\":\"Soberan\u00eda, autonom\u00eda y justicia, tres principios claves en la transici\u00f3n energ\u00e9tica\",\"datePublished\":\"2026-04-27T18:39:03+00:00\",\"dateModified\":\"2026-04-27T18:39:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/tres-principios-claves-en-la-transicion\\\/\"},\"wordCount\":753,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/tres-principios-claves-en-la-transicion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/WhatsApp-Image-2026-04-27-at-1.22.45-PM-edited.jpeg\",\"keywords\":[\"Amazon\u00eda\",\"Colombia\",\"Derechos Humanos\",\"Ecolog\u00eda Integral\",\"REPAM\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/tres-principios-claves-en-la-transicion\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/tres-principios-claves-en-la-transicion\\\/\",\"name\":\"Soberan\u00eda, autonom\u00eda y justicia, tres principios claves en la transici\u00f3n energ\u00e9tica - REPAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/tres-principios-claves-en-la-transicion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/tres-principios-claves-en-la-transicion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/WhatsApp-Image-2026-04-27-at-1.22.45-PM-edited.jpeg\",\"datePublished\":\"2026-04-27T18:39:03+00:00\",\"dateModified\":\"2026-04-27T18:39:05+00:00\",\"description\":\"Durante la Conferencia \u201cTerritorios Libres de Combustibles F\u00f3siles\u201d la Red Eclesial Panamaz\u00f3nica (REPAM) pudo manifestar su sentir y posici\u00f3n respecto al tema. Ximena Lombana, secretaria ejecutiva de la red, dej\u00f3 en claro una serie de principios a considerar en los procesos de transici\u00f3n energ\u00e9tica. Tener en cuenta ciertos principios y derechos de los pueblos es el punto de partida en este proceso tan necesario.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/tres-principios-claves-en-la-transicion\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repam.net\\\/es\\\/tres-principios-claves-en-la-transicion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/tres-principios-claves-en-la-transicion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/WhatsApp-Image-2026-04-27-at-1.22.45-PM-edited.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/WhatsApp-Image-2026-04-27-at-1.22.45-PM-edited.jpeg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/tres-principios-claves-en-la-transicion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soberan\u00eda, autonom\u00eda y justicia, tres principios claves en la transici\u00f3n energ\u00e9tica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"name\":\"REPAM\",\"description\":\"Red Eclesial Panamaz\u00f3nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repam.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\",\"name\":\"REPAM\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"REPAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\",\"name\":\"repam@adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"caption\":\"repam@adm\"},\"sameAs\":[\"http:\\\/\\\/repam.net\"],\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/author\\\/repamadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soberan\u00eda, autonom\u00eda y justicia, tres principios claves en la transici\u00f3n energ\u00e9tica - REPAM","description":"Durante la Conferencia \u201cTerritorios Libres de Combustibles F\u00f3siles\u201d la Red Eclesial Panamaz\u00f3nica (REPAM) pudo manifestar su sentir y posici\u00f3n respecto al tema. Ximena Lombana, secretaria ejecutiva de la red, dej\u00f3 en claro una serie de principios a considerar en los procesos de transici\u00f3n energ\u00e9tica. Tener en cuenta ciertos principios y derechos de los pueblos es el punto de partida en este proceso tan necesario.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repam.net\/es\/tres-principios-claves-en-la-transicion\/","og_locale":"es_ES","og_type":"article","og_title":"Soberan\u00eda, autonom\u00eda y justicia, tres principios claves en la transici\u00f3n energ\u00e9tica - REPAM","og_description":"Durante la Conferencia \u201cTerritorios Libres de Combustibles F\u00f3siles\u201d la Red Eclesial Panamaz\u00f3nica (REPAM) pudo manifestar su sentir y posici\u00f3n respecto al tema. Ximena Lombana, secretaria ejecutiva de la red, dej\u00f3 en claro una serie de principios a considerar en los procesos de transici\u00f3n energ\u00e9tica. Tener en cuenta ciertos principios y derechos de los pueblos es el punto de partida en este proceso tan necesario.","og_url":"https:\/\/www.repam.net\/es\/tres-principios-claves-en-la-transicion\/","og_site_name":"REPAM","article_published_time":"2026-04-27T18:39:03+00:00","article_modified_time":"2026-04-27T18:39:05+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-27-at-1.22.45-PM-edited.jpeg","type":"image\/jpeg"}],"author":"repam@adm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"repam@adm","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repam.net\/es\/tres-principios-claves-en-la-transicion\/#article","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/tres-principios-claves-en-la-transicion\/"},"author":{"name":"repam@adm","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033"},"headline":"Soberan\u00eda, autonom\u00eda y justicia, tres principios claves en la transici\u00f3n energ\u00e9tica","datePublished":"2026-04-27T18:39:03+00:00","dateModified":"2026-04-27T18:39:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repam.net\/es\/tres-principios-claves-en-la-transicion\/"},"wordCount":753,"publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"image":{"@id":"https:\/\/www.repam.net\/es\/tres-principios-claves-en-la-transicion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-27-at-1.22.45-PM-edited.jpeg","keywords":["Amazon\u00eda","Colombia","Derechos Humanos","Ecolog\u00eda Integral","REPAM"],"articleSection":["Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.repam.net\/es\/tres-principios-claves-en-la-transicion\/","url":"https:\/\/www.repam.net\/es\/tres-principios-claves-en-la-transicion\/","name":"Soberan\u00eda, autonom\u00eda y justicia, tres principios claves en la transici\u00f3n energ\u00e9tica - REPAM","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repam.net\/es\/tres-principios-claves-en-la-transicion\/#primaryimage"},"image":{"@id":"https:\/\/www.repam.net\/es\/tres-principios-claves-en-la-transicion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-27-at-1.22.45-PM-edited.jpeg","datePublished":"2026-04-27T18:39:03+00:00","dateModified":"2026-04-27T18:39:05+00:00","description":"Durante la Conferencia \u201cTerritorios Libres de Combustibles F\u00f3siles\u201d la Red Eclesial Panamaz\u00f3nica (REPAM) pudo manifestar su sentir y posici\u00f3n respecto al tema. Ximena Lombana, secretaria ejecutiva de la red, dej\u00f3 en claro una serie de principios a considerar en los procesos de transici\u00f3n energ\u00e9tica. Tener en cuenta ciertos principios y derechos de los pueblos es el punto de partida en este proceso tan necesario.","breadcrumb":{"@id":"https:\/\/www.repam.net\/es\/tres-principios-claves-en-la-transicion\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repam.net\/es\/tres-principios-claves-en-la-transicion\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/tres-principios-claves-en-la-transicion\/#primaryimage","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-27-at-1.22.45-PM-edited.jpeg","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-27-at-1.22.45-PM-edited.jpeg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.repam.net\/es\/tres-principios-claves-en-la-transicion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repam.net\/es\/"},{"@type":"ListItem","position":2,"name":"Soberan\u00eda, autonom\u00eda y justicia, tres principios claves en la transici\u00f3n energ\u00e9tica"}]},{"@type":"WebSite","@id":"https:\/\/www.repam.net\/es\/#website","url":"https:\/\/www.repam.net\/es\/","name":"REPAM","description":"Red Eclesial Panamaz\u00f3nica","publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repam.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.repam.net\/es\/#organization","name":"REPAM","url":"https:\/\/www.repam.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","width":512,"height":512,"caption":"REPAM"},"image":{"@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033","name":"repam@adm","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","caption":"repam@adm"},"sameAs":["http:\/\/repam.net"],"url":"https:\/\/www.repam.net\/es\/author\/repamadm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/13131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/comments?post=13131"}],"version-history":[{"count":1,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/13131\/revisions"}],"predecessor-version":[{"id":13134,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/13131\/revisions\/13134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media\/13133"}],"wp:attachment":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media?parent=13131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/categories?post=13131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/tags?post=13131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}