{"id":13325,"date":"2026-06-25T15:37:37","date_gmt":"2026-06-25T20:37:37","guid":{"rendered":"https:\/\/www.repam.net\/es\/?p=13325"},"modified":"2026-06-30T15:56:19","modified_gmt":"2026-06-30T20:56:19","slug":"secretaria-de-repam-en-caqueta","status":"publish","type":"post","link":"https:\/\/www.repam.net\/es\/secretaria-de-repam-en-caqueta\/","title":{"rendered":"La secretar\u00eda ejecutiva de la REPAM participa de espacios de acci\u00f3n y reflexi\u00f3n en el Caquet\u00e1"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.42.11-AM-edited.jpeg\" alt=\"\" class=\"wp-image-13327\" srcset=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.42.11-AM-edited.jpeg 1280w, https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.42.11-AM-edited-300x169.jpeg 300w, https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.42.11-AM-edited-1024x576.jpeg 1024w, https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.42.11-AM-edited-768x432.jpeg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n<\/div>\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>Durante la semana del 14 al 17 de junio, la secretaria ejecutiva de REPAM, tuvo la oportunidad de participar en el Encuentro Regional de las Comisiones por la Vida del Agua del Sur del Caquet\u00e1; proceso eclesial que por m\u00e1s de 10 a\u00f1os ha promovido la defensa y cuidado del territorio amaz\u00f3nico en el marco del extractivismo minero energ\u00e9tico.<\/em><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Por: Equipo de Comunicaciones de REPAM<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este Encuentro fue una oportunidad para recordar el proceso de resistencia campesina contra la actividad petrolera y conocer los logros alcanzados, especialmente en el marco de la implementaci\u00f3n del Bloque El Nogal por parte de la Empresa Emerald Energy y conocer el estado actual del proceso; en este sentido, celebrar la suspensi\u00f3n de la licencia ambiental.&nbsp; Tambi\u00e9n conocer los avances del proceso de la Red de Conservacionistas de Semillas Nativas y Criollas, como apuesta por la soberan\u00eda alimentaria y alternativas comunitarias al desarrollo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El equipo de la secretar\u00eda pudo compartir la propuesta del III ciclo de la REPAM 2026 &#8211; 2030, realizar un ejercicio de escucha y dialogo para identificar necesidades e intereses estrat\u00e9gicos, aspectos de trabajo conjunto para poder prestar un mejor servicio a los territorios y responder de forma m\u00e1s eficiente a las realidades que afectan la poblaci\u00f3n campesina y el agua en la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, se dio espacio para analizar los programas de gobierno de los dos candidatos a la presidencia de Colombia, para promover un voto informado y consciente. Conocer y ver caminos de incidencia en torno al Decreto 0960 de 2025, como el reconocimiento de las Comisiones y comisionados como gestores del agua para poder incidir en la implementaci\u00f3n local del Decreto, que favorece la Gesti\u00f3n Comunitaria del Agua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El d\u00eda 18 de junio, se realiz\u00f3 una reuni\u00f3n con el presidente y el secretario ejecutivo de la REPAM en Colombia: Monse\u00f1or Omar de Jes\u00fas Mej\u00eda y Elkin Rodr\u00edguez, junto con el vicepresidente de la REPAM, padre Julio Caldeira; en la que a trav\u00e9s de un di\u00e1logo fraterno se conocieron los principales aspectos de los procesos en Colombia y en el \u00e1mbito panamaz\u00f3nico y encontrar puntos de trabajo comunes para impulsar la Red y su servicio a los territorios.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"960\" src=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.45.55-AM-edited.jpeg\" alt=\"\" class=\"wp-image-13329\" srcset=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.45.55-AM-edited.jpeg 960w, https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.45.55-AM-edited-300x300.jpeg 300w, https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.45.55-AM-edited-150x150.jpeg 150w, https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.45.55-AM-edited-768x768.jpeg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"963\" height=\"963\" src=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.42.58-AM-edited.jpeg\" alt=\"\" class=\"wp-image-13331\" srcset=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.42.58-AM-edited.jpeg 963w, https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.42.58-AM-edited-300x300.jpeg 300w, https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.42.58-AM-edited-150x150.jpeg 150w, https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.42.58-AM-edited-768x768.jpeg 768w\" sizes=\"auto, (max-width: 963px) 100vw, 963px\" \/><\/figure>\n<\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Durante la semana del 14 al 17 de junio, la secretaria ejecutiva de REPAM, tuvo la oportunidad de participar en el Encuentro Regional de las Comisiones por la Vida del Agua del Sur del Caquet\u00e1; proceso eclesial que por m\u00e1s de 10 a\u00f1os ha promovido la defensa y cuidado del territorio amaz\u00f3nico en el marco [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13327,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[4],"tags":[33,122,8,9],"class_list":["post-13325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-amazonia","tag-colombia","tag-querida-amazonia","tag-repam"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La secretar\u00eda ejecutiva de la REPAM participa de espacios de acci\u00f3n y reflexi\u00f3n en el Caquet\u00e1 - REPAM<\/title>\n<meta name=\"description\" content=\"Durante la semana del 14 al 17 de junio, la secretaria ejecutiva de REPAM, tuvo la oportunidad de participar en el Encuentro Regional de las Comisiones por la Vida del Agua del Sur del Caquet\u00e1; proceso eclesial que por m\u00e1s de 10 a\u00f1os ha promovido la defensa y cuidado del territorio amaz\u00f3nico en el marco del extractivismo minero energ\u00e9tico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repam.net\/es\/secretaria-de-repam-en-caqueta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La secretar\u00eda ejecutiva de la REPAM participa de espacios de acci\u00f3n y reflexi\u00f3n en el Caquet\u00e1 - REPAM\" \/>\n<meta property=\"og:description\" content=\"Durante la semana del 14 al 17 de junio, la secretaria ejecutiva de REPAM, tuvo la oportunidad de participar en el Encuentro Regional de las Comisiones por la Vida del Agua del Sur del Caquet\u00e1; proceso eclesial que por m\u00e1s de 10 a\u00f1os ha promovido la defensa y cuidado del territorio amaz\u00f3nico en el marco del extractivismo minero energ\u00e9tico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repam.net\/es\/secretaria-de-repam-en-caqueta\/\" \/>\n<meta property=\"og:site_name\" content=\"REPAM\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-25T20:37:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-30T20:56:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.42.11-AM-edited.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"repam@adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repam@adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/secretaria-de-repam-en-caqueta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/secretaria-de-repam-en-caqueta\\\/\"},\"author\":{\"name\":\"repam@adm\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\"},\"headline\":\"La secretar\u00eda ejecutiva de la REPAM participa de espacios de acci\u00f3n y reflexi\u00f3n en el Caquet\u00e1\",\"datePublished\":\"2026-06-25T20:37:37+00:00\",\"dateModified\":\"2026-06-30T20:56:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/secretaria-de-repam-en-caqueta\\\/\"},\"wordCount\":396,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/secretaria-de-repam-en-caqueta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-23-at-11.42.11-AM-edited.jpeg\",\"keywords\":[\"Amazon\u00eda\",\"Colombia\",\"Querida Amazon\u00eda\",\"REPAM\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/secretaria-de-repam-en-caqueta\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/secretaria-de-repam-en-caqueta\\\/\",\"name\":\"La secretar\u00eda ejecutiva de la REPAM participa de espacios de acci\u00f3n y reflexi\u00f3n en el Caquet\u00e1 - REPAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/secretaria-de-repam-en-caqueta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/secretaria-de-repam-en-caqueta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-23-at-11.42.11-AM-edited.jpeg\",\"datePublished\":\"2026-06-25T20:37:37+00:00\",\"dateModified\":\"2026-06-30T20:56:19+00:00\",\"description\":\"Durante la semana del 14 al 17 de junio, la secretaria ejecutiva de REPAM, tuvo la oportunidad de participar en el Encuentro Regional de las Comisiones por la Vida del Agua del Sur del Caquet\u00e1; proceso eclesial que por m\u00e1s de 10 a\u00f1os ha promovido la defensa y cuidado del territorio amaz\u00f3nico en el marco del extractivismo minero energ\u00e9tico.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/secretaria-de-repam-en-caqueta\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repam.net\\\/es\\\/secretaria-de-repam-en-caqueta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/secretaria-de-repam-en-caqueta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-23-at-11.42.11-AM-edited.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-23-at-11.42.11-AM-edited.jpeg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/secretaria-de-repam-en-caqueta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La secretar\u00eda ejecutiva de la REPAM participa de espacios de acci\u00f3n y reflexi\u00f3n en el Caquet\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"name\":\"REPAM\",\"description\":\"Red Eclesial Panamaz\u00f3nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repam.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\",\"name\":\"REPAM\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"REPAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\",\"name\":\"repam@adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"caption\":\"repam@adm\"},\"sameAs\":[\"http:\\\/\\\/repam.net\"],\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/author\\\/repamadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La secretar\u00eda ejecutiva de la REPAM participa de espacios de acci\u00f3n y reflexi\u00f3n en el Caquet\u00e1 - REPAM","description":"Durante la semana del 14 al 17 de junio, la secretaria ejecutiva de REPAM, tuvo la oportunidad de participar en el Encuentro Regional de las Comisiones por la Vida del Agua del Sur del Caquet\u00e1; proceso eclesial que por m\u00e1s de 10 a\u00f1os ha promovido la defensa y cuidado del territorio amaz\u00f3nico en el marco del extractivismo minero energ\u00e9tico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repam.net\/es\/secretaria-de-repam-en-caqueta\/","og_locale":"es_ES","og_type":"article","og_title":"La secretar\u00eda ejecutiva de la REPAM participa de espacios de acci\u00f3n y reflexi\u00f3n en el Caquet\u00e1 - REPAM","og_description":"Durante la semana del 14 al 17 de junio, la secretaria ejecutiva de REPAM, tuvo la oportunidad de participar en el Encuentro Regional de las Comisiones por la Vida del Agua del Sur del Caquet\u00e1; proceso eclesial que por m\u00e1s de 10 a\u00f1os ha promovido la defensa y cuidado del territorio amaz\u00f3nico en el marco del extractivismo minero energ\u00e9tico.","og_url":"https:\/\/www.repam.net\/es\/secretaria-de-repam-en-caqueta\/","og_site_name":"REPAM","article_published_time":"2026-06-25T20:37:37+00:00","article_modified_time":"2026-06-30T20:56:19+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.42.11-AM-edited.jpeg","type":"image\/jpeg"}],"author":"repam@adm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"repam@adm","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repam.net\/es\/secretaria-de-repam-en-caqueta\/#article","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/secretaria-de-repam-en-caqueta\/"},"author":{"name":"repam@adm","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033"},"headline":"La secretar\u00eda ejecutiva de la REPAM participa de espacios de acci\u00f3n y reflexi\u00f3n en el Caquet\u00e1","datePublished":"2026-06-25T20:37:37+00:00","dateModified":"2026-06-30T20:56:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repam.net\/es\/secretaria-de-repam-en-caqueta\/"},"wordCount":396,"publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"image":{"@id":"https:\/\/www.repam.net\/es\/secretaria-de-repam-en-caqueta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.42.11-AM-edited.jpeg","keywords":["Amazon\u00eda","Colombia","Querida Amazon\u00eda","REPAM"],"articleSection":["Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.repam.net\/es\/secretaria-de-repam-en-caqueta\/","url":"https:\/\/www.repam.net\/es\/secretaria-de-repam-en-caqueta\/","name":"La secretar\u00eda ejecutiva de la REPAM participa de espacios de acci\u00f3n y reflexi\u00f3n en el Caquet\u00e1 - REPAM","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repam.net\/es\/secretaria-de-repam-en-caqueta\/#primaryimage"},"image":{"@id":"https:\/\/www.repam.net\/es\/secretaria-de-repam-en-caqueta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.42.11-AM-edited.jpeg","datePublished":"2026-06-25T20:37:37+00:00","dateModified":"2026-06-30T20:56:19+00:00","description":"Durante la semana del 14 al 17 de junio, la secretaria ejecutiva de REPAM, tuvo la oportunidad de participar en el Encuentro Regional de las Comisiones por la Vida del Agua del Sur del Caquet\u00e1; proceso eclesial que por m\u00e1s de 10 a\u00f1os ha promovido la defensa y cuidado del territorio amaz\u00f3nico en el marco del extractivismo minero energ\u00e9tico.","breadcrumb":{"@id":"https:\/\/www.repam.net\/es\/secretaria-de-repam-en-caqueta\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repam.net\/es\/secretaria-de-repam-en-caqueta\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/secretaria-de-repam-en-caqueta\/#primaryimage","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.42.11-AM-edited.jpeg","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-23-at-11.42.11-AM-edited.jpeg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.repam.net\/es\/secretaria-de-repam-en-caqueta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repam.net\/es\/"},{"@type":"ListItem","position":2,"name":"La secretar\u00eda ejecutiva de la REPAM participa de espacios de acci\u00f3n y reflexi\u00f3n en el Caquet\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/www.repam.net\/es\/#website","url":"https:\/\/www.repam.net\/es\/","name":"REPAM","description":"Red Eclesial Panamaz\u00f3nica","publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repam.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.repam.net\/es\/#organization","name":"REPAM","url":"https:\/\/www.repam.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","width":512,"height":512,"caption":"REPAM"},"image":{"@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033","name":"repam@adm","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","caption":"repam@adm"},"sameAs":["http:\/\/repam.net"],"url":"https:\/\/www.repam.net\/es\/author\/repamadm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/13325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/comments?post=13325"}],"version-history":[{"count":1,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/13325\/revisions"}],"predecessor-version":[{"id":13332,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/13325\/revisions\/13332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media\/13327"}],"wp:attachment":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media?parent=13325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/categories?post=13325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/tags?post=13325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}