{"id":2331,"date":"2020-05-04T00:00:00","date_gmt":"2020-05-04T05:00:00","guid":{"rendered":"http:\/\/repam.net\/obispos-de-la-amazonia-brasilena-covid-19\/"},"modified":"2020-05-04T00:00:00","modified_gmt":"2020-05-04T05:00:00","slug":"obispos-de-la-amazonia-brasilena-covid-19","status":"publish","type":"post","link":"https:\/\/www.repam.net\/es\/obispos-de-la-amazonia-brasilena-covid-19\/","title":{"rendered":"Obispos de la Amazon\u00eda brasile\u00f1a exigen medidas urgentes de los gobiernos para combatir el COVID-19"},"content":{"rendered":"<p>Ante la situaci\u00f3n de la pandemia del COVID-19 en la Amazon\u00eda, 67 obispos de la Amazon\u00eda brasile\u00f1a firman una nota p\u00fablica divulgada en la ma\u00f1ana del lunes, 4 de mayo. En el texto, liderado por la Comisi\u00f3n Episcopal Especial para la Amazon\u00eda de la CNBB (Conferencia Nacional de los Obispos de Brasil), ellos convocan la Iglesia y de toda la Sociedad para exigir medidas urgentes del Gobierno Federal, del Congreso Nacional, de los Gobiernos Estatales y de las Asambleas Legislativas.<\/p>\n<p><a href=\"http:\/\/repam.org.br\/wp-content\/uploads\/2020\/05\/Nota-Comissao-Amazonia-ESP.pdf\">Nota Comissao Amazonia \u2013 ESPA\u00d1OL<\/a><\/p>\n<p><a href=\"http:\/\/repam.org.br\/wp-content\/uploads\/2020\/05\/Nota-Comissao-Amazonia-PORT.pdf\">Nota Comiss\u00e3o Amaz\u00f4nia \u2013 PORTUGU\u00caS<\/a><\/p>\n<p><a href=\"http:\/\/repam.org.br\/wp-content\/uploads\/2020\/05\/Nota-Comissao-Amazonia-TUKANO.pdf\">Nota Comissao Amazonia \u2013 TUKANO<\/a><\/p>\n<p><a href=\"http:\/\/repam.org.br\/wp-content\/uploads\/2020\/05\/Nota-Comissao-Amazonia-FRA.pdf\">Nota Comisi\u00f3n Amazon\u00eda \u2013 FRANC\u00caS<\/a><\/p>\n<p><a href=\"http:\/\/repam.org.br\/wp-content\/uploads\/2020\/05\/Nota-Comiss%C3%A3o-Amaz%C3%B4nia-ITA.pdf\">Nota Comiss\u00e3o Amaz\u00f4nia \u2013 ITALIANO<\/a><\/p>\n<p><a href=\"http:\/\/repam.org.br\/wp-content\/uploads\/2020\/05\/Nota-Comissao-Amazonia-ING.pdf\">Nota Comissao Amazonia INGL\u00caS<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Mire aqu\u00ed la nota completa:<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>NOTA DE LOS OBISPOS DE LA AMAZONIA BRASILE\u00d1A SOBRE LA SITUACI\u00d3N DE LOS PUEBLOS Y EL BOSQUE EN TIEMPOS DE PANDEMIA DE COVID-19<\/strong><\/p>\n<p style=\"text-align: right;\">&#8220;A los emprendimientos que da\u00f1an la Amazonia hay que ponerles<\/p>\n<p style=\"text-align: right;\">los nombres que les corresponde: injusticia y crimen&#8221;<\/p>\n<p style=\"text-align: right;\">&#8220;Es necesario indignarse&#8221;<\/p>\n<p style=\"text-align: right;\">(Papa Francisco &#8211; Querida Amazona, 14-15).<\/p>\n<p>Nosotros, obispos de la Amazon\u00eda, ante el avance incontrolado del COVID-19 en Brasil, especialmente en la Amazon\u00eda, expresamos nuestra inmensa preocupaci\u00f3n y exigimos una mayor atenci\u00f3n de los gobiernos federales y estatales a esta enfermedad que se est\u00e1 extendiendo cada vez m\u00e1s en esta regi\u00f3n. Los pueblos de la Amazon\u00eda exigen especial atenci\u00f3n de las autoridades para que sus vidas no sean violadas. La tasa de mortalidad es una de las m\u00e1s altas del pa\u00eds y la sociedad ya est\u00e1 presenciando el colapso de los sistemas de salud en las principales ciudades, como Manaos y Bel\u00e9m.\u00a0Las estad\u00edsticas proporcionadas por los medios de comunicaci\u00f3n no se corresponden con la realidad. Las pruebas son insuficientes para conocer la expansi\u00f3n real del virus. Muchas personas con s\u00edntomas evidentes de la enfermedad mueren en casa sin asistencia m\u00e9dica y sin acceso a un hospital.<\/p>\n<p>Frente a este escenario de pandemia, corresponde a las autoridades p\u00fablicas implementar estrategias de atenci\u00f3n responsable para los sectores de poblaci\u00f3n m\u00e1s vulnerables. Los pueblos ind\u00edgenas, los afrodescendientes y otras comunidades tradicionales corren un gran riesgo, que tambi\u00e9n se extiende al bosque, dado el importante papel de estas comunidades en su conservaci\u00f3n.<\/p>\n<p>Los datos son alarmantes: la regi\u00f3n tiene la proporci\u00f3n m\u00e1s baja de hospitales en el pa\u00eds, con baja y alta complejidad (solo 10%). Grandes \u00e1reas del territorio amaz\u00f3nico no cuentan con camas de UCI y solo unos pocos municipios cumplen con los requisitos m\u00ednimos recomendados por la Organizaci\u00f3n Mundial de la Salud (OMS), en n\u00famero de camas y UCIs por habitante (10 camas de UCI por cada 100 mil usuarios).<\/p>\n<p>Adem\u00e1s de los pueblos del bosque, las poblaciones urbanas, especialmente en las periferias, est\u00e1n expuestas y sus condiciones de vida se degradan a\u00fan m\u00e1s por la falta de saneamiento b\u00e1sico, vivienda, alimentaci\u00f3n y empleo. Son migrantes, refugiados, pueblos ind\u00edgenas urbanos, trabajadores industriales, trabajadoras dom\u00e9sticas, personas que viven del trabajo informal y que piden protecci\u00f3n de la salud. Es obligaci\u00f3n del Estado garantizar los derechos establecidos en la Constituci\u00f3n Federal ofreciendo condiciones m\u00ednimas para que puedan superar este grave momento.<\/p>\n<p>La miner\u00eda de oro, la miner\u00eda y la deforestaci\u00f3n para el monocultivo de soja y la ganader\u00eda para la exportaci\u00f3n han aumentado de manera alarmante en los \u00faltimos a\u00f1os. Seg\u00fan el sistema Deter-B, desarrollado por el Instituto Nacional de Investigaci\u00f3n Espacial (Inpe), la deforestaci\u00f3n en la selva amaz\u00f3nica creci\u00f3 un 29,9% en marzo de 2020, en comparaci\u00f3n con el mismo mes del a\u00f1o pasado. Contribuy\u00f3 a este crecimiento, la notable reducci\u00f3n de las inspecciones y el continuo discurso pol\u00edtico del gobierno federal contra la protecci\u00f3n del medio ambiente y las \u00e1reas ind\u00edgenas protegidas por la Constituci\u00f3n Federal (Art. 231 y 232). El coronavirus que nos est\u00e1 atormentando ahora y la crisis socio ambiental ya est\u00e1n mostrando una gran tragedia humanitaria causada por un colapso estructural. <span style=\"color: var(--vamtam-primary-font-color); letter-spacing: var(--vamtam-primary-font-letter-spacing,normal);\">Con la Amazon\u00eda cada vez m\u00e1s devastada, las sucesivas pandemias ser\u00e1n a\u00fan peores que la que e<\/span>stamos experimentando actualmente.<\/p>\n<p>Estamos extremadamente preocupados por el aumento de la violencia en el campo, un 23% m\u00e1s que en 2018. En 2019, el 84% de los asesinatos (27 de 32) y el 73% de los intentos de asesinato (22 de 30) tuvieron lugar en la Amazon\u00eda, seg\u00fan los datos del \u201cCuaderno de Conflictos en el Campo Brasil 2019&#8243; de la Comisi\u00f3n Pastoral de la Tierra (CPT Nacional). Causas del aumento de la violencia en el campo y la deforestaci\u00f3n de la selva amaz\u00f3nica son, sin duda, la extinci\u00f3n, el desguace, la destrucci\u00f3n financiera y la instrumentalizaci\u00f3n pol\u00edtica de organismos como el Ministerio de Desarrollo Agrario (MDA), la Fundaci\u00f3n Nacional del Ind\u00edgena (FUNAI), el Instituto Brasile\u00f1o de Medio Ambiente (IBAMA) y organismos de inspecci\u00f3n y control agr\u00edcola, ambiental y laboral.<\/p>\n<p>Tambi\u00e9n nos preocupa la militarizaci\u00f3n de la Comisi\u00f3n Nacional para la Amazon\u00eda, seg\u00fan el Decreto n\u00ba 10.239, de 11 de febrero de 2020, con su transferencia del Ministerio del Medio Ambiente a la Vicepresidencia de la Rep\u00fablica.<\/p>\n<p>Nosotros, obispos de la Amazon\u00eda brasile\u00f1a que firmamos esta nota, exhortamos a la Iglesia y a toda la Sociedad a exigir medidas urgentes del Gobierno Federal, del Congreso Nacional, de los gobiernos estatales y las Asambleas Legislativas, para:<\/p>\n<p>\u2022 Salvar vidas humanas, reconstruir comunidades y relaciones fortaleciendo las pol\u00edticas p\u00fablicas, especialmente el Sistema \u00danico de Salud (SUS);<\/p>\n<p>\u2022 Rechazar discursos que descalifiquen y desacrediten la efectividad de las estrategias cient\u00edficas;<\/p>\n<p>\u2022 Adoptar medidas restrictivas para la entrada de personas en todos los territorios ind\u00edgenas,\u00a0debido al riesgo de transmisi\u00f3n del nuevo coronavirus, a excepci\u00f3n de los profesionales de los Distritos Sanitarios Especiales Ind\u00edgenas (DSEI);<\/p>\n<p>\u2022 Realizar pruebas en la poblaci\u00f3n ind\u00edgena para adoptar las medidas de aislamiento necesarias y prevenir la propagaci\u00f3n del COVID-19;<\/p>\n<p>\u2022 Proporcionar el equipo de protecci\u00f3n personal (EPP) recomendado por la Organizaci\u00f3n Mundial de la Salud, en una cantidad adecuada y con las instrucciones correctas de uso y descarte;<\/p>\n<p>\u2022 Proteger a los profesionales de la salud que trabajan en los frentes de salud de los pueblos, acompa\u00f1\u00e1ndolos tambi\u00e9n en sus debilidades psicol\u00f3gicas y f\u00edsicas;<\/p>\n<p>\u2022 Garantizar la seguridad alimentaria de los pueblos \u00a0ind\u00edgenas, afrodescendientes, ribere\u00f1os y otras poblaciones tradicionales en la Amazon\u00eda;<\/p>\n<p>\u2022 Fortalecer las medidas de inspecci\u00f3n contra la deforestaci\u00f3n, la miner\u00eda y la miner\u00eda de oro, especialmente en tierras ind\u00edgenas y tradicionales y \u00e1reas de protecci\u00f3n ambiental;<\/p>\n<p>\u2022 Garantizar la participaci\u00f3n de la sociedad civil, movimientos sociales y representantes de las poblaciones tradicionales en espacios de deliberaciones pol\u00edticas;<\/p>\n<p>\u2022 Rechazar la Medida Provisional 910\/2019, que propone una nueva regularizaci\u00f3n de la tierra en Brasil, ya que elimina la reforma agraria, la regularizaci\u00f3n de los territorios de los pueblos originarios y tradicionales, favorece el acaparamiento de tierras, la deforestaci\u00f3n y los emprendimientos depredadores, regulariza las ocupaciones ilegales por parte del agro negocio, promueve la liquidaci\u00f3n de tierras p\u00fablicas en la Uni\u00f3n a precios insignificantes<br \/>y autoriza la adquisici\u00f3n de tierras por el capital extranjero, la explotaci\u00f3n especulativa de bosques y alienta la invasi\u00f3n y devastaci\u00f3n de tierras ind\u00edgenas y territorios tradicionales;<\/p>\n<p>\u2022 Rechazar el PL 191\/2020 que regula el Art\u00edculo 176.1 y el Art\u00edculo 231.3 de la<br \/>Constituci\u00f3n Federal, estableciendo las condiciones espec\u00edficas para realizar investigaciones y extracci\u00f3n de recursos minerales e h\u00eddricos en tierras ind\u00edgenas.<\/p>\n<p>\u2022 Derogar el Decreto n\u00ba 10.239 \/ 2020, devolviendo la Comisi\u00f3n para la Amazon\u00eda al Ministerio del Medio Ambiente, con la participaci\u00f3n de representantes de FUNAI e IBAMA y otras organizaciones de la sociedad civil, ind\u00edgenas o indigenistas como el Consejo Misionero Indigenista (CIMI), que act\u00faan en la Amazon\u00eda.<\/p>\n<p>\u2022 Derogar la Instrucci\u00f3n Normativa 09\/2020 de FUNAI, que permite la invasi\u00f3n, explotaci\u00f3n y incluso comercializaci\u00f3n en tierras ind\u00edgenas a\u00fan no aprobadas.<\/p>\n<p>La Iglesia en la Amazon\u00eda, despu\u00e9s de un rico proceso de escucha para la celebraci\u00f3n de la Asamblea Especial del S\u00ednodo de los Obispos para la Amazon\u00eda, est\u00e1 atenta a estos escenarios y demandas, haci\u00e9ndose eco de los gritos de los pobres y de la Tierra, de que se tomen medidas urgentes para<br \/>detener las actividades depredadoras y, al mismo tiempo, invertir esfuerzos en alternativas a la propuesta fallida de progreso y desarrollo que destruyen la Amazon\u00eda y amenazan la vida de sus pueblos.<\/p>\n<p>Que Nuestra Se\u00f1ora de Nazaret, Reina de la Amazon\u00eda, nos acompa\u00f1e y nos ayude en nuestro deseo de servir a los pobres y en la defensa intransigente de la justicia y la verdad.<\/p>\n<p style=\"text-align: right;\"><em>Brasilia-DF, 04 de mayo de 2020.<\/em><\/p>\n<p><em><strong>Firman esta nota:<\/strong><\/em><\/p>\n<p>Cardeal Cl\u00e1udio Hummes, OFM \u2013 Presidente da Comiss\u00e3o Episcopal para a Amaz\u00f4nia<\/p>\n<p><strong>Regional Norte 1<\/strong><br \/>Dom Adolfo Zon Pereira, S.X \u2013 Diocese de Alto Solim\u00f5es<br \/>Dom Edmilson Tadeu Canavarros dos Santos, SDB \u2013 Arquidiocese de Manaus (Auxiliar)<br \/>Dom Edson Tasquetto Damian \u2013 Diocese de S\u00e3o Gabriel da Cachoeira<br \/>Dom Fernando Barbosa dos Santos, CM \u2013 Diocese de Tef\u00e9<br \/>Dom Jos\u00e9 Albuquerque Ara\u00fajo \u2013 Arquidiocese de Manaus (Auxiliar)<br \/>Dom Jos\u00e9 Ionilton Lisboa de Ara\u00fajo, SDV \u2013 Prelazia de Itacoatiara<br \/>Dom Marcos Marian Piatek, CSSR \u2013 Diocese de Coari<br \/>Dom M\u00e1rio Ant\u00f4nio da Silva \u2013 Diocese de Roraima<br \/>Dom M\u00e1rio Pasqualloto, PIME &#8211; Arquidiocese de Manaus (Auxiliar Em\u00e9rito)<br \/>Dom Leonardo Ulrich Steiner, OFM \u2013 Arquidiocese de Manaus<br \/>Dom Zenildo Luiz Pereira da Silva, C.SS.R &#8211; Prelazia de Borba<br \/>Dom S\u00e9rgio Eduardo Castriani, CSSp \u2013 Arquidiocese de Manaus (Em\u00e9rito)<\/p>\n<p><strong>Regional Norte 2<\/strong><br \/>Dom Alberto Taveira Corr\u00eaa \u2013 Arquidiocese de Bel\u00e9m<br \/>Dom Alessio Saccardo \u2013 Diocese de Ponta de Pedras (\u00c9merito)<br \/>Dom Ant\u00f4nio de Assis Ribeiro, SDB \u2013 Arquidiocese de Bel\u00e9m (Auxiliar)<br \/>Dom Bernardo Johannes Bahlmann, OFM \u2013 Diocese de \u00d4bidos<br \/>Dom Carlos Verzeletti \u2013 Diocese de Castanhal<br \/>Dom Erwin Krautler, CPPS \u2013 Diocese do Xing\u00fa (Em\u00e9rito)<br \/>Dom Evaristo Pascoal Spengler, OFM \u2013 Prelazia do Maraj\u00f3<br \/>Dom Irineu Roman, CSJ \u2013 Arquidiocese de Santar\u00e9m<br \/>Dom Jesus Maria Cizaurre Berdonces, OAR \u2013 Diocese de Bragan\u00e7a<br \/>Dom Jes\u00fas Mar\u00eda L\u00f3pez Maule\u00f3n, OAR \u2013 Prelazia Alto Xingu \/Tucum\u00e3<br \/>Dom Jo\u00e3o Muniz Alves, OFM \u2013 Diocese do Xing\u00fa<br \/>Dom Jos\u00e9 Altevir da Silva, CSSp \u2013 Diocese de Camet\u00e1<br \/>Dom Jos\u00e9 Azcona Hermoso, OAR \u2013 Prelazia do Maraj\u00f3 (Em\u00e9rito)<br \/>Dom Jos\u00e9 Maria Chaves dos Reis \u2013 Diocese de Abaetetuba<br \/>Dom Lu\u00eds Ferrando \u2013 Diocese de Bragan\u00e7a (Em\u00e9rito)<br \/>Dom Pedro Jos\u00e9 Conti \u2013 Diocese de Macap\u00e1<br \/>Dom Teodoro Mendes Tavares, CSSp \u2013 Diocese de Ponta de Pedras<br \/>Dom Vital Corbellini \u2013 Diocese de Marab\u00e1<br \/>Dom Wilmar Santim, Ocarm \u2013 Prelazia de Itaituba<\/p>\n<p><strong>Regional Norte 3<\/strong><br \/>Dom Adriano Ciocca Vasino \u2013 Prelazia de S\u00e3o F\u00e9lix do Araguaia<br \/>Dom Dominique Marie Jean Denis You \u2013 Diocese de Sant\u00edssima Concei\u00e7\u00e3o do Araguaia<br \/>Dom Giovane Pereira de Melo \u2013 Diocese de Tocantin\u00f3polis<br \/>Dom Pedro Brito Guimar\u00e3es \u2013 Arquidiocese de Palmas<br \/>Dom Philip Dickmans \u2013 Diocese de Miracema do Tocantins<br \/>Dom Romualdo Matias Kujawski \u2013 Diocese de Porto Nacional<br \/>Dom Wellington de Queiroz Vieira \u2013 Diocese de Cristal\u00e2ndia<\/p>\n<p><strong>Regional Noroeste<\/strong><br \/>Dom Benedito Ara\u00fajo \u2013 Diocese de Guajar\u00e1-Mirim<br \/>Dom Fl\u00e1vio Giovenale, SDB \u2013 Diocese de Cruzeiro do Sul<br \/>Dom Joaqu\u00edn Perti\u00f1ez Fern\u00e1ndez, OAR \u2013 Diocese de Rio Branco<br \/>Dom Meinrad Francisco Merkel, CSSp \u2013 Diocese de Humait\u00e1<br \/>Dom Mos\u00e9 Jo\u00e3o Pontelo, CSSp \u2013 Diocese de Cruzeiro do Sul (Em\u00e9rito)<br \/>Dom Roque Paloschi \u2013 Arquidiocese de Porto Velho<br \/>Dom Santiago S\u00e1nchez Sebasti\u00e1n, OAR \u2013 Prelazia de L\u00e1brea<br \/>Pe. Jos\u00e9 Celestino dos Santos \u2013 Diocese de Ji-paran\u00e1 (Administrador Diocesano)<\/p>\n<p><strong>Regional Nordeste 5<\/strong><br \/>Dom Armando Mart\u00edn Guti\u00e9rrez, FAM \u2013 Diocese de Bacabal<br \/>Dom Elio Rama, IMC \u2013 Diocese de Pinheiro<br \/>Dom Evaldo Carvalho dos Santos, CM \u2013 Diocese de Viana<br \/>Dom Francisco Lima Soares \u2013 Diocese de Carolina<br \/>Dom Jo\u00e3o Kot, OMI \u2013 Diocese de Z\u00e9 Doca<br \/>Dom Jos\u00e9 Belis\u00e1rio da Silva, OFM \u2013 Arquidiocese de S\u00e3o Lu\u00eds do Maranh\u00e3o<br \/>Dom Jos\u00e9 Valdeci Santos Mendes \u2013 Diocese de Brejo<br \/>Dom Rubival Cabral Britto, OFMCap \u2013 Diocese de Graja\u00fa<br \/>Dom Sebasti\u00e3o Bandeira Co\u00ealho \u2013 Diocese de Coroat\u00e1<br \/>Dom Sebasti\u00e3o Lima Duarte \u2013 Diocese de Caxias do Maranh\u00e3o<br \/>Dom Vilsom Basso, SCJ \u2013 Diocese de Imperatriz<br \/>Pe. Nadir Lu\u00eds Zancheti \u2013 Diocese de Balsas (Administrador Diocesano)<\/p>\n<p><strong>Regional Oeste 2<\/strong><br \/>Dom Can\u00edsio Klaus \u2013 Diocese de Sinop<br \/>Dom Derek John Christopher Byrne, SPS \u2013 Diocese de Primavera do Leste-Paranatinga<br \/>Dom Jacy Diniz Rocha \u2013 Diocese de S\u00e3o Lu\u00eds dos C\u00e1rceres<br \/>Dom Juventino Kestering \u2013 Diocese de Rondon\u00f3polis-Guiratinga<br \/>Dom Milton Antonio dos Santos, SDB \u2013 Arquidiocese de Cuiab\u00e1<br \/>Dom Neri Jos\u00e9 Tondello \u2013 Diocese de Ju\u00edna<br \/>Dom Protogenes Jos\u00e9 Luft, SdC \u2013 Diocese de Barra do Gar\u00e7as<br \/>Dom Vital Chitolina, SCJ \u2013 Diocese de Diamantino<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante la situaci\u00f3n de la pandemia del COVID-19 en la Amazon\u00eda, 67 obispos de la Amazon\u00eda brasile\u00f1a firman una nota p\u00fablica divulgada en la ma\u00f1ana del lunes, 4 de mayo. En el texto, liderado por la Comisi\u00f3n Episcopal Especial para la Amazon\u00eda de la CNBB (Conferencia Nacional de los Obispos de Brasil), ellos convocan la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2332,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[189,4],"tags":[121,380,158,458],"class_list":["post-2331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-noticias","tag-brasil","tag-comunicado","tag-covid-19","tag-denuncia"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Obispos de la Amazon\u00eda brasile\u00f1a exigen medidas urgentes de los gobiernos para combatir el COVID-19 - REPAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repam.net\/es\/obispos-de-la-amazonia-brasilena-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Obispos de la Amazon\u00eda brasile\u00f1a exigen medidas urgentes de los gobiernos para combatir el COVID-19 - REPAM\" \/>\n<meta property=\"og:description\" content=\"Ante la situaci\u00f3n de la pandemia del COVID-19 en la Amazon\u00eda, 67 obispos de la Amazon\u00eda brasile\u00f1a firman una nota p\u00fablica divulgada en la ma\u00f1ana del lunes, 4 de mayo. En el texto, liderado por la Comisi\u00f3n Episcopal Especial para la Amazon\u00eda de la CNBB (Conferencia Nacional de los Obispos de Brasil), ellos convocan la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repam.net\/es\/obispos-de-la-amazonia-brasilena-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"REPAM\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-04T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/EncontroBel\u00e9m-1200x762_c.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"762\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"repam@adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repam@adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/obispos-de-la-amazonia-brasilena-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/obispos-de-la-amazonia-brasilena-covid-19\\\/\"},\"author\":{\"name\":\"repam@adm\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\"},\"headline\":\"Obispos de la Amazon\u00eda brasile\u00f1a exigen medidas urgentes de los gobiernos para combatir el COVID-19\",\"datePublished\":\"2020-05-04T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/obispos-de-la-amazonia-brasilena-covid-19\\\/\"},\"wordCount\":2134,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/obispos-de-la-amazonia-brasilena-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/EncontroBel\u00e9m-1200x762_c.jpg\",\"keywords\":[\"Brasil\",\"Comunicado\",\"COVID-19\",\"Denuncia\"],\"articleSection\":[\"Brasil\",\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/obispos-de-la-amazonia-brasilena-covid-19\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/obispos-de-la-amazonia-brasilena-covid-19\\\/\",\"name\":\"Obispos de la Amazon\u00eda brasile\u00f1a exigen medidas urgentes de los gobiernos para combatir el COVID-19 - REPAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/obispos-de-la-amazonia-brasilena-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/obispos-de-la-amazonia-brasilena-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/EncontroBel\u00e9m-1200x762_c.jpg\",\"datePublished\":\"2020-05-04T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/obispos-de-la-amazonia-brasilena-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repam.net\\\/es\\\/obispos-de-la-amazonia-brasilena-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/obispos-de-la-amazonia-brasilena-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/EncontroBel\u00e9m-1200x762_c.jpg\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/EncontroBel\u00e9m-1200x762_c.jpg\",\"width\":1200,\"height\":762},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/obispos-de-la-amazonia-brasilena-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Obispos de la Amazon\u00eda brasile\u00f1a exigen medidas urgentes de los gobiernos para combatir el COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"name\":\"REPAM\",\"description\":\"Red Eclesial Panamaz\u00f3nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repam.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\",\"name\":\"REPAM\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"REPAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\",\"name\":\"repam@adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"caption\":\"repam@adm\"},\"sameAs\":[\"http:\\\/\\\/repam.net\"],\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/author\\\/repamadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Obispos de la Amazon\u00eda brasile\u00f1a exigen medidas urgentes de los gobiernos para combatir el COVID-19 - REPAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repam.net\/es\/obispos-de-la-amazonia-brasilena-covid-19\/","og_locale":"es_ES","og_type":"article","og_title":"Obispos de la Amazon\u00eda brasile\u00f1a exigen medidas urgentes de los gobiernos para combatir el COVID-19 - REPAM","og_description":"Ante la situaci\u00f3n de la pandemia del COVID-19 en la Amazon\u00eda, 67 obispos de la Amazon\u00eda brasile\u00f1a firman una nota p\u00fablica divulgada en la ma\u00f1ana del lunes, 4 de mayo. En el texto, liderado por la Comisi\u00f3n Episcopal Especial para la Amazon\u00eda de la CNBB (Conferencia Nacional de los Obispos de Brasil), ellos convocan la [&hellip;]","og_url":"https:\/\/www.repam.net\/es\/obispos-de-la-amazonia-brasilena-covid-19\/","og_site_name":"REPAM","article_published_time":"2020-05-04T05:00:00+00:00","og_image":[{"width":1200,"height":762,"url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/EncontroBel\u00e9m-1200x762_c.jpg","type":"image\/jpeg"}],"author":"repam@adm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"repam@adm","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repam.net\/es\/obispos-de-la-amazonia-brasilena-covid-19\/#article","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/obispos-de-la-amazonia-brasilena-covid-19\/"},"author":{"name":"repam@adm","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033"},"headline":"Obispos de la Amazon\u00eda brasile\u00f1a exigen medidas urgentes de los gobiernos para combatir el COVID-19","datePublished":"2020-05-04T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repam.net\/es\/obispos-de-la-amazonia-brasilena-covid-19\/"},"wordCount":2134,"publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"image":{"@id":"https:\/\/www.repam.net\/es\/obispos-de-la-amazonia-brasilena-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/EncontroBel\u00e9m-1200x762_c.jpg","keywords":["Brasil","Comunicado","COVID-19","Denuncia"],"articleSection":["Brasil","Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.repam.net\/es\/obispos-de-la-amazonia-brasilena-covid-19\/","url":"https:\/\/www.repam.net\/es\/obispos-de-la-amazonia-brasilena-covid-19\/","name":"Obispos de la Amazon\u00eda brasile\u00f1a exigen medidas urgentes de los gobiernos para combatir el COVID-19 - REPAM","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repam.net\/es\/obispos-de-la-amazonia-brasilena-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/www.repam.net\/es\/obispos-de-la-amazonia-brasilena-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/EncontroBel\u00e9m-1200x762_c.jpg","datePublished":"2020-05-04T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.repam.net\/es\/obispos-de-la-amazonia-brasilena-covid-19\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repam.net\/es\/obispos-de-la-amazonia-brasilena-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/obispos-de-la-amazonia-brasilena-covid-19\/#primaryimage","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/EncontroBel\u00e9m-1200x762_c.jpg","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/EncontroBel\u00e9m-1200x762_c.jpg","width":1200,"height":762},{"@type":"BreadcrumbList","@id":"https:\/\/www.repam.net\/es\/obispos-de-la-amazonia-brasilena-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repam.net\/es\/"},{"@type":"ListItem","position":2,"name":"Obispos de la Amazon\u00eda brasile\u00f1a exigen medidas urgentes de los gobiernos para combatir el COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/www.repam.net\/es\/#website","url":"https:\/\/www.repam.net\/es\/","name":"REPAM","description":"Red Eclesial Panamaz\u00f3nica","publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repam.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.repam.net\/es\/#organization","name":"REPAM","url":"https:\/\/www.repam.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","width":512,"height":512,"caption":"REPAM"},"image":{"@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033","name":"repam@adm","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","caption":"repam@adm"},"sameAs":["http:\/\/repam.net"],"url":"https:\/\/www.repam.net\/es\/author\/repamadm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/comments?post=2331"}],"version-history":[{"count":0,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2331\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media\/2332"}],"wp:attachment":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media?parent=2331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/categories?post=2331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/tags?post=2331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}