{"id":2443,"date":"2020-04-03T00:00:00","date_gmt":"2020-04-03T05:00:00","guid":{"rendered":"http:\/\/repam.net\/organismo-episcopal-panamazonico-oep\/"},"modified":"2021-09-29T18:35:09","modified_gmt":"2021-09-29T23:35:09","slug":"organismo-episcopal-panamazonico-oep","status":"publish","type":"post","link":"https:\/\/www.repam.net\/es\/organismo-episcopal-panamazonico-oep\/","title":{"rendered":"Impulsan la creaci\u00f3n del Organismo Episcopal Panamaz\u00f3nico"},"content":{"rendered":"<p><h5 style=\"text-align: center;\"><strong><em>Mediante una carta fechada el 1 de abril, el presidente de la Red Eclesial Panamaz&oacute;nica (REPAM), Cardenal Claudio Hummes, comunic&oacute; los pasos a seguir en los pr&oacute;ximos meses para la constituci&oacute;n oficial del Organismo Episcopal Panamaz&oacute;nico (OEP) que se propuso en el punto 115 del Documento Final del S&iacute;nodo. Este proceso cuenta con el benepl&aacute;cito del Papa Francisco.<\/em><\/strong><\/h5>\n<p>&nbsp;<\/p>\n<p><em>&ldquo;Comenzamos la fase m&aacute;s significativa, por ser aquella en la que podamos poner este amor por la Querida Amazon&iacute;a en obras, inspirados por las palabras&rdquo;<\/em>. Esta frase se incluye dentro de la misiva que, con fecha 1 de abril de 2020, el Cardenal Claudio Hummes, como presidente de la Red Eclesial Panamaz&oacute;nica, ha enviado a todas las instancias involucradas en la creaci&oacute;n del Organismo Episcopal Amaz&oacute;nico &ndash; OEP, con perspectiva eclesial, y en cu&aacute;l se indican los pasos a seguir para poner en marcha esta instituci&oacute;n cuya necesidad fue visibilizada durante el &uacute;ltimo S&iacute;nodo para la Amazon&iacute;a celebrado el &uacute;ltimo mes de octubre en Roma.<\/p>\n<p>La conformaci&oacute;n del OEP figura de manera espec&iacute;fica en el Documento Final del mencionado encuentro, concretamente en el punto n&uacute;mero 115 donde se indica: &ldquo;<em>Se tratar&iacute;a de un organismo episcopal permanente y representativo que promueva la sinodalidad en la regi&oacute;n amaz&oacute;nica, articulado con el CELAM, con su estructura propia, en una organizaci&oacute;n simple y tambi&eacute;n articulado con la REPAM. De esta manera puede ser el cauce eficaz para asumir, desde el territorio de la Iglesia latinoamericana y caribe&ntilde;a, muchas de las propuestas surgidas en este S&iacute;nodo. Ser&iacute;a el nexo que articule redes e iniciativas eclesiales y socio ambientales a nivel continental e internacional&rdquo;. <\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"  alignleft\" src=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/48770413648_1ebe3d4f80_c.jpg\" alt=\"\" width=\"230\" height=\"165\">Son tres los pasos iniciales que detalla el Cardenal Hummes en su carta, indicando que todo el proceso cuenta con el benepl&aacute;cito del Santo Padre y que, por la coyuntura mundial con motivo de la pandemia por el COVID-19, estos avances deber&aacute;n darse de manera telem&aacute;tica. Primero, durante el mes de abril, se preparar&aacute; la asamblea constitutiva del Organismo Episcopal Panamaz&oacute;nico &ndash; OEP con la ayuda de la REPAM y en di&aacute;logo con la Presidencia del CELAM. En paralelo, durante los meses de abril y mayo, el presidente de la REPAM indica que se deber&aacute; &ldquo;mantener una comunicaci&oacute;n con la Secretar&iacute;a General del S&iacute;nodo y los miembros del Consejo PostSinodal para compartir los pasos que estaremos dando como Iglesia en el territorio Amaz&oacute;nico, y para pedir sus consejos, orientaciones y sugerencias&rdquo;. Por &uacute;ltimo, se espera que en mayo o junio pueda celebrarse propiamente la Asamblea Constitutiva del OEP para revisar y aprobar una constituci&oacute;n esencial, elegir un cuerpo colegiado y una secretar&iacute;a, y preparar una Asamblea ampliada con amplia perspectiva eclesial.<\/p>\n<p>Cabe mencionar que la Asamblea Constitutiva estar&iacute;a compuesta por miembros con voz y voto que ser&iacute;an un obispo amaz&oacute;nico de cada pa&iacute;s, salvo Brasil que contar&aacute; con dos por su mayor extensi&oacute;n, y las presidencia de la REPAM y el CELAM (Card. Claudio Hummes, Card. Barreto, y Mons. Cabrejos). Entre los miembros que tendr&aacute; voz, pero no voto, est&aacute;n: los presidentes\/as de C&Aacute;RITAS ALyC y CLAR, el secretario ejecutivo de la REPAM, cuatro miembros de las instancias Vaticanas (Card. Baldisseri, Card. Ouellet, Card. Tagle, Card. Czerny) por su relaci&oacute;n con esta iniciativa aprobada en el Documento Final del S&iacute;nodo, los\/as tres representantes de los pueblos originarios delegados al Consejo Post-Sinodal, y dos expertos (un te&oacute;logo de la sinodalidad y un jurista can&oacute;nico).<\/p>\n<p>&nbsp;<\/p>\n<h5><strong>ENTREVISTA<\/strong><\/h5>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"  alignleft\" src=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Asamblea_Sinodal.jpg\" alt=\"\" width=\"230\" height=\"118\">A continuaci&oacute;n, se brinda una breve entrevista con el Cardenal Claudio Hummes, donde se da mayores alcances sobre la importancia y significado de este Observatorio Episcopal Panamaz&oacute;nico, destacando que&nbsp;<em>&ldquo;el proceso sinodal, de aplicaci&oacute;n de las pautas de &lsquo;Querida Amazon&iacute;a&rsquo; en el territorio amaz&oacute;nico, no debe detenerse&rdquo;. <\/em><\/p>\n<p>Tras comunicar oficialmente la futura creaci&oacute;n del Observatorio Episcopal Panamaz&oacute;nico, el presidente de la Red Eclesial Panamaz&oacute;nica (REPAM), Card. Claudio Hummes, indica que esta constituci&oacute;n es &ldquo;urgente&rdquo; y espera que <em>&ldquo;no sea solo una formalidad, un organismo abstracto, sino que est&eacute; muy involucrado con las personas y las comunidades del territorio&rdquo;<\/em><\/p>\n<p><strong>Frente a esta situaci&oacute;n delicada de la Pandemia, &iquest;por qu&eacute; es importante para la REPAM y la Iglesia en la Amazon&iacute;a seguir impulsando el proceso Sinodal en el territorio?<\/strong><\/p>\n<p>Todo indica que pasar&aacute;n meses antes de que podamos reunirnos nuevamente en reuniones y asambleas cara a cara. Por ahora solo nos comunicamos a trav&eacute;s de internet y otras redes sociales. Sin embargo, el proceso de aplicaci&oacute;n de las pautas de la Exhortaci&oacute;n Apost&oacute;lica Querida Amazon&iacute;a y el Documento Final del S&iacute;nodo en el territorio no debe detenerse, de lo contrario existe el riesgo de debilitar el proceso y reducir las esperanzas de las poblaciones del territorio. En este contexto, la constituci&oacute;n del Organismo Episcopal Pan-Amaz&oacute;nico, prevista por el S&iacute;nodo, es urgente, porque este organismo promover&aacute; y coordinar&aacute; la aplicaci&oacute;n del S&iacute;nodo en el territorio. Ahora estamos comenzando este proceso de constituir este organismo episcopal.<\/p>\n<p><strong>Hemos tenido noticias que, desde la REPAM, en di&aacute;logo con las instancias eclesiales regionales, y con el Vaticano, se estar&aacute; comenzando un camino para la constituci&oacute;n del nuevo organismo Episcopal-Eclesial Amaz&oacute;nico que se afirma en el n&uacute;mero 115 del Documento Final del S&iacute;nodo. &iquest;D&oacute;nde radica la importancia de este organismo? &iquest;Qu&eacute; pasos se estar&aacute;n dando? <\/strong><\/p>\n<p>De hecho, estamos comenzando este proceso de constituci&oacute;n de este organismo con el apoyo tanto del Vaticano como de los organismos eclesiales regionales. Por ejemplo, las conferencias episcopales nacionales de los pa&iacute;ses involucrados, CLAR, la Secretar&iacute;a Latinoamericana de C&aacute;ritas y otros interesados. Comenzamos pidiendo que estas conferencias episcopales nacionales citadas, despu&eacute;s de consultar a sus obispos amaz&oacute;nicos, designen a un miembro de su episcopado amaz&oacute;nico para componer el n&uacute;cleo episcopal de ese organismo. Brasil, debido a la magnitud de su regi&oacute;n amaz&oacute;nica, indicar&aacute; dos. La propuesta es que este cuerpo tambi&eacute;n incluya a otros miembros que no sean obispos, para que tambi&eacute;n tenga una caracter&iacute;stica m&aacute;s eclesial-sinodal.<\/p>\n<p><strong>&iquest;Cu&aacute;l es su expectativa para los pr&oacute;ximos a&ntilde;os con respecto al servicio y funci&oacute;n de este organismo Episcopal-Eclesial Panamaz&oacute;nico en cuanto a su servicio para el proceso Sinodal y c&oacute;mo servir&aacute; a la iglesia universal y al itinerario del Papa Francisco?<\/strong><\/p>\n<p>Espero que este organismo no sea solo una formalidad, un organismo abstracto, sino que est&eacute; muy involucrado con las personas y las comunidades del territorio, ya sean comunidades eclesiales o comunidades de la poblaci&oacute;n local, como las comunidades ind&iacute;genas. Debe ser un organismo din&aacute;mico, cercano a la gente, que camina con la gente, que escucha a la gente y que, con la gente, decida las pr&aacute;cticas para construir estos nuevos caminos para la Iglesia en la Amazon&iacute;a y para una ecolog&iacute;a integral. De esta manera, sin duda contribuir&aacute; a los sue&ntilde;os del Papa Francisco, los sue&ntilde;os de una Iglesia m&aacute;s sinodal, misionera, misericordiosa y pobre con los pobres, en salida hacia las periferias. El S&iacute;nodo para la Amazon&iacute;a fue hist&oacute;rico, ning&uacute;n s&iacute;nodo anterior fue tan sinodal y reformador como este.<\/p>\n<p><em><strong>Por: <a href=\"http:\/\/www.redamazonica.org\" target=\"_blank\" rel=\"noopener noreferrer\">Comunicaciones REPAM<\/a><\/strong><\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mediante una carta fechada el 1 de abril, el presidente de la Red Eclesial Panamaz&oacute;nica (REPAM), Cardenal Claudio Hummes, comunic&oacute; los pasos a seguir en los pr&oacute;ximos meses para la constituci&oacute;n oficial del Organismo Episcopal Panamaz&oacute;nico (OEP) que se propuso en el punto 115 del Documento Final del S&iacute;nodo. Este proceso cuenta con el benepl&aacute;cito [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2444,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[4,141],"tags":[109,562,9,28],"class_list":["post-2443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-panamazonia","tag-celam","tag-organismo-episcopal-panamazonico","tag-repam","tag-sinodo-amazonico"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impulsan la creaci\u00f3n del Organismo Episcopal Panamaz\u00f3nico - REPAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repam.net\/es\/organismo-episcopal-panamazonico-oep\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impulsan la creaci\u00f3n del Organismo Episcopal Panamaz\u00f3nico - REPAM\" \/>\n<meta property=\"og:description\" content=\"Mediante una carta fechada el 1 de abril, el presidente de la Red Eclesial Panamaz&oacute;nica (REPAM), Cardenal Claudio Hummes, comunic&oacute; los pasos a seguir en los pr&oacute;ximos meses para la constituci&oacute;n oficial del Organismo Episcopal Panamaz&oacute;nico (OEP) que se propuso en el punto 115 del Documento Final del S&iacute;nodo. Este proceso cuenta con el benepl&aacute;cito [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repam.net\/es\/organismo-episcopal-panamazonico-oep\/\" \/>\n<meta property=\"og:site_name\" content=\"REPAM\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-03T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-29T23:35:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/30489310642_e04f4e979f_k-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"repam@adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repam@adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/organismo-episcopal-panamazonico-oep\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/organismo-episcopal-panamazonico-oep\\\/\"},\"author\":{\"name\":\"repam@adm\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\"},\"headline\":\"Impulsan la creaci\u00f3n del Organismo Episcopal Panamaz\u00f3nico\",\"datePublished\":\"2020-04-03T05:00:00+00:00\",\"dateModified\":\"2021-09-29T23:35:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/organismo-episcopal-panamazonico-oep\\\/\"},\"wordCount\":1406,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/organismo-episcopal-panamazonico-oep\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/30489310642_e04f4e979f_k-3.jpg\",\"keywords\":[\"CELAM\",\"Organismo Episcopal Panamaz\u00f3nico\",\"REPAM\",\"S\u00ednodo Amaz\u00f3nico\"],\"articleSection\":[\"Noticias\",\"Panamazon\u00eda\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/organismo-episcopal-panamazonico-oep\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/organismo-episcopal-panamazonico-oep\\\/\",\"name\":\"Impulsan la creaci\u00f3n del Organismo Episcopal Panamaz\u00f3nico - REPAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/organismo-episcopal-panamazonico-oep\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/organismo-episcopal-panamazonico-oep\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/30489310642_e04f4e979f_k-3.jpg\",\"datePublished\":\"2020-04-03T05:00:00+00:00\",\"dateModified\":\"2021-09-29T23:35:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/organismo-episcopal-panamazonico-oep\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repam.net\\\/es\\\/organismo-episcopal-panamazonico-oep\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/organismo-episcopal-panamazonico-oep\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/30489310642_e04f4e979f_k-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/30489310642_e04f4e979f_k-3.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/organismo-episcopal-panamazonico-oep\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impulsan la creaci\u00f3n del Organismo Episcopal Panamaz\u00f3nico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"name\":\"REPAM\",\"description\":\"Red Eclesial Panamaz\u00f3nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repam.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\",\"name\":\"REPAM\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"REPAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\",\"name\":\"repam@adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"caption\":\"repam@adm\"},\"sameAs\":[\"http:\\\/\\\/repam.net\"],\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/author\\\/repamadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impulsan la creaci\u00f3n del Organismo Episcopal Panamaz\u00f3nico - REPAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repam.net\/es\/organismo-episcopal-panamazonico-oep\/","og_locale":"es_ES","og_type":"article","og_title":"Impulsan la creaci\u00f3n del Organismo Episcopal Panamaz\u00f3nico - REPAM","og_description":"Mediante una carta fechada el 1 de abril, el presidente de la Red Eclesial Panamaz&oacute;nica (REPAM), Cardenal Claudio Hummes, comunic&oacute; los pasos a seguir en los pr&oacute;ximos meses para la constituci&oacute;n oficial del Organismo Episcopal Panamaz&oacute;nico (OEP) que se propuso en el punto 115 del Documento Final del S&iacute;nodo. Este proceso cuenta con el benepl&aacute;cito [&hellip;]","og_url":"https:\/\/www.repam.net\/es\/organismo-episcopal-panamazonico-oep\/","og_site_name":"REPAM","article_published_time":"2020-04-03T05:00:00+00:00","article_modified_time":"2021-09-29T23:35:09+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/30489310642_e04f4e979f_k-3.jpg","type":"image\/jpeg"}],"author":"repam@adm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"repam@adm","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repam.net\/es\/organismo-episcopal-panamazonico-oep\/#article","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/organismo-episcopal-panamazonico-oep\/"},"author":{"name":"repam@adm","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033"},"headline":"Impulsan la creaci\u00f3n del Organismo Episcopal Panamaz\u00f3nico","datePublished":"2020-04-03T05:00:00+00:00","dateModified":"2021-09-29T23:35:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repam.net\/es\/organismo-episcopal-panamazonico-oep\/"},"wordCount":1406,"publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"image":{"@id":"https:\/\/www.repam.net\/es\/organismo-episcopal-panamazonico-oep\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/30489310642_e04f4e979f_k-3.jpg","keywords":["CELAM","Organismo Episcopal Panamaz\u00f3nico","REPAM","S\u00ednodo Amaz\u00f3nico"],"articleSection":["Noticias","Panamazon\u00eda"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.repam.net\/es\/organismo-episcopal-panamazonico-oep\/","url":"https:\/\/www.repam.net\/es\/organismo-episcopal-panamazonico-oep\/","name":"Impulsan la creaci\u00f3n del Organismo Episcopal Panamaz\u00f3nico - REPAM","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repam.net\/es\/organismo-episcopal-panamazonico-oep\/#primaryimage"},"image":{"@id":"https:\/\/www.repam.net\/es\/organismo-episcopal-panamazonico-oep\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/30489310642_e04f4e979f_k-3.jpg","datePublished":"2020-04-03T05:00:00+00:00","dateModified":"2021-09-29T23:35:09+00:00","breadcrumb":{"@id":"https:\/\/www.repam.net\/es\/organismo-episcopal-panamazonico-oep\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repam.net\/es\/organismo-episcopal-panamazonico-oep\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/organismo-episcopal-panamazonico-oep\/#primaryimage","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/30489310642_e04f4e979f_k-3.jpg","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/30489310642_e04f4e979f_k-3.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/www.repam.net\/es\/organismo-episcopal-panamazonico-oep\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repam.net\/es\/"},{"@type":"ListItem","position":2,"name":"Impulsan la creaci\u00f3n del Organismo Episcopal Panamaz\u00f3nico"}]},{"@type":"WebSite","@id":"https:\/\/www.repam.net\/es\/#website","url":"https:\/\/www.repam.net\/es\/","name":"REPAM","description":"Red Eclesial Panamaz\u00f3nica","publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repam.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.repam.net\/es\/#organization","name":"REPAM","url":"https:\/\/www.repam.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","width":512,"height":512,"caption":"REPAM"},"image":{"@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033","name":"repam@adm","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","caption":"repam@adm"},"sameAs":["http:\/\/repam.net"],"url":"https:\/\/www.repam.net\/es\/author\/repamadm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/comments?post=2443"}],"version-history":[{"count":1,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2443\/revisions"}],"predecessor-version":[{"id":2447,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2443\/revisions\/2447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media\/2444"}],"wp:attachment":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media?parent=2443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/categories?post=2443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/tags?post=2443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}