{"id":2483,"date":"2020-03-26T00:00:00","date_gmt":"2020-03-26T05:00:00","guid":{"rendered":"http:\/\/repam.net\/quien-va-por-caminos-muy-diferentes-incomoda\/"},"modified":"2020-03-26T00:00:00","modified_gmt":"2020-03-26T05:00:00","slug":"quien-va-por-caminos-muy-diferentes-incomoda","status":"publish","type":"post","link":"https:\/\/www.repam.net\/es\/quien-va-por-caminos-muy-diferentes-incomoda\/","title":{"rendered":"Quien va por caminos muy diferentes incomoda"},"content":{"rendered":"<h5 style=\"text-align: center;\">27 de marzo: Viernes de la Cuarta Semana de Cuaresma<\/h5>\n<h5 style=\"text-align: center;\">QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n<\/h5>\n<p>&nbsp;<\/p>\n<p><strong>1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda<\/strong><\/p>\n<p style=\"text-align: center;\"><em>Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los signos de los tiempos, y la presencia de un Dios encarnado de diferentes modos, en distintos lugares. Un Dios que nos ayude a discernir su presencia y a anunciarle en todos los rincones, tambi\u00e9n entre los que m\u00e1s lejos se encuentran; a ser una Iglesia en salida, que va al encuentro, que escucha y dialoga con todos. Que busquemos el bien para todos los que nos encontramos cada d\u00eda y sepamos traer de vuelta a la Amazon\u00eda y a todos los lugares donde estemos, todo lo vivido en el proceso sinodal, y as\u00ed hacer realidad aquello que Dios espera de nosotros.<\/em><\/p>\n<p>Meditar por unos momentos esta petici\u00f3n inicial, buscar la calma interior para entrar en este momento de conversi\u00f3n desde la Amazon\u00eda por las aguas de la sinodalidad, al servicio del Pueblo de Dios y sus pueblos y comunidades, y para escuchar el llamado de Dios a trav\u00e9s de su Palabra Viva.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>2. Fragmento de una lectura del d\u00eda (cada uno es invitado a profundizar en las lecturas completas seg\u00fan su propia necesidad y criterio)<\/strong><\/p>\n<p>Los imp\u00edos se dicen entre s\u00ed, razonando equivocadamente: \u00abTendamos trampas al justo, porque nos molesta y se opone a nuestra manera de obrar; nos echa en cara las transgresiones a la Ley y nos reprocha las faltas contra la ense\u00f1anza recibida. El se glor\u00eda de poseer el conocimiento de Dios y se llama a s\u00ed mismo hijo del Se\u00f1or. Es un vivo reproche contra nuestra manera de pensar y su sola presencia nos resulta insoportable, porque lleva una vida distinta de los dem\u00e1s y va por caminos muy diferentes. Nos considera como algo viciado y se aparta de nuestros caminos como de las inmundicias. El proclama dichosa la suerte final de los justos y se jacta de tener por padre a Dios.Veamos si sus palabras son verdaderas y comprobemos lo que le pasar\u00e1 al final. Porque si el justo es hijo de Dios, \u00e9l lo proteger\u00e1 y lo librar\u00e1 de las manos de sus enemigos.<br \/>Pong\u00e1moslo a prueba con ultrajes y tormentos, para conocer su temple y probar su paciencia.<br \/>Conden\u00e9moslo a una muerte infame, ya que \u00e9l asegura que Dios lo visitar\u00e1.\u00bb As\u00ed razonan ellos, pero se equivocan, porque su malicia los ha enceguecido. No conocen los secretos de Dios, no esperan retribuci\u00f3n por la santidad, ni valoran la recompensa de las almas puras. (Sabidur\u00eda 2,1a.12-22).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>3. Reflexi\u00f3n desde la perspectiva del proceso sinodal amaz\u00f3nico<\/strong><\/p>\n<p>La presencia de los pueblos ind\u00edgenas, su forma de pensar, de entender la vida, resulta insoportable para muchos. Quien lleva una vida distinta de los dem\u00e1s, quien va por caminos muy diferentes incomoda. Si hoy hay alguien que se plantea la existencia de ese modo son los pueblos originarios, y eso tiene consecuencias en la vida pr\u00e1ctica. En cuanto la sociedad mayoritaria piensa en explotar, como prioridad absoluta, los pueblos ind\u00edgenas, considerados por muchos como atrasados, son el mejor exponente, como tipo de sociedad, del desarrollo sostenible.<\/p>\n<p>La Palabra de Dios siempre nos cuestiona, podr\u00edamos decir que es una bofetada en nuestra cara, que nos lleva a cuestionarnos y darnos cuenta que, aunque no lo aceptemos, somos nosotros quienes hemos elegido el camino equivocado. Es tiempo de parar, pensar y entender que es necesario cambiar, convertirnos y entender que los otros pueden ser los que est\u00e1n en el camino de la vida.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>4. Contemplaci\u00f3n<\/strong><\/p>\n<p><em>Contemplemos la imagen de este d\u00eda y dediquemos un momento a reconocer nuestra propia vida y experiencia en la Iglesia y al servicio de la Amazon\u00eda para pedir luz en esta Palabra de Dios y as\u00ed traer de vuelta todo lo vivido. Escribir mis peticiones particulares y permanecer en ellas durante este d\u00eda. Hacemos una invitaci\u00f3n a llevar un registro de todo lo que el Esp\u00edritu suscite en nosotros como preparaci\u00f3n interior para poder asimilar mejor el proceso sinodal.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>5. Meditaci\u00f3n Final<\/strong><\/p>\n<p>Esta historia de dolor y de desprecios no se sana f\u00e1cilmente. Y la colonizaci\u00f3n no se detiene, sino que en muchos lugares se transforma, se disfraza y se disimula, pero no pierde la prepotencia contra la vida de los pobres y la fragilidad del ambiente. Los Obispos de la Amazon\u00eda brasile\u00f1a recordaron que \u00abla historia de la Amazon\u00eda revela que siempre fue una minor\u00eda la que lucraba a costa de la pobreza de la mayor\u00eda y de la depredaci\u00f3n sin escr\u00fapulos de las riquezas naturales de la regi\u00f3n, d\u00e1diva divina para los pueblos que aqu\u00ed viven desde milenios y para los migrantes que llegaron a lo largo de los siglos pasados\u00bb. (Querida Amazon\u00eda, 16).<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/redamazonica.org\/wp-content\/uploads\/D\u00eda-31-ESP-27-marzo-Viernes-de-la-semana-IV.pdf\">D\u00eda 31 ESP &#8211; 27 marzo &#8211; Viernes de la semana IV<\/a><\/p>\n<p><a href=\"https:\/\/redamazonica.org\/wp-content\/uploads\/Dia-31-PT-27-mar\u00e7o-Sexta-feira-da-Semana-IV.pdf\">Dia 31 PT &#8211; 27 mar\u00e7o &#8211; Sexta-feira da Semana IV<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>27 de marzo: Viernes de la Cuarta Semana de Cuaresma QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n &nbsp; 1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los signos de los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2484,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[69,4],"tags":[560,204,8],"class_list":["post-2483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-justicia-socioambiental-y-buen-vivir","category-noticias","tag-40-dias-navegando-hacia-la-conversion","tag-espiritualidad-amazonica","tag-querida-amazonia"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quien va por caminos muy diferentes incomoda - REPAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repam.net\/es\/quien-va-por-caminos-muy-diferentes-incomoda\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quien va por caminos muy diferentes incomoda - REPAM\" \/>\n<meta property=\"og:description\" content=\"27 de marzo: Viernes de la Cuarta Semana de Cuaresma QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n &nbsp; 1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los signos de los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repam.net\/es\/quien-va-por-caminos-muy-diferentes-incomoda\/\" \/>\n<meta property=\"og:site_name\" content=\"REPAM\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-26T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/dia-31.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"971\" \/>\n\t<meta property=\"og:image:height\" content=\"717\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"repam@adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repam@adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/quien-va-por-caminos-muy-diferentes-incomoda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/quien-va-por-caminos-muy-diferentes-incomoda\\\/\"},\"author\":{\"name\":\"repam@adm\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\"},\"headline\":\"Quien va por caminos muy diferentes incomoda\",\"datePublished\":\"2020-03-26T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/quien-va-por-caminos-muy-diferentes-incomoda\\\/\"},\"wordCount\":881,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/quien-va-por-caminos-muy-diferentes-incomoda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/dia-31.jpg\",\"keywords\":[\"40 d\u00edas navegando hacia la conversi\u00f3n\",\"Espiritualidad Amaz\u00f3nica\",\"Querida Amazon\u00eda\"],\"articleSection\":[\"Justicia Socioambiental y Buen Vivir\",\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/quien-va-por-caminos-muy-diferentes-incomoda\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/quien-va-por-caminos-muy-diferentes-incomoda\\\/\",\"name\":\"Quien va por caminos muy diferentes incomoda - REPAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/quien-va-por-caminos-muy-diferentes-incomoda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/quien-va-por-caminos-muy-diferentes-incomoda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/dia-31.jpg\",\"datePublished\":\"2020-03-26T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/quien-va-por-caminos-muy-diferentes-incomoda\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repam.net\\\/es\\\/quien-va-por-caminos-muy-diferentes-incomoda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/quien-va-por-caminos-muy-diferentes-incomoda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/dia-31.jpg\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/dia-31.jpg\",\"width\":971,\"height\":717},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/quien-va-por-caminos-muy-diferentes-incomoda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quien va por caminos muy diferentes incomoda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"name\":\"REPAM\",\"description\":\"Red Eclesial Panamaz\u00f3nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repam.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\",\"name\":\"REPAM\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"REPAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\",\"name\":\"repam@adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"caption\":\"repam@adm\"},\"sameAs\":[\"http:\\\/\\\/repam.net\"],\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/author\\\/repamadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quien va por caminos muy diferentes incomoda - REPAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repam.net\/es\/quien-va-por-caminos-muy-diferentes-incomoda\/","og_locale":"es_ES","og_type":"article","og_title":"Quien va por caminos muy diferentes incomoda - REPAM","og_description":"27 de marzo: Viernes de la Cuarta Semana de Cuaresma QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n &nbsp; 1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los signos de los [&hellip;]","og_url":"https:\/\/www.repam.net\/es\/quien-va-por-caminos-muy-diferentes-incomoda\/","og_site_name":"REPAM","article_published_time":"2020-03-26T05:00:00+00:00","og_image":[{"width":971,"height":717,"url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/dia-31.jpg","type":"image\/jpeg"}],"author":"repam@adm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"repam@adm","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repam.net\/es\/quien-va-por-caminos-muy-diferentes-incomoda\/#article","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/quien-va-por-caminos-muy-diferentes-incomoda\/"},"author":{"name":"repam@adm","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033"},"headline":"Quien va por caminos muy diferentes incomoda","datePublished":"2020-03-26T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repam.net\/es\/quien-va-por-caminos-muy-diferentes-incomoda\/"},"wordCount":881,"publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"image":{"@id":"https:\/\/www.repam.net\/es\/quien-va-por-caminos-muy-diferentes-incomoda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/dia-31.jpg","keywords":["40 d\u00edas navegando hacia la conversi\u00f3n","Espiritualidad Amaz\u00f3nica","Querida Amazon\u00eda"],"articleSection":["Justicia Socioambiental y Buen Vivir","Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.repam.net\/es\/quien-va-por-caminos-muy-diferentes-incomoda\/","url":"https:\/\/www.repam.net\/es\/quien-va-por-caminos-muy-diferentes-incomoda\/","name":"Quien va por caminos muy diferentes incomoda - REPAM","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repam.net\/es\/quien-va-por-caminos-muy-diferentes-incomoda\/#primaryimage"},"image":{"@id":"https:\/\/www.repam.net\/es\/quien-va-por-caminos-muy-diferentes-incomoda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/dia-31.jpg","datePublished":"2020-03-26T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.repam.net\/es\/quien-va-por-caminos-muy-diferentes-incomoda\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repam.net\/es\/quien-va-por-caminos-muy-diferentes-incomoda\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/quien-va-por-caminos-muy-diferentes-incomoda\/#primaryimage","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/dia-31.jpg","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/dia-31.jpg","width":971,"height":717},{"@type":"BreadcrumbList","@id":"https:\/\/www.repam.net\/es\/quien-va-por-caminos-muy-diferentes-incomoda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repam.net\/es\/"},{"@type":"ListItem","position":2,"name":"Quien va por caminos muy diferentes incomoda"}]},{"@type":"WebSite","@id":"https:\/\/www.repam.net\/es\/#website","url":"https:\/\/www.repam.net\/es\/","name":"REPAM","description":"Red Eclesial Panamaz\u00f3nica","publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repam.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.repam.net\/es\/#organization","name":"REPAM","url":"https:\/\/www.repam.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","width":512,"height":512,"caption":"REPAM"},"image":{"@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033","name":"repam@adm","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","caption":"repam@adm"},"sameAs":["http:\/\/repam.net"],"url":"https:\/\/www.repam.net\/es\/author\/repamadm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/comments?post=2483"}],"version-history":[{"count":0,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2483\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media\/2484"}],"wp:attachment":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media?parent=2483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/categories?post=2483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/tags?post=2483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}