{"id":2485,"date":"2020-03-25T00:00:00","date_gmt":"2020-03-25T05:00:00","guid":{"rendered":"http:\/\/repam.net\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\/"},"modified":"2020-03-25T00:00:00","modified_gmt":"2020-03-25T05:00:00","slug":"sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente","status":"publish","type":"post","link":"https:\/\/www.repam.net\/es\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\/","title":{"rendered":"Sustituir a Dios por los \u00eddolos, una tentaci\u00f3n siempre presente"},"content":{"rendered":"<h5 style=\"text-align: center;\">26 de marzo: Jueves de la Cuarta Semana de Cuaresma<\/h5>\n<h5 style=\"text-align: center;\">QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n<\/h5>\n<p>&nbsp;<\/p>\n<p><strong>1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda<\/strong><\/p>\n<p style=\"text-align: center;\"><em>Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los signos de los tiempos, y la presencia de un Dios encarnado de diferentes modos, en distintos lugares. Un Dios que nos ayude a discernir su presencia y a anunciarle en todos los rincones, tambi\u00e9n entre los que m\u00e1s lejos se encuentran; a ser una Iglesia en salida, que va al encuentro, que escucha y dialoga con todos. Que busquemos el bien para todos los que nos encontramos cada d\u00eda y sepamos traer de vuelta a la Amazon\u00eda y a todos los lugares donde estemos, todo lo vivido en el proceso sinodal, y as\u00ed hacer realidad aquello que Dios espera de nosotros.<\/em><\/p>\n<p>Meditar por unos momentos esta petici\u00f3n inicial, buscar la calma interior para entrar en este momento de conversi\u00f3n desde la Amazon\u00eda por las aguas de la sinodalidad, al servicio del Pueblo de Dios y sus pueblos y comunidades, y para escuchar el llamado de Dios a trav\u00e9s de su Palabra Viva.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>2. Fragmento de una lectura del d\u00eda (cada uno es invitado a profundizar en las lecturas completas seg\u00fan su propia necesidad y criterio)<\/strong><\/h2>\n<p>El Se\u00f1or dijo a Mois\u00e9s: &#8220;Baja en seguida, porque tu pueblo, ese que hiciste salir de Egipto, se ha pervertido. Ellos se han apartado r\u00e1pidamente del camino que yo les hab\u00eda se\u00f1alado, y se han fabricado un ternero de metal fundido. Despu\u00e9s se postraron delante de \u00e9l, le ofrecieron sacrificios y exclamaron: &#8220;Este es tu Dios, Israel, el que te hizo salir de Egipto&#8221;.<br \/>Luego le sigui\u00f3 diciendo: &#8220;Ya veo que este es un pueblo obstinado. Por eso, d\u00e9jame obrar: mi ira arder\u00e1 contra ellos y los exterminar\u00e9. De ti, en cambio, suscitar\u00e9 una gran naci\u00f3n&#8221;.<br \/>Pero Mois\u00e9s trat\u00f3 de aplacar al Se\u00f1or con estas palabras: &#8220;\u00bfPor qu\u00e9, Se\u00f1or, arder\u00e1 tu ira contra tu pueblo, ese pueblo que t\u00fa mismo hiciste salir de Egipto con gran firmeza y mano poderosa? \u00bfPor qu\u00e9 tendr\u00e1n que decir los egipcios: &#8220;El los sac\u00f3 con la perversa intenci\u00f3n de hacerlos morir en las monta\u00f1as y exterminarlos de la superficie de la tierra?&#8221;. Deja de lado tu indignaci\u00f3n y arrepi\u00e9ntete del mal que quieres infligir a tu pueblo.<br \/>Acu\u00e9rdate de Abraham, de Isaac y de Jacob, tus servidores, a quienes juraste por ti mismo diciendo: &#8220;Yo multiplicar\u00e9 su descendencia como las estrellas del cielo, y les dar\u00e9 toda esta tierra de la que habl\u00e9, para que la tengan siempre como herencia&#8221;. Y el Se\u00f1or se arrepinti\u00f3 del mal con que hab\u00eda amenazado a su pueblo. (\u00c9xodo 32,7-14).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>3. Reflexi\u00f3n desde la perspectiva del proceso sinodal amaz\u00f3nico<\/strong><\/p>\n<p>La tentaci\u00f3n de sustituir a Dios por los \u00eddolos siempre ha estado presente en la vida de la humanidad. El becerro de oro es s\u00f3lo un ejemplo de actitudes que nunca han dejado de formar parte de la condici\u00f3n humana. Siempre ha habido quienes encuentran su felicidad y la \u00fanica raz\u00f3n para vivir en el hecho de tener, haciendo lo que sea necesario para tener cada vez m\u00e1s, dobleg\u00e1ndose a la voluntad de aquello que el Papa Francisco llama capitalismo que mata.<\/p>\n<p>Los pueblos originarios nos muestran que es posible vivir con poco y ser feliz, es lo que el Papa Francisco llama sobriedad feliz, una actitud que tiene como base el hecho de saber que a tu lado hay quien est\u00e1 dispuesto a repartir contigo cuando lo necesites. Se trata de modelos de sociedad completamente diferentes, que nos deben llevar a preguntarnos por cual queremos apostar, y en caso de estar en el que creemos que nos puede ayudar a ser m\u00e1s felices, convertirnos.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>4. Contemplaci\u00f3n<\/strong><\/p>\n<p style=\"text-align: center;\"><em>Contemplemos la imagen de este d\u00eda y dediquemos un momento a reconocer nuestra propia vida y experiencia en la Iglesia y al servicio de la Amazon\u00eda para pedir luz en esta Palabra de Dios y as\u00ed traer de vuelta todo lo vivido. Escribir mis peticiones particulares y permanecer en ellas durante este d\u00eda. Hacemos una invitaci\u00f3n a llevar un registro de todo lo que el Esp\u00edritu suscite en nosotros como preparaci\u00f3n interior para poder asimilar mejor el proceso sinodal.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>5. Meditaci\u00f3n Final<\/strong><\/p>\n<p>\u201cLos pueblos ind\u00edgenas amaz\u00f3nicos expresan la aut\u00e9ntica calidad de vida como un \u201cbuen vivir\u201d que implica una armon\u00eda personal, familiar, comunitaria y c\u00f3smica, y que se expresa en su modo comunitario de pensar la existencia, en la capacidad de encontrar gozo y plenitud en medio de una vida austera y sencilla, as\u00ed como en el cuidado responsable de la naturaleza que preserva los recursos para las siguientes generaciones. Los pueblos abor\u00edgenes podr\u00edan ayudarnos a percibir lo que es una feliz sobriedad y en este sentido \u00ab tienen mucho que ense\u00f1arnos \u00bb. Ellos saben ser felices con poco, disfrutan los peque\u00f1os dones de Dios sin acumular tantas cosas, no destruyen sin necesidad, cuidan los ecosistemas y reconocen que la tierra, al mismo tiempo que se ofrece para sostener su vida, como una fuente generosa, tiene un sentido materno que despierta respetuosa ternura\u201d.\u00a0 (Querida Amazon\u00eda, 71).<\/p>\n<p>&nbsp;<\/p>\n<p><em> <a href=\"https:\/\/redamazonica.org\/wp-content\/uploads\/D\u00eda-30-ESP-26-marzo-Jueves-de-la-semana-IV.pdf\">D\u00eda 30 ESP &#8211; 26 marzo &#8211; Jueves de la semana IV<\/a> <\/em><\/p>\n<p><em><a href=\"https:\/\/redamazonica.org\/wp-content\/uploads\/Dia-30-PT-26-mar\u00e7o-Quinta-feira-da-Semana-IV.pdf\">Dia 30 PT &#8211; 26 mar\u00e7o &#8211; Quinta-feira da Semana IV<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>26 de marzo: Jueves de la Cuarta Semana de Cuaresma QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n &nbsp; 1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los signos de los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2486,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[69,4],"tags":[560,204,8],"class_list":["post-2485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-justicia-socioambiental-y-buen-vivir","category-noticias","tag-40-dias-navegando-hacia-la-conversion","tag-espiritualidad-amazonica","tag-querida-amazonia"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sustituir a Dios por los \u00eddolos, una tentaci\u00f3n siempre presente - REPAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repam.net\/es\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sustituir a Dios por los \u00eddolos, una tentaci\u00f3n siempre presente - REPAM\" \/>\n<meta property=\"og:description\" content=\"26 de marzo: Jueves de la Cuarta Semana de Cuaresma QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n &nbsp; 1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los signos de los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repam.net\/es\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\/\" \/>\n<meta property=\"og:site_name\" content=\"REPAM\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-25T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/dia-30.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"954\" \/>\n\t<meta property=\"og:image:height\" content=\"692\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"repam@adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repam@adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\\\/\"},\"author\":{\"name\":\"repam@adm\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\"},\"headline\":\"Sustituir a Dios por los \u00eddolos, una tentaci\u00f3n siempre presente\",\"datePublished\":\"2020-03-25T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\\\/\"},\"wordCount\":948,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/dia-30.jpg\",\"keywords\":[\"40 d\u00edas navegando hacia la conversi\u00f3n\",\"Espiritualidad Amaz\u00f3nica\",\"Querida Amazon\u00eda\"],\"articleSection\":[\"Justicia Socioambiental y Buen Vivir\",\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\\\/\",\"name\":\"Sustituir a Dios por los \u00eddolos, una tentaci\u00f3n siempre presente - REPAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/dia-30.jpg\",\"datePublished\":\"2020-03-25T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repam.net\\\/es\\\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/dia-30.jpg\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/dia-30.jpg\",\"width\":954,\"height\":692},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sustituir a Dios por los \u00eddolos, una tentaci\u00f3n siempre presente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"name\":\"REPAM\",\"description\":\"Red Eclesial Panamaz\u00f3nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repam.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\",\"name\":\"REPAM\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"REPAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\",\"name\":\"repam@adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"caption\":\"repam@adm\"},\"sameAs\":[\"http:\\\/\\\/repam.net\"],\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/author\\\/repamadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sustituir a Dios por los \u00eddolos, una tentaci\u00f3n siempre presente - REPAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repam.net\/es\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\/","og_locale":"es_ES","og_type":"article","og_title":"Sustituir a Dios por los \u00eddolos, una tentaci\u00f3n siempre presente - REPAM","og_description":"26 de marzo: Jueves de la Cuarta Semana de Cuaresma QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n &nbsp; 1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los signos de los [&hellip;]","og_url":"https:\/\/www.repam.net\/es\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\/","og_site_name":"REPAM","article_published_time":"2020-03-25T05:00:00+00:00","og_image":[{"width":954,"height":692,"url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/dia-30.jpg","type":"image\/jpeg"}],"author":"repam@adm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"repam@adm","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repam.net\/es\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\/#article","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\/"},"author":{"name":"repam@adm","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033"},"headline":"Sustituir a Dios por los \u00eddolos, una tentaci\u00f3n siempre presente","datePublished":"2020-03-25T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repam.net\/es\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\/"},"wordCount":948,"publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"image":{"@id":"https:\/\/www.repam.net\/es\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/dia-30.jpg","keywords":["40 d\u00edas navegando hacia la conversi\u00f3n","Espiritualidad Amaz\u00f3nica","Querida Amazon\u00eda"],"articleSection":["Justicia Socioambiental y Buen Vivir","Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.repam.net\/es\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\/","url":"https:\/\/www.repam.net\/es\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\/","name":"Sustituir a Dios por los \u00eddolos, una tentaci\u00f3n siempre presente - REPAM","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repam.net\/es\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\/#primaryimage"},"image":{"@id":"https:\/\/www.repam.net\/es\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/dia-30.jpg","datePublished":"2020-03-25T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.repam.net\/es\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repam.net\/es\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\/#primaryimage","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/dia-30.jpg","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/dia-30.jpg","width":954,"height":692},{"@type":"BreadcrumbList","@id":"https:\/\/www.repam.net\/es\/sustituir-a-dios-por-los-idolos-una-tentacion-siempre-presente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repam.net\/es\/"},{"@type":"ListItem","position":2,"name":"Sustituir a Dios por los \u00eddolos, una tentaci\u00f3n siempre presente"}]},{"@type":"WebSite","@id":"https:\/\/www.repam.net\/es\/#website","url":"https:\/\/www.repam.net\/es\/","name":"REPAM","description":"Red Eclesial Panamaz\u00f3nica","publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repam.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.repam.net\/es\/#organization","name":"REPAM","url":"https:\/\/www.repam.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","width":512,"height":512,"caption":"REPAM"},"image":{"@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033","name":"repam@adm","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","caption":"repam@adm"},"sameAs":["http:\/\/repam.net"],"url":"https:\/\/www.repam.net\/es\/author\/repamadm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/comments?post=2485"}],"version-history":[{"count":0,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media\/2486"}],"wp:attachment":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media?parent=2485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/categories?post=2485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/tags?post=2485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}