{"id":2503,"date":"2020-03-19T00:00:00","date_gmt":"2020-03-19T05:00:00","guid":{"rendered":"http:\/\/repam.net\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\/"},"modified":"2020-03-19T00:00:00","modified_gmt":"2020-03-19T05:00:00","slug":"lo-que-llega-de-fuera-no-garantiza-la-felicidad","status":"publish","type":"post","link":"https:\/\/www.repam.net\/es\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\/","title":{"rendered":"\u00a0Lo que llega de fuera no garantiza la felicidad"},"content":{"rendered":"<h5 style=\"text-align: center;\">20 de marzo: Viernes de la Tercera Semana de Cuaresma<\/h5>\n<h5 style=\"text-align: center;\">QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n<\/h5>\n<p>&nbsp;<\/p>\n<p><strong>1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda<\/strong><\/p>\n<p style=\"text-align: center;\"><em>Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los signos de los tiempos, y la presencia de un Dios encarnado de diferentes modos, en distintos lugares. Un Dios que nos ayude a discernir su presencia y a anunciarle en todos los rincones, tambi\u00e9n entre los que m\u00e1s lejos se encuentran; a ser una Iglesia en salida, que va al encuentro, que escucha y dialoga con todos. Que busquemos el bien para todos los que nos encontramos cada d\u00eda y sepamos traer de vuelta a la Amazon\u00eda y a todos los lugares donde estemos, todo lo vivido en el proceso sinodal, y as\u00ed hacer realidad aquello que Dios espera de nosotros.<\/em><\/p>\n<p>Meditar por unos momentos esta petici\u00f3n inicial, buscar la calma interior para entrar en este momento de conversi\u00f3n desde la Amazon\u00eda por las aguas de la sinodalidad, al servicio del Pueblo de Dios y sus pueblos y comunidades, y para escuchar el llamado de Dios a trav\u00e9s de su Palabra Viva.<\/p>\n<h2><\/h2>\n<p><strong>2. Fragmento de una lectura del d\u00eda (cada uno es invitado a profundizar en las lecturas completas seg\u00fan su propia necesidad y criterio)<\/strong><\/p>\n<p>As\u00ed habla el Se\u00f1or: Vuelve, Israel, al Se\u00f1or tu Dios, porque tu falta te ha hecho caer. Preparen lo que van decir y vuelvan al Se\u00f1or. D\u00edganle: &#8220;Borra todas las faltas, acepta lo que hay de bueno, y te ofreceremos el fruto de nuestros labios.<br \/>Asiria no nos salvar\u00e1, ya no montaremos a caballo, ni diremos m\u00e1s &#8220;\u00a1Dios nuestro!&#8221; a la obra de nuestras manos, porque s\u00f3lo en ti el hu\u00e9rfano encuentra compasi\u00f3n&#8221;.<br \/>Yo los curar\u00e9 de su apostas\u00eda, los amar\u00e9 generosamente, porque mi ira se ha apartado de ellos.<br \/>Ser\u00e9 como roc\u00edo para Israel: \u00e9l florecer\u00e1 como el lirio, hundir\u00e1 sus ra\u00edces como el bosque del L\u00edbano; sus reto\u00f1os se extender\u00e1n, su esplendor ser\u00e1 como el del olivo y su fragancia como la del L\u00edbano. Volver\u00e1n a sentarse a mi sombra, har\u00e1n revivir el trigo, florecer\u00e1n como la vi\u00f1a, y su renombre ser\u00e1 como el del vino del L\u00edbano.<br \/>Efra\u00edm, \u00bfqu\u00e9 tengo a\u00fan que ver con los \u00eddolos? Yo le respondo y velo por \u00e9l. Soy como un cipr\u00e9s siempre verde, y de m\u00ed procede tu fruto. \u00a1Que el sabio comprenda estas cosas! \u00a1Que el hombre inteligente las entienda! Los caminos del Se\u00f1or son rectos: por ellos caminar\u00e1n los justos, pero los rebeldes tropezar\u00e1n en ellos. (Oseas 14,2-10).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>3. Reflexi\u00f3n desde la perspectiva del proceso sinodal amaz\u00f3nico<\/strong><\/p>\n<p>Volver a Dios, asumir de nuevo aquello que siempre fue el fundamento de nuestra vida, entender que solo eso da sentido a nuestra existencia y nos ayuda a construir el futuro desde una base s\u00f3lida. La tentaci\u00f3n de pensar que lo que viene de fuera es mejor que lo que siempre hemos tenido, es mejor que aquello que tradicionalmente ha garantizado nuestra felicidad, siempre est\u00e1 ah\u00ed. Estuvo presente en el pueblo de Israel y contin\u00faa presente entre nosotros.<\/p>\n<p>En la Amazon\u00eda esa es una actitud que cada vez m\u00e1s supone una amenaza para el futuro de los pueblos, especialmente entre los m\u00e1s j\u00f3venes. El proceso sinodal ha hecho una llamada a cuidar de los j\u00f3venes, a ayudarles a descubrir que lo que llega de fuera no garantiza la felicidad, que no es eso lo que va a hacer que sientan realizados como personas y como pueblos. Asiria no nos salvar\u00e1, y s\u00ed todo lo que la cultura comunica, todo lo que es expresi\u00f3n de un modo de vida que tiene su fundamento en la divinidad.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>4. Contemplaci\u00f3n<\/strong><\/p>\n<p style=\"text-align: center;\"><em>Contemplemos la imagen de este d\u00eda y dediquemos un momento a reconocer nuestra propia vida y experiencia en la Iglesia y al servicio de la Amazon\u00eda para pedir luz en esta Palabra de Dios y as\u00ed traer de vuelta todo lo vivido. Escribir mis peticiones particulares y permanecer en ellas durante este d\u00eda. Hacemos una invitaci\u00f3n a llevar un registro de todo lo que el Esp\u00edritu suscite en nosotros como preparaci\u00f3n interior para poder asimilar mejor el proceso sinodal.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>5. Meditaci\u00f3n Final<\/strong><\/p>\n<p>\u201cQuiero recordar ahora que \u00abla visi\u00f3n consumista del ser humano, alentada por los engranajes de la actual econom\u00eda globalizada, tiende a homogeneizar las culturas y a debilitar la inmensa variedad cultural, que es un tesoro de la humanidad\u00bb. Esto afecta mucho a los j\u00f3venes, cuando se tiende \u00aba disolver las diferencias propias de su lugar de origen, a convertirlos en seres manipulables hechos en serie\u00bb. Para evitar esta din\u00e1mica de empobrecimiento humano, hace falta amar y cuidar las ra\u00edces, porque ellas son \u00abun punto de arraigo que nos permite desarrollarnos y responder a los nuevos desaf\u00edos\u00bb. Invito a los j\u00f3venes de la Amazon\u00eda, especialmente a los ind\u00edgenas, a \u00abhacerse cargo de las ra\u00edces, porque de las ra\u00edces viene la fuerza que los va a hacer crecer, florecer y fructificar\u00bb. (Querida Amazon\u00eda, 33).<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/redamazonica.org\/wp-content\/uploads\/D\u00eda-24-ESP-20-marzo-Viernes-de-la-semana-III.pdf\">D\u00eda 24 ESP &#8211; 20 marzo &#8211; Viernes de la semana III<\/a><\/p>\n<p><a href=\"https:\/\/redamazonica.org\/wp-content\/uploads\/Dia-24-PT-20-mar\u00e7o-Sexta-feira-da-Semana-III.pdf\">Dia 24 PT &#8211; 20 mar\u00e7o &#8211; Sexta-feira da Semana III<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>20 de marzo: Viernes de la Tercera Semana de Cuaresma QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n &nbsp; 1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los signos de los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2504,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[203,4],"tags":[560,204,8],"class_list":["post-2503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-amazonica","category-noticias","tag-40-dias-navegando-hacia-la-conversion","tag-espiritualidad-amazonica","tag-querida-amazonia"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a0Lo que llega de fuera no garantiza la felicidad - REPAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repam.net\/es\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a0Lo que llega de fuera no garantiza la felicidad - REPAM\" \/>\n<meta property=\"og:description\" content=\"20 de marzo: Viernes de la Tercera Semana de Cuaresma QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n &nbsp; 1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los signos de los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repam.net\/es\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\/\" \/>\n<meta property=\"og:site_name\" content=\"REPAM\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-19T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/D\u00eda-24.png\" \/>\n\t<meta property=\"og:image:width\" content=\"711\" \/>\n\t<meta property=\"og:image:height\" content=\"524\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"repam@adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repam@adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\\\/\"},\"author\":{\"name\":\"repam@adm\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\"},\"headline\":\"\u00a0Lo que llega de fuera no garantiza la felicidad\",\"datePublished\":\"2020-03-19T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\\\/\"},\"wordCount\":933,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/D\u00eda-24.png\",\"keywords\":[\"40 d\u00edas navegando hacia la conversi\u00f3n\",\"Espiritualidad Amaz\u00f3nica\",\"Querida Amazon\u00eda\"],\"articleSection\":[\"Espiritualidad Amaz\u00f3nica\",\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\\\/\",\"name\":\"\u00a0Lo que llega de fuera no garantiza la felicidad - REPAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/D\u00eda-24.png\",\"datePublished\":\"2020-03-19T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/D\u00eda-24.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/D\u00eda-24.png\",\"width\":711,\"height\":524},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a0Lo que llega de fuera no garantiza la felicidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"name\":\"REPAM\",\"description\":\"Red Eclesial Panamaz\u00f3nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repam.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\",\"name\":\"REPAM\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"REPAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\",\"name\":\"repam@adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"caption\":\"repam@adm\"},\"sameAs\":[\"http:\\\/\\\/repam.net\"],\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/author\\\/repamadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a0Lo que llega de fuera no garantiza la felicidad - REPAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repam.net\/es\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a0Lo que llega de fuera no garantiza la felicidad - REPAM","og_description":"20 de marzo: Viernes de la Tercera Semana de Cuaresma QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n &nbsp; 1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los signos de los [&hellip;]","og_url":"https:\/\/www.repam.net\/es\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\/","og_site_name":"REPAM","article_published_time":"2020-03-19T05:00:00+00:00","og_image":[{"width":711,"height":524,"url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/D\u00eda-24.png","type":"image\/png"}],"author":"repam@adm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"repam@adm","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repam.net\/es\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\/#article","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\/"},"author":{"name":"repam@adm","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033"},"headline":"\u00a0Lo que llega de fuera no garantiza la felicidad","datePublished":"2020-03-19T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repam.net\/es\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\/"},"wordCount":933,"publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"image":{"@id":"https:\/\/www.repam.net\/es\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/D\u00eda-24.png","keywords":["40 d\u00edas navegando hacia la conversi\u00f3n","Espiritualidad Amaz\u00f3nica","Querida Amazon\u00eda"],"articleSection":["Espiritualidad Amaz\u00f3nica","Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.repam.net\/es\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\/","url":"https:\/\/www.repam.net\/es\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\/","name":"\u00a0Lo que llega de fuera no garantiza la felicidad - REPAM","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repam.net\/es\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\/#primaryimage"},"image":{"@id":"https:\/\/www.repam.net\/es\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/D\u00eda-24.png","datePublished":"2020-03-19T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.repam.net\/es\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repam.net\/es\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\/#primaryimage","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/D\u00eda-24.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/D\u00eda-24.png","width":711,"height":524},{"@type":"BreadcrumbList","@id":"https:\/\/www.repam.net\/es\/lo-que-llega-de-fuera-no-garantiza-la-felicidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repam.net\/es\/"},{"@type":"ListItem","position":2,"name":"\u00a0Lo que llega de fuera no garantiza la felicidad"}]},{"@type":"WebSite","@id":"https:\/\/www.repam.net\/es\/#website","url":"https:\/\/www.repam.net\/es\/","name":"REPAM","description":"Red Eclesial Panamaz\u00f3nica","publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repam.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.repam.net\/es\/#organization","name":"REPAM","url":"https:\/\/www.repam.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","width":512,"height":512,"caption":"REPAM"},"image":{"@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033","name":"repam@adm","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","caption":"repam@adm"},"sameAs":["http:\/\/repam.net"],"url":"https:\/\/www.repam.net\/es\/author\/repamadm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/comments?post=2503"}],"version-history":[{"count":0,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2503\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media\/2504"}],"wp:attachment":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media?parent=2503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/categories?post=2503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/tags?post=2503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}