{"id":2513,"date":"2020-03-17T00:00:00","date_gmt":"2020-03-17T05:00:00","guid":{"rendered":"http:\/\/repam.net\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\/"},"modified":"2020-03-17T00:00:00","modified_gmt":"2020-03-17T05:00:00","slug":"lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida","status":"publish","type":"post","link":"https:\/\/www.repam.net\/es\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\/","title":{"rendered":"Lo peor que podemos hacer es promover leyes a nuestra medida"},"content":{"rendered":"<h5 style=\"text-align: center;\">D\u00eda 22 &#8211; 18 de marzo: Mi\u00e9rcoles de la Tercera Semana de Cuaresma<\/h5>\n<h5 style=\"text-align: center;\">QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n<\/h5>\n<p>&nbsp;<\/p>\n<p><strong>1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda<\/strong><\/p>\n<p style=\"text-align: center;\"><em>Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los signos de los tiempos, y la presencia de un Dios encarnado de diferentes modos, en distintos lugares. Un Dios que nos ayude a discernir su presencia y a anunciarle en todos los rincones, tambi\u00e9n entre los que m\u00e1s lejos se encuentran; a ser una Iglesia en salida, que va al encuentro, que escucha y dialoga con todos. Que busquemos el bien para todos los que nos encontramos cada d\u00eda y sepamos traer de vuelta a la Amazon\u00eda y a todos los lugares donde estemos, todo lo vivido en el proceso sinodal, y as\u00ed hacer realidad aquello que Dios espera de nosotros.<\/em><\/p>\n<p>Meditar por unos momentos esta petici\u00f3n inicial, buscar la calma interior para entrar en este momento de conversi\u00f3n desde la Amazon\u00eda por las aguas de la sinodalidad, al servicio del Pueblo de Dios y sus pueblos y comunidades, y para escuchar el llamado de Dios a trav\u00e9s de su Palabra Viva.<\/p>\n<h2><\/h2>\n<p><strong>2. Fragmento de una lectura del d\u00eda (cada uno es invitado a profundizar en las lecturas completas seg\u00fan su propia necesidad y criterio)<\/strong><\/p>\n<p>Jes\u00fas dijo a sus disc\u00edpulos: \u00abNo piensen que vine para abolir la Ley o los Profetas: yo no he venido a abolir, sino a dar cumplimiento.<br \/>Les aseguro que no desaparecer\u00e1 ni una i ni una coma de la Ley, antes que desaparezcan el cielo y la tierra, hasta que todo se realice.<br \/>El que no cumpla el m\u00e1s peque\u00f1o de estos mandamientos, y ense\u00f1e a los otros a hacer lo mismo, ser\u00e1 considerado el menor en el Reino de los Cielos. En cambio, el que los cumpla y ense\u00f1e, ser\u00e1 considerado grande en el Reino de los Cielos.\u00bb (Mateo 5,17-19).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>3. Reflexi\u00f3n desde la perspectiva del proceso sinodal amaz\u00f3nico<\/strong><\/p>\n<p>La Ley de Dios tiene que llevarnos a pensar en el otro, en el que est\u00e1 a nuestro lado y en el que viene despu\u00e9s de nosotros. Es una Ley que est\u00e1 basada en el amor y que nos lleva a ver al otro como alguien que ocupa un lugar destacado en nuestra vida, que nos lleva a crecer hasta hacernos grandes a los ojos de Dios, un requisito esencial para entrar en el Reino de los Cielos.<\/p>\n<p>Lo peor que podemos hacer es promover leyes a nuestra medida, para satisfacer nuestros intereses particulares o de grupo. Hoy vemos como en la Amazon\u00eda, la Ley de Dios, que piensa en los peque\u00f1os, quiere ser suplantada por una ley humana, que responda a los intereses de los poderosos, aprovech\u00e1ndose de la vida de la naturaleza y de quienes siempre han respetado la Ley divina. Son estos poderosos quienes est\u00e1n queriendo instaurar una nueva realidad, propia de quien se cree grande, pero que en realidad tiene un coraz\u00f3n peque\u00f1o.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>4. Contemplaci\u00f3n<\/strong><\/p>\n<p style=\"text-align: center;\"><em>Contemplemos la imagen de este d\u00eda y dediquemos un momento a reconocer nuestra propia vida y experiencia en la Iglesia y al servicio de la Amazon\u00eda para pedir luz en esta Palabra de Dios y as\u00ed traer de vuelta todo lo vivido. Escribir mis peticiones particulares y permanecer en ellas durante este d\u00eda. Hacemos una invitaci\u00f3n a llevar un registro de todo lo que el Esp\u00edritu suscite en nosotros como preparaci\u00f3n interior para poder asimilar mejor el proceso sinodal.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>5. Meditaci\u00f3n Final<\/strong><\/p>\n<p>\u201cLa Iglesia, con su larga experiencia espiritual, con su renovada consciencia sobre el valor de la creaci\u00f3n, con su preocupaci\u00f3n por la justicia, con su opci\u00f3n por los \u00faltimos, con su tradici\u00f3n educativa y con su historia de encarnaci\u00f3n en culturas tan diversas de todo el mundo, tambi\u00e9n quiere aportar al cuidado y al crecimiento de la Amazon\u00eda\u201d.(Querida Amazon\u00eda, 60).<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/redamazonica.org\/wp-content\/uploads\/D\u00eda-22-ESP-18-marzo-Mi\u00e9rcoles-de-la-semana-III.pdf\">D\u00eda 22 ESP &#8211; 18 marzo &#8211; Mi\u00e9rcoles de la semana III<\/a><\/p>\n<p><a href=\"https:\/\/redamazonica.org\/wp-content\/uploads\/Dia-22-PT-18-mar\u00e7o-Quarta-feira-da-Semana-III.pdf\">Dia 22 PT &#8211; 18 mar\u00e7o &#8211; Quarta-feira da Semana III<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00eda 22 &#8211; 18 de marzo: Mi\u00e9rcoles de la Tercera Semana de Cuaresma QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n &nbsp; 1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2514,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[203,4],"tags":[560,204,8],"class_list":["post-2513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-amazonica","category-noticias","tag-40-dias-navegando-hacia-la-conversion","tag-espiritualidad-amazonica","tag-querida-amazonia"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lo peor que podemos hacer es promover leyes a nuestra medida - REPAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repam.net\/es\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo peor que podemos hacer es promover leyes a nuestra medida - REPAM\" \/>\n<meta property=\"og:description\" content=\"D\u00eda 22 &#8211; 18 de marzo: Mi\u00e9rcoles de la Tercera Semana de Cuaresma QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n &nbsp; 1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repam.net\/es\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\/\" \/>\n<meta property=\"og:site_name\" content=\"REPAM\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-17T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Dia-22.png\" \/>\n\t<meta property=\"og:image:width\" content=\"710\" \/>\n\t<meta property=\"og:image:height\" content=\"528\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"repam@adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repam@adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\\\/\"},\"author\":{\"name\":\"repam@adm\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\"},\"headline\":\"Lo peor que podemos hacer es promover leyes a nuestra medida\",\"datePublished\":\"2020-03-17T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\\\/\"},\"wordCount\":726,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Dia-22.png\",\"keywords\":[\"40 d\u00edas navegando hacia la conversi\u00f3n\",\"Espiritualidad Amaz\u00f3nica\",\"Querida Amazon\u00eda\"],\"articleSection\":[\"Espiritualidad Amaz\u00f3nica\",\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\\\/\",\"name\":\"Lo peor que podemos hacer es promover leyes a nuestra medida - REPAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Dia-22.png\",\"datePublished\":\"2020-03-17T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Dia-22.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Dia-22.png\",\"width\":710,\"height\":528},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo peor que podemos hacer es promover leyes a nuestra medida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"name\":\"REPAM\",\"description\":\"Red Eclesial Panamaz\u00f3nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repam.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\",\"name\":\"REPAM\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"REPAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\",\"name\":\"repam@adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"caption\":\"repam@adm\"},\"sameAs\":[\"http:\\\/\\\/repam.net\"],\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/author\\\/repamadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo peor que podemos hacer es promover leyes a nuestra medida - REPAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repam.net\/es\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\/","og_locale":"es_ES","og_type":"article","og_title":"Lo peor que podemos hacer es promover leyes a nuestra medida - REPAM","og_description":"D\u00eda 22 &#8211; 18 de marzo: Mi\u00e9rcoles de la Tercera Semana de Cuaresma QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n &nbsp; 1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los [&hellip;]","og_url":"https:\/\/www.repam.net\/es\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\/","og_site_name":"REPAM","article_published_time":"2020-03-17T05:00:00+00:00","og_image":[{"width":710,"height":528,"url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Dia-22.png","type":"image\/png"}],"author":"repam@adm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"repam@adm","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repam.net\/es\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\/#article","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\/"},"author":{"name":"repam@adm","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033"},"headline":"Lo peor que podemos hacer es promover leyes a nuestra medida","datePublished":"2020-03-17T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repam.net\/es\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\/"},"wordCount":726,"publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"image":{"@id":"https:\/\/www.repam.net\/es\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Dia-22.png","keywords":["40 d\u00edas navegando hacia la conversi\u00f3n","Espiritualidad Amaz\u00f3nica","Querida Amazon\u00eda"],"articleSection":["Espiritualidad Amaz\u00f3nica","Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.repam.net\/es\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\/","url":"https:\/\/www.repam.net\/es\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\/","name":"Lo peor que podemos hacer es promover leyes a nuestra medida - REPAM","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repam.net\/es\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\/#primaryimage"},"image":{"@id":"https:\/\/www.repam.net\/es\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Dia-22.png","datePublished":"2020-03-17T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.repam.net\/es\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repam.net\/es\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\/#primaryimage","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Dia-22.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Dia-22.png","width":710,"height":528},{"@type":"BreadcrumbList","@id":"https:\/\/www.repam.net\/es\/lo-peor-que-podemos-hacer-es-promover-leyes-a-nuestra-medida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repam.net\/es\/"},{"@type":"ListItem","position":2,"name":"Lo peor que podemos hacer es promover leyes a nuestra medida"}]},{"@type":"WebSite","@id":"https:\/\/www.repam.net\/es\/#website","url":"https:\/\/www.repam.net\/es\/","name":"REPAM","description":"Red Eclesial Panamaz\u00f3nica","publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repam.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.repam.net\/es\/#organization","name":"REPAM","url":"https:\/\/www.repam.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","width":512,"height":512,"caption":"REPAM"},"image":{"@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033","name":"repam@adm","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","caption":"repam@adm"},"sameAs":["http:\/\/repam.net"],"url":"https:\/\/www.repam.net\/es\/author\/repamadm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/comments?post=2513"}],"version-history":[{"count":0,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2513\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media\/2514"}],"wp:attachment":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media?parent=2513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/categories?post=2513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/tags?post=2513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}