{"id":2562,"date":"2020-03-03T00:00:00","date_gmt":"2020-03-03T05:00:00","guid":{"rendered":"http:\/\/repam.net\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\/"},"modified":"2020-03-03T00:00:00","modified_gmt":"2020-03-03T05:00:00","slug":"desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion","status":"publish","type":"post","link":"https:\/\/www.repam.net\/es\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\/","title":{"rendered":"Desde los confines de la tierra somos llamados a la conversi\u00f3n"},"content":{"rendered":"<h5 style=\"text-align: center;\">D\u00eda 8 \u2013 4 de marzo: Mi\u00e9rcoles de la Primera Semana de Cuaresma<\/h5>\n<h5 style=\"text-align: center;\">QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n<\/h5>\n<p>&nbsp;<\/p>\n<p><strong>1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda<\/strong><\/p>\n<p style=\"text-align: center;\"><em>Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los signos de los tiempos, y la presencia de un Dios encarnado de diferentes modos, en distintos lugares. Un Dios que nos ayude a discernir su presencia y a anunciarle en todos los rincones, tambi\u00e9n entre los que m\u00e1s lejos se encuentran; a ser una Iglesia en salida, que va al encuentro, que escucha y dialoga con todos. Que busquemos el bien para todos los que nos encontramos cada d\u00eda y sepamos traer de vuelta a la Amazon\u00eda y a todos los lugares donde estemos, todo lo vivido en el proceso sinodal, y as\u00ed hacer realidad aquello que Dios espera de nosotros.<\/em><\/p>\n<p>Meditar por unos momentos esta petici\u00f3n inicial, buscar la calma interior para entrar en este momento de conversi\u00f3n desde la Amazon\u00eda por las aguas de la sinodalidad, al servicio del Pueblo de Dios y sus pueblos y comunidades, y para escuchar el llamado de Dios a trav\u00e9s de su Palabra Viva.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>2. Fragmento de una lectura del d\u00eda (cada uno es invitado a profundizar en las lecturas completas seg\u00fan su propia necesidad y criterio)<\/strong><\/p>\n<p><strong>\u00a0<\/strong>Al ver Jes\u00fas que la multitud se apretujaba, comenz\u00f3 a decir: &#8220;Esta es una generaci\u00f3n malvada. Pide un signo y no le ser\u00e1 dado otro que el de Jon\u00e1s. As\u00ed como Jon\u00e1s fue un signo para los ninivitas, tambi\u00e9n el Hijo del hombre lo ser\u00e1 para esta generaci\u00f3n.<br \/>El d\u00eda del Juicio, la Reina del Sur se levantar\u00e1 contra los hombres de esta generaci\u00f3n y los condenar\u00e1, porque ella vino de los confines de la tierra para escuchar la sabidur\u00eda de Salom\u00f3n y aqu\u00ed hay alguien que es m\u00e1s que Salom\u00f3n.<br \/>El d\u00eda del Juicio, los hombres de N\u00ednive se levantar\u00e1n contra esta generaci\u00f3n y la condenar\u00e1n, porque ellos se convirtieron por la predicaci\u00f3n de Jon\u00e1s y aqu\u00ed hay alguien que es m\u00e1s que Jon\u00e1s. (Lucas 11,29-32).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>3. Reflexi\u00f3n desde la perspectiva del proceso sinodal amaz\u00f3nico<\/strong><\/p>\n<p>Son muchos los que a lo largo de la historia predicaron la necesidad de conversi\u00f3n. Al fin y al cabo, Dios nos habla a trav\u00e9s de aquellos a quienes env\u00eda. No siempre ese mensaje ha sido escuchado, inclusive cuando Dios habl\u00f3 a trav\u00e9s de su propio Hijo. En el siglo XXI, Dios nos est\u00e1 hablando a trav\u00e9s del Papa Francisco, que entre las muchas conversiones a las que nos llama es a una conversi\u00f3n ecol\u00f3gica.<\/p>\n<p>Muchos no le escuchan, sobre todo aquellos que viven instalados en el centro de la Iglesia y de la sociedad, en ese primer mundo social y eclesial. Pero el S\u00ednodo para la Amazon\u00eda nos ha mostrado que alguien que vino de los confines de la tierra, de la periferia, son el ejemplo a seguir. Los pueblos amaz\u00f3nicos escucharon esa invitaci\u00f3n y se pusieron manos a la obra junto con el obispo de Roma, llamando al mundo a descubrir la necesidad de cuidar de la Casa Com\u00fan, una actitud asumida secularmente, que quieren hacer ver como algo a ser asumido por todos.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>4. Contemplaci\u00f3n<\/strong><\/p>\n<p><em>Contemplemos la imagen de este d\u00eda y dediquemos un momento a reconocer nuestra propia vida y experiencia en la Iglesia y al servicio de la Amazon\u00eda para pedir luz en esta Palabra de Dios y as\u00ed traer de vuelta todo lo vivido. Escribir mis peticiones particulares y permanecer en ellas durante este d\u00eda. Hacemos una invitaci\u00f3n a llevar un registro de todo lo que el Esp\u00edritu suscite en nosotros como preparaci\u00f3n interior para poder asimilar mejor el proceso sinodal.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>5. Cita para meditaci\u00f3n de cierre<\/strong><\/p>\n<p>Nuestro planeta es un regalo de Dios, pero sabemos tambi\u00e9n que vivimos la urgencia de actuar frente a una crisis socioambiental sin precedentes. Necesitamos una conversi\u00f3n ecol\u00f3gica para responder adecuadamente. Por ello como Iglesia Amaz\u00f3nica, frente a la agresi\u00f3n cada vez mayor a nuestro bioma amenazado por su desaparici\u00f3n con consecuencias tremendas para nuestro planeta, nos ponemos en camino inspirados por la propuesta de la ecolog\u00eda integral. Reconocemos las heridas causadas por el ser humano en nuestro territorio, queremos aprender de nuestros hermanos y hermanas de los pueblos originarios, en un di\u00e1logo de saberes, el desaf\u00edo de dar nuevas respuestas buscando modelos de desarrollo justo y solidario. Queremos cuidar nuestra \u201ccasa com\u00fan\u201d en la Amazon\u00eda y proponemos nuevos caminos para ello. (Documento Final, 65).<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/redamazonica.org\/wp-content\/uploads\/D\u00eda-8-ESP-4-marzo-Mi\u00e9rcoles-de-la-semana-I.pdf\">D\u00eda 8 ESP &#8211; 4 marzo &#8211; Mi\u00e9rcoles de la semana I<\/a><\/p>\n<p><a href=\"https:\/\/redamazonica.org\/wp-content\/uploads\/Dia-8-PT-4-mar\u00e7o-Quarta-feira-da-Semana-I.pdf\">Dia 8 PT &#8211; 4 mar\u00e7o &#8211; Quarta-feira da Semana I<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00eda 8 \u2013 4 de marzo: Mi\u00e9rcoles de la Primera Semana de Cuaresma QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n &nbsp; 1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2563,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[203,4],"tags":[560,204,8],"class_list":["post-2562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-amazonica","category-noticias","tag-40-dias-navegando-hacia-la-conversion","tag-espiritualidad-amazonica","tag-querida-amazonia"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desde los confines de la tierra somos llamados a la conversi\u00f3n - REPAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repam.net\/es\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desde los confines de la tierra somos llamados a la conversi\u00f3n - REPAM\" \/>\n<meta property=\"og:description\" content=\"D\u00eda 8 \u2013 4 de marzo: Mi\u00e9rcoles de la Primera Semana de Cuaresma QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n &nbsp; 1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repam.net\/es\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\/\" \/>\n<meta property=\"og:site_name\" content=\"REPAM\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-03T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Presentaci\u00f3n1-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"711\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"repam@adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repam@adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\\\/\"},\"author\":{\"name\":\"repam@adm\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\"},\"headline\":\"Desde los confines de la tierra somos llamados a la conversi\u00f3n\",\"datePublished\":\"2020-03-03T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\\\/\"},\"wordCount\":853,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Presentaci\u00f3n1-3.png\",\"keywords\":[\"40 d\u00edas navegando hacia la conversi\u00f3n\",\"Espiritualidad Amaz\u00f3nica\",\"Querida Amazon\u00eda\"],\"articleSection\":[\"Espiritualidad Amaz\u00f3nica\",\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\\\/\",\"name\":\"Desde los confines de la tierra somos llamados a la conversi\u00f3n - REPAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Presentaci\u00f3n1-3.png\",\"datePublished\":\"2020-03-03T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repam.net\\\/es\\\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Presentaci\u00f3n1-3.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Presentaci\u00f3n1-3.png\",\"width\":711,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desde los confines de la tierra somos llamados a la conversi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"name\":\"REPAM\",\"description\":\"Red Eclesial Panamaz\u00f3nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repam.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\",\"name\":\"REPAM\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"REPAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\",\"name\":\"repam@adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"caption\":\"repam@adm\"},\"sameAs\":[\"http:\\\/\\\/repam.net\"],\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/author\\\/repamadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desde los confines de la tierra somos llamados a la conversi\u00f3n - REPAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repam.net\/es\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\/","og_locale":"es_ES","og_type":"article","og_title":"Desde los confines de la tierra somos llamados a la conversi\u00f3n - REPAM","og_description":"D\u00eda 8 \u2013 4 de marzo: Mi\u00e9rcoles de la Primera Semana de Cuaresma QUERIDA AMAZON\u00cdA: 40 d\u00edas navegando hacia la conversi\u00f3n &nbsp; 1. Petici\u00f3n permanente por la conversi\u00f3n sinodal al inicio de cada d\u00eda Que el Dios Trinitario, ejemplo de vida en comuni\u00f3n, nos ayude a so\u00f1ar con una Iglesia sinodal, donde sepamos descubrir los [&hellip;]","og_url":"https:\/\/www.repam.net\/es\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\/","og_site_name":"REPAM","article_published_time":"2020-03-03T05:00:00+00:00","og_image":[{"width":711,"height":550,"url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Presentaci\u00f3n1-3.png","type":"image\/png"}],"author":"repam@adm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"repam@adm","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repam.net\/es\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\/#article","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\/"},"author":{"name":"repam@adm","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033"},"headline":"Desde los confines de la tierra somos llamados a la conversi\u00f3n","datePublished":"2020-03-03T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repam.net\/es\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\/"},"wordCount":853,"publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"image":{"@id":"https:\/\/www.repam.net\/es\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Presentaci\u00f3n1-3.png","keywords":["40 d\u00edas navegando hacia la conversi\u00f3n","Espiritualidad Amaz\u00f3nica","Querida Amazon\u00eda"],"articleSection":["Espiritualidad Amaz\u00f3nica","Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.repam.net\/es\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\/","url":"https:\/\/www.repam.net\/es\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\/","name":"Desde los confines de la tierra somos llamados a la conversi\u00f3n - REPAM","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repam.net\/es\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\/#primaryimage"},"image":{"@id":"https:\/\/www.repam.net\/es\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Presentaci\u00f3n1-3.png","datePublished":"2020-03-03T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.repam.net\/es\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repam.net\/es\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\/#primaryimage","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Presentaci\u00f3n1-3.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Presentaci\u00f3n1-3.png","width":711,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/www.repam.net\/es\/desde-los-confines-de-la-tierra-somos-llamados-a-la-conversion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repam.net\/es\/"},{"@type":"ListItem","position":2,"name":"Desde los confines de la tierra somos llamados a la conversi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.repam.net\/es\/#website","url":"https:\/\/www.repam.net\/es\/","name":"REPAM","description":"Red Eclesial Panamaz\u00f3nica","publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repam.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.repam.net\/es\/#organization","name":"REPAM","url":"https:\/\/www.repam.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","width":512,"height":512,"caption":"REPAM"},"image":{"@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033","name":"repam@adm","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","caption":"repam@adm"},"sameAs":["http:\/\/repam.net"],"url":"https:\/\/www.repam.net\/es\/author\/repamadm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/comments?post=2562"}],"version-history":[{"count":0,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media\/2563"}],"wp:attachment":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media?parent=2562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/categories?post=2562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/tags?post=2562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}