{"id":2960,"date":"2019-09-02T00:00:00","date_gmt":"2019-09-02T05:00:00","guid":{"rendered":"http:\/\/repam.net\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\/"},"modified":"2019-09-02T00:00:00","modified_gmt":"2019-09-02T05:00:00","slug":"a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos","status":"publish","type":"post","link":"https:\/\/www.repam.net\/es\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\/","title":{"rendered":"A Igreja na Amaz\u00f4nia e o desenvolvimento humano integral:  Compromisso prof\u00e9tico com a dignidade de todos os povos"},"content":{"rendered":"<p>Como o <strong>Bom Samaritano<\/strong>, a <strong>Igreja<\/strong> quer implementar seu compromisso com a compaix\u00e3o e com a justi\u00e7a do Evangelho na <strong>Amaz\u00f4nia<\/strong>. Ela \u00e9 chamada a observar e compreender, para depois se abrir para o di\u00e1logo e agir. Esta \u00e9 a raz\u00e3o pela qual o <strong>Papa Francisco<\/strong> convocou um <a href=\"http:\/\/www.ihu.unisinos.br\/78-noticias\/588217-a-amazonia-e-nossa-um-sinodo-para-a-pan-amazonia-dom-erwin-kraeutler-apresenta-10-desafios-para-igreja-na-amazonia\">S\u00ednodo dos Bispos para a regi\u00e3o Pan-Amaz\u00f4nica<\/a>. Com a ajuda do S\u00ednodo, ser\u00e1 poss\u00edvel iniciar a\u00e7\u00f5es pastorais e ambientais na Amaz\u00f4nia e reafirmar as modalidades de &#8220;ser Igreja&#8221; implicadas por tais a\u00e7\u00f5es.<\/p>\n<p>O texto \u00e9 de <a href=\"http:\/\/www.ihu.unisinos.br\/78-noticias\/581179-michael-czerny-sobre-o-trafico-de-seres-humanos-e-as-escravidoes-modernas-derrubar-os-muros-da-hipocrisia\">Michael Czerny<\/a> SJ, secret\u00e1rio do Dicast\u00e9rio pelo servi\u00e7o do desenvolvimento humano integral e Secret\u00e1rio Especial do S\u00ednodo para a Amaz\u00f4nia, publicado por<strong> L&#8217;Osservatore Romano<\/strong>, 1-08-2019. A tradu\u00e7\u00e3o \u00e9 de<strong> Luisa Rabolini<\/strong>.<\/p>\n<p>Essa preocupa\u00e7\u00e3o em se comprometer \u00e9 explicitamente assumida no \u00faltimo cap\u00edtulo do <a href=\"http:\/\/www.ihu.unisinos.br\/78-noticias\/590572-as-15-propostas-mais-audaciosas-do-instrumentum-laboris-do-sinodo-da-amazonia\">Instrumentum laboris<\/a> (<strong>IL<\/strong>), que sintetiza os desafios e as esperan\u00e7as de uma <strong>Igreja prof\u00e9tica na regi\u00e3o amaz\u00f4nica<\/strong>. O horizonte em que nos movemos, sem o qual a vida e a justi\u00e7a n\u00e3o podem existir, \u00e9 o fato de que &#8220;tudo est\u00e1 conectado&#8221;, como o <strong>Papa Francisco<\/strong> explicou na enc\u00edclica <a href=\"http:\/\/www.ihuonline.unisinos.br\/edicao\/469\">Laudato Si&#8217;<\/a> (138). O social e o natural, o meio ambiente e o cuidado pastoral n\u00e3o podem e n\u00e3o devem ser separados. As compartimentaliza\u00e7\u00f5es redutivas &#8211; intelectuais e espirituais, empreendedoras e pol\u00edticas &#8211; puseram em perigo a vida humana na Terra, a casa comum da humanidade.<\/p>\n<p>O pr\u00f3ximo <strong>S\u00ednodo<\/strong> compromete-se em ajudar a reparar as viola\u00e7\u00f5es em uma parte do mundo onde as consequ\u00eancias das concep\u00e7\u00f5es err\u00f4neas e das pr\u00e1ticas nocivas s\u00e3o particularmente s\u00e9rias. Chegou a hora de a Igreja confrontar essa quest\u00e3o. Por esta raz\u00e3o, no tema do <strong>S\u00ednodo<\/strong>, encontramos as palavras &#8220;<a href=\"http:\/\/www.ihu.unisinos.br\/78-noticias\/590760-sinodo-sobre-a-amazonia-novos-caminhos-para-a-igreja-e-para-a-ecologia-integral\">Novos caminhos para a Igreja e para uma ecologia integral<\/a>&#8220;, e o t\u00edtulo do \u00faltimo cap\u00edtulo do IL \u00e9 &#8220;<strong>O papel prof\u00e9tico da Igreja e a promo\u00e7\u00e3o humana integral<\/strong>&#8220;. Ambos falam de dimens\u00f5es ou din\u00e2micas que devem caminhar juntas na<strong> miss\u00e3o da Igreja<\/strong>: seu minist\u00e9rio pastoral n\u00e3o deve ser separado da promo\u00e7\u00e3o humana e da ecologia integral.<\/p>\n<p>Como a enc\u00edclica <strong>Laudato Si&#8217;<\/strong>, com sua exaustiva exposi\u00e7\u00e3o hist\u00f3rica, cient\u00edfica, econ\u00f4mica e pastoral, tamb\u00e9m o <strong>IL<\/strong> oferece uma longa an\u00e1lise das condi\u00e7\u00f5es da <strong>Amaz\u00f4nia<\/strong>. Nas palavras do <strong>Papa Francisco<\/strong>: \u201c<em>A Amaz\u00f4nia \u00e9 uma terra disputada em v\u00e1rias frentes: o neoextrativismo e a forte press\u00e3o dos grandes interesses econ\u00f4micos que direcionam sua gan\u00e2ncia sobre petr\u00f3leo, g\u00e1s, madeira, ouro, monoculturas agroindustriais<\/em>&#8221; (<a href=\"http:\/\/www.ihu.unisinos.br\/78-noticias\/575444-precisamos-escuta-los-papa-francisco-diz-que-povos-indigenas-nunca-estiveram-tao-ameacados\">Discurso no encontro com os povos da Amaz\u00f4nia<\/a>, Puerto Maldonado, Peru, 19 de janeiro de 2018). Acrescenta o IL: \u201c<em>A destrui\u00e7\u00e3o m\u00faltipla da vida humana e ambiental, as enfermidades e a contamina\u00e7\u00e3o de rios e terras, o abate e a queima de \u00e1rvores, a perda maci\u00e7a da biodiversidade, o desaparecimento de esp\u00e9cies (mais de um milh\u00e3o dos oito milh\u00f5es de animais e vegetais est\u00e3o em perigo), constituem uma realidade crua que interpela todos n\u00f3s. Reinam a viol\u00eancia, o caos e a corrup\u00e7\u00e3o. O territ\u00f3rio se transformou em um espa\u00e7o de desencontros e de exterm\u00ednio de povos, culturas e gera\u00e7\u00f5es.<\/em>&#8221; (n. 23).<\/p>\n<p>A <strong>situa\u00e7\u00e3o na Amaz\u00f4nia<\/strong> tem v\u00e1rias causas. Existem responsabilidades locais e multinacionais que apoiam e incentivam investimentos, p\u00fablicos ou privados, que t\u00eam impactos devastadores sobre o meio ambiente amaz\u00f4nico e seus habitantes. No entanto, um ponto de partida fundamental \u00e9 o fato de que as popula\u00e7\u00f5es ind\u00edgenas veem amea\u00e7ados seus territ\u00f3rios delimitados por interesses que os exploram, e muitas vezes lhes \u00e9 negado o direito \u00e0 sua pr\u00f3pria terra.<\/p>\n<p>Isto constitui uma viola\u00e7\u00e3o das leis e conven\u00e7\u00f5es internacionais. &#8220;<em>A Declara\u00e7\u00e3o das Na\u00e7\u00f5es Unidas sobre os Direitos dos Povos Ind\u00edgenas (aprovada em 13 de setembro de 2007), \u00e0 qual o Papa se referiu em v\u00e1rias ocasi\u00f5es, cont\u00e9m importantes direitos como o da autodetermina\u00e7\u00e3o, em virtude do qual aqueles povos decidem livremente seu pr\u00f3prio status pol\u00edtica e livremente buscam seu desenvolvimento econ\u00f4mico, social e cultural (Art. 3). No exerc\u00edcio de seu direito \u00e0 autodetermina\u00e7\u00e3o, os povos ind\u00edgenas podem reivindicar a autonomia nas quest\u00f5es relativas a seus assuntos internos e locais (Art. 4). E do art. 6 da Conven\u00e7\u00e3o 169 da Organiza\u00e7\u00e3o Internacional do Trabalho (OIT) sobre os povos ind\u00edgenas e tribais, de 1989, deriva seu direito de n\u00e3o estarem sujeitos a medidas legislativas ou administrativas que possam afet\u00e1-los diretamente sem antes terem sido consultados &#8217;em boa-f\u00e9 e de forma adequada \u00e0s circunst\u00e2ncias&#8217;, para que deem seu pr\u00e9vio consentimento, livre e informado<\/em>&#8221; (<a href=\"http:\/\/www.ihu.unisinos.br\/78-noticias\/590944-o-sinodo-para-a-amazonia-e-os-direitos-humanos-povos-comunidades-e-estados-em-dialogo-artigo-de-pedro-barreto-cardeal-peruano\">Pedro Barreto<\/a> SJ, S\u00ednodo para a Amaz\u00f4nia e direitos humanos: Povos, comunidades e estados em di\u00e1logo, <em>La Civilt\u00e0 Cattolica<\/em>, 20 de julho de 2019).<\/p>\n<p>Na realidade, \u00e9 justamente a desigualdade das for\u00e7as e, em muitos casos, a flagrante falta de respeito pelos direitos constitucionais, al\u00e9m da imposi\u00e7\u00e3o de um chamado <strong>modelo de desenvolvimento<\/strong>, que continua a causar grande desarticula\u00e7\u00e3o social, vulnerabilidade, degrada\u00e7\u00e3o das rela\u00e7\u00f5es, migra\u00e7\u00e3o, desemprego, viol\u00eancia e fome em muitas comunidades ind\u00edgenas. A falta de reconhecimento, demarca\u00e7\u00e3o e propriedade dos territ\u00f3rios (condi\u00e7\u00e3o <em>sine qua non<\/em> para a seguran\u00e7a, para a estabilidade da comunidade e sobreviv\u00eancia cultural) levou a um n\u00famero alarmante de mortes devido a novas doen\u00e7as ou de natureza violenta. &#8220;<em>Questionar o poder na defesa do territ\u00f3rio e dos direitos humanos significa arriscar a pr\u00f3pria vida, abrindo um caminho de cruz e de mart\u00edrio<\/em>&#8221; (IL 145).<\/p>\n<p>O<strong> IL<\/strong> d\u00e1 o exemplo dos <strong>1119 ind\u00edgenas que foram mortos<\/strong> entre 2003 e 2017 apenas no Brasil &#8220;por defender seus territ\u00f3rios&#8221; (Cf. Conselho Indigenista Mission\u00e1rio, CNBB, Brasil, Relat\u00f3rio de Viol\u00eancia contra os Povos Ind\u00edgenas no Brasil &#8211; Dados de 2017, p. 84ss, cf. tamb\u00e9m a apresenta\u00e7\u00e3o de dom <a href=\"http:\/\/www.ihu.unisinos.br\/591138-esse-governo-nao-esta-enganando-ninguem-denuncia-dom-roque-paloschi-apos-assassinato-de-lider-indigena\">Roque Paloschi<\/a>: \u201cNa aus\u00eancia da justi\u00e7a, a viol\u00eancia cotidiana devasta como as vidas dentro e fora das terras ind\u00edgenas\u201d, p. 9, Bras\u00edlia, 2018.). Na verdade, em muitos casos, essas mortes s\u00e3o atribu\u00edveis \u00e0 embriaguez, viol\u00eancia dom\u00e9stica ou brigas entre pessoas. Em geral, no entanto, devem ser consideradas consequ\u00eancias de causas tanto ambientais como sociais e estruturais, de problemas decorrentes da falta de demarca\u00e7\u00e3o de territ\u00f3rios e da invas\u00e3o dos mesmos por poderosos interesses externos.<\/p>\n<p>A Igreja, no seu papel pastoral, trabalha em favor das v\u00edtimas e, em seu papel prof\u00e9tico, op\u00f5e-se aos abusos. Ela \u00e9 chamada a ser &#8220;uma defensora da justi\u00e7a e defensora dos pobres&#8221;. O <strong>Papa Bento XVI<\/strong> lembrou-o na <a href=\"http:\/\/www.ihuonline.unisinos.br\/edicao\/224\">Confer\u00eancia de Aparecida<\/a> em seu discurso inaugural (n\u00ba 395). Sua presen\u00e7a \u00e9, na realidade, &#8220;um prisma que nos permite identificar os pontos fr\u00e1geis da resposta dos estados e das sociedades como tais, diante de situa\u00e7\u00f5es urgentes, sobre as quais, independentemente da Igreja, existem d\u00edvidas concretas e hist\u00f3ricas que eles n\u00e3o podem ignorar&#8221; (Pedro Barreto SJ, art. cit.). Ao mesmo tempo, a Igreja v\u00ea &#8220;com consci\u00eancia cr\u00edtica&#8221;, como acontece com todos os povos entre os quais evangeliza, &#8220;uma s\u00e9rie de comportamentos e realidades dos povos ind\u00edgenas que v\u00e3o contra o Evangelho&#8221; (IL 144).<\/p>\n<p>Os Pont\u00edfices, partindo do <strong>Papa Le\u00e3o XIII<\/strong> no final do s\u00e9culo XIX, o <a href=\"http:\/\/www.ihu.unisinos.br\/78-noticias\/588394-reabre-se-o-processo-contra-o-concilio-vaticano-ii-artigo-de-massimo-faggioli\">Conc\u00edlio Vaticano II<\/a> e a <strong>Doutrina Social da Igreja<\/strong> oferecem diretrizes claras. Em resposta a um modelo dominante de sociedade que produz exclus\u00e3o e desigualdade, e um modelo econ\u00f4mico que mata os homens e as mulheres mais vulner\u00e1veis e destr\u00f3i a casa comum, a miss\u00e3o da Igreja inclui um compromisso prof\u00e9tico com a dignidade de todos os seres humanos. sem distin\u00e7\u00e3o, a justi\u00e7a, a paz e a integridade da cria\u00e7\u00e3o.<\/p>\n<p>Como o <strong>Papa Francisco<\/strong> disse claramente: &#8220;<em>Eu acredito que o problema essencial \u00e9 como conciliar o direito ao desenvolvimento, incluindo aquele social e cultural, com a prote\u00e7\u00e3o das caracter\u00edsticas pr\u00f3prias dos ind\u00edgenas e de seus territ\u00f3rios. [&#8230;] Nesse sentido, o direito ao consenso pr\u00e9vio e informado deve sempre prevalecer<\/em>&#8221; (Discurso aos representantes dos povos ind\u00edgenas, por ocasi\u00e3o da 40\u00aa sess\u00e3o do Conselho de Governadores do Fundo Internacional para o Desenvolvimento Agr\u00edcola, FIDA, 15 de fevereiro de 2017). Tamb\u00e9m em <strong>Puerto Maldonado<\/strong>, o Papa afirmou: \u201c<em>considero imprescind\u00edvel fazer esfor\u00e7os para criar espa\u00e7os institucionais de respeito, reconhecimento e di\u00e1logo com os povos nativos; assumindo e resgatando cultura, l\u00edngua, tradi\u00e7\u00f5es, direitos e espiritualidade que lhes s\u00e3o pr\u00f3prios<\/em>&#8221; (19 de janeiro de 2018).<\/p>\n<p>Na <strong>Amaz\u00f4nia<\/strong>, o &#8220;<strong>bom viver<\/strong>&#8221; dos<strong> povos ind\u00edgenas<\/strong> depende principalmente da demarca\u00e7\u00e3o de seus territ\u00f3rios e de seu respeito escrupuloso. &#8220;A pol\u00edtica &#8211; disse S\u00e3o Jo\u00e3o Paulo II &#8211; \u00e9 o uso do poder leg\u00edtimo para alcan\u00e7ar o bem comum da sociedade&#8221; (Discurso no &#8220;Jubileu dos Governantes e Parlamentares&#8221;, 4 de novembro de 2000). A tarefa fundamental da pol\u00edtica \u00e9 assegurar uma ordem social justa, e a Igreja &#8220;n\u00e3o pode [e nem] deve permanecer \u00e0 margem na luta pela justi\u00e7a&#8221; (Deus caritas est, 28; <a href=\"http:\/\/www.ihu.unisinos.br\/185-noticias\/noticias-2016\/551813-evangelii-gaudium-promove-a-liturgia-autentica-um-ponto-de-inflexao-em-direcao-a-sexta-instrucao-sobre-a-reforma-da-liturgia-artigo-de-andrea-grillo\">Evangelii gaudium<\/a>, 183). Assim, a Igreja est\u00e1 ao lado dos <strong>povos ind\u00edgenas<\/strong> no cuidado de seu territ\u00f3rio.<\/p>\n<p>Com todas essas grandes din\u00e2micas e desafios, amea\u00e7as e promessas que est\u00e3o presentes em nossa mente e tamb\u00e9m em nossa ora\u00e7\u00e3o, recordamos as palavras do Papa Francisco, que abre o \u00faltimo cap\u00edtulo da Eg. &#8220;<em>Do cora\u00e7\u00e3o do Evangelho reconhecemos a \u00edntima conex\u00e3o entre evangeliza\u00e7\u00e3o e promo\u00e7\u00e3o humana, que deve necessariamente se expressar e desenvolver em toda a\u00e7\u00e3o evangelizadora<\/em>&#8221; (Eg 178).<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\"><a href=\"http:\/\/www.ihu.unisinos.br\/78-noticias\/581179-michael-czerny-sobre-o-trafico-de-seres-humanos-e-as-escravidoes-modernas-derrubar-os-muros-da-hipocrisia\">Michael Czerny<\/a> SJ,<\/p>\n<p style=\"text-align: right;\">secret\u00e1rio do Dicast\u00e9rio pelo servi\u00e7o do desenvolvimento humano integral<\/p>\n<p style=\"text-align: right;\">Secret\u00e1rio Especial do S\u00ednodo para a Amaz\u00f4nia<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como o Bom Samaritano, a Igreja quer implementar seu compromisso com a compaix\u00e3o e com a justi\u00e7a do Evangelho na Amaz\u00f4nia. Ela \u00e9 chamada a observar e compreender, para depois se abrir para o di\u00e1logo e agir. Esta \u00e9 a raz\u00e3o pela qual o Papa Francisco convocou um S\u00ednodo dos Bispos para a regi\u00e3o Pan-Amaz\u00f4nica. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2961,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[285,4],"tags":[264],"class_list":["post-2960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales","category-noticias","tag-sinodo-de-la-amazonia"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Igreja na Amaz\u00f4nia e o desenvolvimento humano integral: Compromisso prof\u00e9tico com a dignidade de todos os povos - REPAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repam.net\/es\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Igreja na Amaz\u00f4nia e o desenvolvimento humano integral: Compromisso prof\u00e9tico com a dignidade de todos os povos - REPAM\" \/>\n<meta property=\"og:description\" content=\"Como o Bom Samaritano, a Igreja quer implementar seu compromisso com a compaix\u00e3o e com a justi\u00e7a do Evangelho na Amaz\u00f4nia. Ela \u00e9 chamada a observar e compreender, para depois se abrir para o di\u00e1logo e agir. Esta \u00e9 a raz\u00e3o pela qual o Papa Francisco convocou um S\u00ednodo dos Bispos para a regi\u00e3o Pan-Amaz\u00f4nica. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repam.net\/es\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\/\" \/>\n<meta property=\"og:site_name\" content=\"REPAM\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-02T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/czerny-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"repam@adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repam@adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\\\/\"},\"author\":{\"name\":\"repam@adm\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\"},\"headline\":\"A Igreja na Amaz\u00f4nia e o desenvolvimento humano integral: Compromisso prof\u00e9tico com a dignidade de todos os povos\",\"datePublished\":\"2019-09-02T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\\\/\"},\"wordCount\":1687,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/czerny-1.jpg\",\"keywords\":[\"S\u00ednodo de la Amazon\u00eda\"],\"articleSection\":[\"Internacionales\",\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\\\/\",\"name\":\"A Igreja na Amaz\u00f4nia e o desenvolvimento humano integral: Compromisso prof\u00e9tico com a dignidade de todos os povos - REPAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/czerny-1.jpg\",\"datePublished\":\"2019-09-02T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repam.net\\\/es\\\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/czerny-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/czerny-1.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Igreja na Amaz\u00f4nia e o desenvolvimento humano integral: Compromisso prof\u00e9tico com a dignidade de todos os povos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"name\":\"REPAM\",\"description\":\"Red Eclesial Panamaz\u00f3nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repam.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\",\"name\":\"REPAM\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"REPAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\",\"name\":\"repam@adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"caption\":\"repam@adm\"},\"sameAs\":[\"http:\\\/\\\/repam.net\"],\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/author\\\/repamadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Igreja na Amaz\u00f4nia e o desenvolvimento humano integral: Compromisso prof\u00e9tico com a dignidade de todos os povos - REPAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repam.net\/es\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\/","og_locale":"es_ES","og_type":"article","og_title":"A Igreja na Amaz\u00f4nia e o desenvolvimento humano integral: Compromisso prof\u00e9tico com a dignidade de todos os povos - REPAM","og_description":"Como o Bom Samaritano, a Igreja quer implementar seu compromisso com a compaix\u00e3o e com a justi\u00e7a do Evangelho na Amaz\u00f4nia. Ela \u00e9 chamada a observar e compreender, para depois se abrir para o di\u00e1logo e agir. Esta \u00e9 a raz\u00e3o pela qual o Papa Francisco convocou um S\u00ednodo dos Bispos para a regi\u00e3o Pan-Amaz\u00f4nica. [&hellip;]","og_url":"https:\/\/www.repam.net\/es\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\/","og_site_name":"REPAM","article_published_time":"2019-09-02T05:00:00+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/czerny-1.jpg","type":"image\/jpeg"}],"author":"repam@adm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"repam@adm","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repam.net\/es\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\/#article","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\/"},"author":{"name":"repam@adm","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033"},"headline":"A Igreja na Amaz\u00f4nia e o desenvolvimento humano integral: Compromisso prof\u00e9tico com a dignidade de todos os povos","datePublished":"2019-09-02T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repam.net\/es\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\/"},"wordCount":1687,"publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"image":{"@id":"https:\/\/www.repam.net\/es\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/czerny-1.jpg","keywords":["S\u00ednodo de la Amazon\u00eda"],"articleSection":["Internacionales","Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.repam.net\/es\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\/","url":"https:\/\/www.repam.net\/es\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\/","name":"A Igreja na Amaz\u00f4nia e o desenvolvimento humano integral: Compromisso prof\u00e9tico com a dignidade de todos os povos - REPAM","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repam.net\/es\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\/#primaryimage"},"image":{"@id":"https:\/\/www.repam.net\/es\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/czerny-1.jpg","datePublished":"2019-09-02T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.repam.net\/es\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repam.net\/es\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\/#primaryimage","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/czerny-1.jpg","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/czerny-1.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/www.repam.net\/es\/a-igreja-na-amazonia-e-o-desenvolvimento-humano-integral-compromisso-profetico-com-a-dignidade-de-todos-os-povos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repam.net\/es\/"},{"@type":"ListItem","position":2,"name":"A Igreja na Amaz\u00f4nia e o desenvolvimento humano integral: Compromisso prof\u00e9tico com a dignidade de todos os povos"}]},{"@type":"WebSite","@id":"https:\/\/www.repam.net\/es\/#website","url":"https:\/\/www.repam.net\/es\/","name":"REPAM","description":"Red Eclesial Panamaz\u00f3nica","publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repam.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.repam.net\/es\/#organization","name":"REPAM","url":"https:\/\/www.repam.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","width":512,"height":512,"caption":"REPAM"},"image":{"@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033","name":"repam@adm","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","caption":"repam@adm"},"sameAs":["http:\/\/repam.net"],"url":"https:\/\/www.repam.net\/es\/author\/repamadm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/comments?post=2960"}],"version-history":[{"count":0,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2960\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media\/2961"}],"wp:attachment":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media?parent=2960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/categories?post=2960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/tags?post=2960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}