{"id":2990,"date":"2019-07-07T00:00:00","date_gmt":"2019-07-07T05:00:00","guid":{"rendered":"http:\/\/repam.net\/informe-proceso-de-consulta-sinodal-realizado-por-repam\/"},"modified":"2021-09-29T18:46:10","modified_gmt":"2021-09-29T23:46:10","slug":"informe-proceso-de-consulta-sinodal-realizado-por-repam","status":"publish","type":"post","link":"https:\/\/www.repam.net\/es\/informe-proceso-de-consulta-sinodal-realizado-por-repam\/","title":{"rendered":"Informe proceso de consulta sinodal realizado por REPAM"},"content":{"rendered":"<p>La REPAM ha sido encomendada formalmente para apoyar a la Secretar&iacute;a del S&iacute;nodo y al Consejo Pre Sinodal, presidido por el Papa Francisco, en el proceso de escucha activa y directa en la amplitud del territorio Panamaz&oacute;nico, en el levantamiento de la informaci&oacute;n de manera adecuada para ayudar en la elaboraci&oacute;n del Documento Preparatorio (Lineamenta) y del Documento de Trabajo (Instrumentum Laboris) que se ha elaborado considerando los diversos aportes del proceso de escucha, y para animar la mayor participaci&oacute;n posible de los diversos actores en la<br \/>Amazon&iacute;a.<\/p>\n<p>A trav&eacute;s de este documento desde la Secretar&iacute;a Ejecutiva de la REPAM, queremos agradecer profundamente a cada una de las manos en las REPAM Nacionales, Ejes, y otras instancias y grupos eclesiales y afines, que representan tantas personas a lo largo de la Panamazon&iacute;a por asumir el llamado de la consulta sinodal territorial. Sobre todo, a quienes conformaron los equipos locales en las jurisdicciones eclesi&aacute;sticas y REPAMs Nacionales, a las\/os sistematizadoras\/es, a los Obispos, a las instituciones animadoras en cada uno de los pa&iacute;ses y a todas\/os los participantes que, con el testimonio desde su vida, sentir y sue&ntilde;os, expresaron sus anhelos y expectativas y los pusieron en la mesa de la comuni&oacute;n en este proceso de escucha sinodal.<\/p>\n<p><em>&ldquo;A cada uno\/a de ustedes que colaboraron en este proceso que aspira a cumplir un sue&ntilde;o mayor, a quienes asumieron con valent&iacute;a la misi&oacute;n de generar todos los espacios de escucha sinodal que se requer&iacute;an les expresamos un agradecimiento profundo&rdquo;<\/em><\/p>\n<p>El presente informe recoge los detalles sobre c&oacute;mo se desarroll&oacute; el proceso de consulta Sinodal animado por la REPAM en los 9 pa&iacute;ses de la Panamazon&iacute;a, y sobre todo plantea los pasos pr&oacute;ximos que consideramos esenciales para continuar tejiendo red como iglesia en la Panamazon&iacute;a.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center\"><strong><a href=\"https:\/\/redamazonica.org\/wp-content\/uploads\/INFORME-camino.recorrido.REPAM_.S%C3%ADnodo..pdf\">DESCARGA EL INFORME COMPLETO AQU&Iacute;<\/a><\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>Como REPAM desarrollamos una estrategia con los miembros de los ejes de trabajo y las redes nacionales para identificar tres niveles de consulta sinodal. En la planificaci&oacute;n Inicial se definieron 50 encuentros: 40 Asambleas Territoriales Sinodales, 8 Foros Tem&aacute;ticos Panamaz&oacute;nicos y 2 Foros<br \/>Internacionales. Sin embargo, el proceso desencaden&oacute; en casi cinco veces m&aacute;s el n&uacute;mero de actividades planificadas. Inicialmente se hab&iacute;an definido Asambleas Territoriales Sinodales y Foros tem&aacute;ticos, sin embargo, a trav&eacute;s de los planteamientos de los pa&iacute;ses se crean dos espacios adicionales de escucha: Foros Tem&aacute;ticos Nacionales y Ruedas de conversaci&oacute;n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"  aligncenter\" src=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/proceso-informe.png\" alt=\"\" width=\"594\" height=\"498\"><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La REPAM ha sido encomendada formalmente para apoyar a la Secretar&iacute;a del S&iacute;nodo y al Consejo Pre Sinodal, presidido por el Papa Francisco, en el proceso de escucha activa y directa en la amplitud del territorio Panamaz&oacute;nico, en el levantamiento de la informaci&oacute;n de manera adecuada para ayudar en la elaboraci&oacute;n del Documento Preparatorio (Lineamenta) [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2991,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[285,4],"tags":[264],"class_list":["post-2990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales","category-noticias","tag-sinodo-de-la-amazonia"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Informe proceso de consulta sinodal realizado por REPAM - REPAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repam.net\/es\/informe-proceso-de-consulta-sinodal-realizado-por-repam\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informe proceso de consulta sinodal realizado por REPAM - REPAM\" \/>\n<meta property=\"og:description\" content=\"La REPAM ha sido encomendada formalmente para apoyar a la Secretar&iacute;a del S&iacute;nodo y al Consejo Pre Sinodal, presidido por el Papa Francisco, en el proceso de escucha activa y directa en la amplitud del territorio Panamaz&oacute;nico, en el levantamiento de la informaci&oacute;n de manera adecuada para ayudar en la elaboraci&oacute;n del Documento Preparatorio (Lineamenta) [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repam.net\/es\/informe-proceso-de-consulta-sinodal-realizado-por-repam\/\" \/>\n<meta property=\"og:site_name\" content=\"REPAM\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-07T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-29T23:46:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/portada-informe.png\" \/>\n\t<meta property=\"og:image:width\" content=\"449\" \/>\n\t<meta property=\"og:image:height\" content=\"538\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"repam@adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repam@adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/informe-proceso-de-consulta-sinodal-realizado-por-repam\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/informe-proceso-de-consulta-sinodal-realizado-por-repam\\\/\"},\"author\":{\"name\":\"repam@adm\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\"},\"headline\":\"Informe proceso de consulta sinodal realizado por REPAM\",\"datePublished\":\"2019-07-07T05:00:00+00:00\",\"dateModified\":\"2021-09-29T23:46:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/informe-proceso-de-consulta-sinodal-realizado-por-repam\\\/\"},\"wordCount\":470,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/informe-proceso-de-consulta-sinodal-realizado-por-repam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/portada-informe.png\",\"keywords\":[\"S\u00ednodo de la Amazon\u00eda\"],\"articleSection\":[\"Internacionales\",\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/informe-proceso-de-consulta-sinodal-realizado-por-repam\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/informe-proceso-de-consulta-sinodal-realizado-por-repam\\\/\",\"name\":\"Informe proceso de consulta sinodal realizado por REPAM - REPAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/informe-proceso-de-consulta-sinodal-realizado-por-repam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/informe-proceso-de-consulta-sinodal-realizado-por-repam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/portada-informe.png\",\"datePublished\":\"2019-07-07T05:00:00+00:00\",\"dateModified\":\"2021-09-29T23:46:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/informe-proceso-de-consulta-sinodal-realizado-por-repam\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repam.net\\\/es\\\/informe-proceso-de-consulta-sinodal-realizado-por-repam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/informe-proceso-de-consulta-sinodal-realizado-por-repam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/portada-informe.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/portada-informe.png\",\"width\":449,\"height\":538},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/informe-proceso-de-consulta-sinodal-realizado-por-repam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informe proceso de consulta sinodal realizado por REPAM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"name\":\"REPAM\",\"description\":\"Red Eclesial Panamaz\u00f3nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repam.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\",\"name\":\"REPAM\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"REPAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\",\"name\":\"repam@adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"caption\":\"repam@adm\"},\"sameAs\":[\"http:\\\/\\\/repam.net\"],\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/author\\\/repamadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informe proceso de consulta sinodal realizado por REPAM - REPAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repam.net\/es\/informe-proceso-de-consulta-sinodal-realizado-por-repam\/","og_locale":"es_ES","og_type":"article","og_title":"Informe proceso de consulta sinodal realizado por REPAM - REPAM","og_description":"La REPAM ha sido encomendada formalmente para apoyar a la Secretar&iacute;a del S&iacute;nodo y al Consejo Pre Sinodal, presidido por el Papa Francisco, en el proceso de escucha activa y directa en la amplitud del territorio Panamaz&oacute;nico, en el levantamiento de la informaci&oacute;n de manera adecuada para ayudar en la elaboraci&oacute;n del Documento Preparatorio (Lineamenta) [&hellip;]","og_url":"https:\/\/www.repam.net\/es\/informe-proceso-de-consulta-sinodal-realizado-por-repam\/","og_site_name":"REPAM","article_published_time":"2019-07-07T05:00:00+00:00","article_modified_time":"2021-09-29T23:46:10+00:00","og_image":[{"width":449,"height":538,"url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/portada-informe.png","type":"image\/png"}],"author":"repam@adm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"repam@adm","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repam.net\/es\/informe-proceso-de-consulta-sinodal-realizado-por-repam\/#article","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/informe-proceso-de-consulta-sinodal-realizado-por-repam\/"},"author":{"name":"repam@adm","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033"},"headline":"Informe proceso de consulta sinodal realizado por REPAM","datePublished":"2019-07-07T05:00:00+00:00","dateModified":"2021-09-29T23:46:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repam.net\/es\/informe-proceso-de-consulta-sinodal-realizado-por-repam\/"},"wordCount":470,"publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"image":{"@id":"https:\/\/www.repam.net\/es\/informe-proceso-de-consulta-sinodal-realizado-por-repam\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/portada-informe.png","keywords":["S\u00ednodo de la Amazon\u00eda"],"articleSection":["Internacionales","Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.repam.net\/es\/informe-proceso-de-consulta-sinodal-realizado-por-repam\/","url":"https:\/\/www.repam.net\/es\/informe-proceso-de-consulta-sinodal-realizado-por-repam\/","name":"Informe proceso de consulta sinodal realizado por REPAM - REPAM","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repam.net\/es\/informe-proceso-de-consulta-sinodal-realizado-por-repam\/#primaryimage"},"image":{"@id":"https:\/\/www.repam.net\/es\/informe-proceso-de-consulta-sinodal-realizado-por-repam\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/portada-informe.png","datePublished":"2019-07-07T05:00:00+00:00","dateModified":"2021-09-29T23:46:10+00:00","breadcrumb":{"@id":"https:\/\/www.repam.net\/es\/informe-proceso-de-consulta-sinodal-realizado-por-repam\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repam.net\/es\/informe-proceso-de-consulta-sinodal-realizado-por-repam\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/informe-proceso-de-consulta-sinodal-realizado-por-repam\/#primaryimage","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/portada-informe.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/portada-informe.png","width":449,"height":538},{"@type":"BreadcrumbList","@id":"https:\/\/www.repam.net\/es\/informe-proceso-de-consulta-sinodal-realizado-por-repam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repam.net\/es\/"},{"@type":"ListItem","position":2,"name":"Informe proceso de consulta sinodal realizado por REPAM"}]},{"@type":"WebSite","@id":"https:\/\/www.repam.net\/es\/#website","url":"https:\/\/www.repam.net\/es\/","name":"REPAM","description":"Red Eclesial Panamaz\u00f3nica","publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repam.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.repam.net\/es\/#organization","name":"REPAM","url":"https:\/\/www.repam.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","width":512,"height":512,"caption":"REPAM"},"image":{"@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033","name":"repam@adm","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","caption":"repam@adm"},"sameAs":["http:\/\/repam.net"],"url":"https:\/\/www.repam.net\/es\/author\/repamadm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/comments?post=2990"}],"version-history":[{"count":1,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2990\/revisions"}],"predecessor-version":[{"id":3001,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/2990\/revisions\/3001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media\/2991"}],"wp:attachment":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media?parent=2990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/categories?post=2990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/tags?post=2990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}