{"id":3525,"date":"2018-07-30T00:00:00","date_gmt":"2018-07-30T05:00:00","guid":{"rendered":"http:\/\/repam.net\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\/"},"modified":"2018-07-30T00:00:00","modified_gmt":"2018-07-30T05:00:00","slug":"cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras","status":"publish","type":"post","link":"https:\/\/www.repam.net\/es\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\/","title":{"rendered":"CIR repudia ataque de garimpeiros ao povo Yanomami do grupo isolado Moxihat\u00e9t\u00e9a e pede provid\u00eancias urgentes \u00e0s autoridades brasileiras"},"content":{"rendered":"<p>Com preocupa\u00e7\u00e3o e indigna\u00e7\u00e3o, o Conselho Ind\u00edgena de Roraima (CIR), organiza\u00e7\u00e3o ind\u00edgena de defesa dos direitos e interesses dos povos ind\u00edgenas de Roraima recebeu a not\u00edcia do ataque\u00a0por garimpeiros de dois yanomami, com mortes,\u00a0do grupo isolado Moxihatetea que vive na Serra da Estrutura, na Terra Ind\u00edgena Yanomami (TI Y), Roraima, de acordo com a CARTA\/HAY N\u00b0 051 \/2018, enviada ao Presidente da Funda\u00e7\u00e3o Nacional do \u00cdndio (FUNAI), Minist\u00e9rio P\u00fablico Federal (MPF) e Superintend\u00eancia da Pol\u00edcia Federal de Roraima, denunciando o caso.<u><\/u><u><\/u><\/p>\n<p>Conforme a Carta, os homic\u00eddios ocorreram no m\u00eas de maio em conflito que se originou quando um garimpeiro estava roubando a ro\u00e7a dos Moxihat\u00e9t\u00e9a, segundo relato coletado pela assessoria ind\u00edgena do Distrito Sanit\u00e1rio Especial Ind\u00edgena Yanomami (DSEI-Y). \u201cA equipe de sa\u00fade do DSEI Y teve conhecimento do caso durante uma reuni\u00e3o realizada em 18 de julho na regi\u00e3o do Alto Catrimani, Terra Ind\u00edgena Yanomami Roraima que fica pr\u00f3xima \u00e0 \u00e1rea onde vivem os isolados e que est\u00e1 invadida por centenas de garimpeiros. Na ocasi\u00e3o, jovens yanomami relataram que ouviram dos pr\u00f3prios garimpeiros sobre o conflito e as mortes, e repassaram para a equipe de sa\u00fade\u201d, registra a Carta.<u><\/u><u><\/u><\/p>\n<p>Segundo a Hutukara Associa\u00e7\u00e3o Yanomami (HAY) o grupo isolado possui aproximadamente 80 pessoas, est\u00e3o localizados na Serra da Estrutura e acompanhados pela FUNAI. O grupo corre graves riscos de sobreviv\u00eancia, pois na regi\u00e3o habitada pelo grupo isolado h\u00e1 atividades garimpeiras a menos de 5 km da casa coletiva, segundo a Carta. A base de prote\u00e7\u00e3o, criada em 2012, est\u00e1 abandonada desde 2015, quando garimpeiros passaram a controlar o local, utilizando tanto da estrutura (pr\u00e9dio) quanto da pista de pouso, que serve de apoio \u00e0s atividades il\u00edcitas.<u><\/u><u><\/u><\/p>\n<p>A Carta registra ainda que, os Yanomami da regi\u00e3o do Alto Catrimani tamb\u00e9m est\u00e3o solicitando que as autoridades brasileiras retirem imediatamente os garimpeiros pois &#8220;<b><i>eles est\u00e3o matando os Moxihatetea, tamb\u00e9m eles est\u00e3o poluindo o nosso rio e prejudicando a nossa sa\u00fade, eles est\u00e3o deixando grande impacto ambiental no nosso territ\u00f3rio<\/i><\/b><i>,<\/i>\u00a0&#8221; segundo uma lideran\u00e7a da regi\u00e3o. (CARTA\/HAY N\u00b0 051 \/2018).<u><\/u><u><\/u><\/p>\n<p>Diante dessa grave den\u00fancia, o Conselho Ind\u00edgena de Roraima (CIR), que h\u00e1 d\u00e9cadas vem acompanhando o descaso e a omiss\u00e3o das autoridades brasileiras em rela\u00e7\u00e3o ao garimpo ilegal na Terra Ind\u00edgena Yanomami e que se alastra a outras terras ind\u00edgenas do Estado, como a Terra Ind\u00edgena Boqueir\u00e3o, na regi\u00e3o do Tabaio, regi\u00e3o de Amajari e bem pr\u00f3ximo, a capital roraimense, Boa Vista, refor\u00e7a a den\u00fancia feita na 47\u00aa Assembleia Geral dos Povos Ind\u00edgenas de Roraima, realizada no m\u00eas de mar\u00e7o desse ano, no Centro Regional do Lago Caracaran\u00e3, onde, mais de 3 mil ind\u00edgenas manifestaram rep\u00fadio ao garimpo ilegal na TI Yanomami.\u00a0\u00a0\u00a0\u00a0\u00a0<u><\/u><u><\/u><\/p>\n<p>&#8211; Garimpo s\u00f3 traz morte e destrui\u00e7\u00e3o! Queremos a rejei\u00e7\u00e3o do PL 1610\/96 de autoria do Senador Romero Juc\u00e1. Esse projeto \u00e9 ruim para os povos ind\u00edgenas, pois n\u00e3o estabelece salvaguardas e n\u00e3o garante o direito a consulta aos povos ind\u00edgenas. Nossa assembleia denuncia que os garimpos tem trazido \u00e0 polui\u00e7\u00e3o dos rios, a degrada\u00e7\u00e3o do meio ambiente, contamina\u00e7\u00e3o por merc\u00fario, e afeta a sa\u00fade ind\u00edgena. Os efeitos v\u00e3o al\u00e9m da TI Yanomami, uma vez que garimpeiros entram pela terra ind\u00edgena Boqueir\u00e3o, e a contamina\u00e7\u00e3o por merc\u00fario que ocorrem ao rio Uraricoera atinge outras comunidades ind\u00edgenas que utilizam das \u00e1guas do rio para seu consumo. (Carta da 47\u00aa. Assembleia Geral dos Povos Ind\u00edgenas de Roraima,\u00a0Centro Regional Lago Caracaran\u00e3, Raposa, TI Raposa Serra do Sol\u2013RR, 14 de Mar\u00e7o de 2018)\u00a0\u00a0<u><\/u><u><\/u><\/p>\n<p>Neste fato recente, o CIR, organiza\u00e7\u00e3o ind\u00edgena de atua\u00e7\u00e3o nacional e internacional, pede provid\u00eancias urgentes \u00e0s autoridades brasileiras na apura\u00e7\u00e3o e puni\u00e7\u00e3o desse caso do povo Yanomami do grupo isolado\u00a0<b>Moxihat\u00e9t\u00e9a.\u00a0<\/b>\u00a0<u><\/u><u><\/u><\/p>\n<p>Chega de genoc\u00eddio dos povos origin\u00e1rios desse pa\u00eds, chega de genoc\u00eddio do povo ind\u00edgena Yanomami. Basta de garimpo ilegal em nossas terras sagradas, poluindo, degradando e matando, nossos rios, florestas, biodiversidade e, principalmente, matando o povo ind\u00edgena.<u><\/u><u><\/u><\/p>\n<p><b>Sobre a epidemia de sarampo<u><\/u><u><\/u><\/b><\/p>\n<p><u><\/u>\u00a0<u><\/u><\/p>\n<p>Da mesma forma, o CIR, refor\u00e7a\u00a0o pedido de aten\u00e7\u00e3o especial \u00e0 sa\u00fade do povo Yanomami da Venezuela que sofrem o surto de sarampo, conforme\u00a0Carta n. 0049\/2018 HAY, de 18 de julho de 2018, onde informa sobre a epidemia de Sarampo que atinge os San\u00f6ma no Polo Base Awaris.<u><\/u><u><\/u><\/p>\n<p><u><\/u>\u00a0<u><\/u><\/p>\n<p>H\u00e1 meses que organiza\u00e7\u00f5es ind\u00edgenas da Venezuela, como\u00a0Wataniba e OEPA\u00a0vem alertando sobre o caso, e desta vez, a Hutukara Associa\u00e7\u00e3o Yanomami (HAY). Um caso que requer aten\u00e7\u00e3o das autoridades p\u00fablicas, urgentemente, para que n\u00e3o ocorra uma cat\u00e1strofe com o povo Yanomami da Venezuela e nem do Brasil.<u><\/u><u><\/u><\/p>\n<p><u><\/u>\u00a0<u><\/u><\/p>\n<p>O CIR, tamb\u00e9m pede apura\u00e7\u00e3o da causa de contamina\u00e7\u00e3o que, pelo hist\u00f3rico de invas\u00e3o de garimpeiros a Terra Ind\u00edgena\u00a0\u00a0Yanomami, \u00e9 poss\u00edvel que a contamina\u00e7\u00e3o n\u00e3o seja somente pela grave crise do pa\u00eds venezuelano, mas pelo ataque de garimpeiros na regi\u00e3o, conforme j\u00e1 denunciado pelo l\u00edder Davi Kapenawa Yanomami.<u><\/u><u><\/u><\/p>\n<p><u><\/u><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com preocupa\u00e7\u00e3o e indigna\u00e7\u00e3o, o Conselho Ind\u00edgena de Roraima (CIR), organiza\u00e7\u00e3o ind\u00edgena de defesa dos direitos e interesses dos povos ind\u00edgenas de Roraima recebeu a not\u00edcia do ataque\u00a0por garimpeiros de dois yanomami, com mortes,\u00a0do grupo isolado Moxihatetea que vive na Serra da Estrutura, na Terra Ind\u00edgena Yanomami (TI Y), Roraima, de acordo com a CARTA\/HAY [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3526,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[384,4],"tags":[693],"class_list":["post-3525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-denuncia","category-noticias","tag-matanza-a-grupo-isolado"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CIR repudia ataque de garimpeiros ao povo Yanomami do grupo isolado Moxihat\u00e9t\u00e9a e pede provid\u00eancias urgentes \u00e0s autoridades brasileiras - REPAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repam.net\/es\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CIR repudia ataque de garimpeiros ao povo Yanomami do grupo isolado Moxihat\u00e9t\u00e9a e pede provid\u00eancias urgentes \u00e0s autoridades brasileiras - REPAM\" \/>\n<meta property=\"og:description\" content=\"Com preocupa\u00e7\u00e3o e indigna\u00e7\u00e3o, o Conselho Ind\u00edgena de Roraima (CIR), organiza\u00e7\u00e3o ind\u00edgena de defesa dos direitos e interesses dos povos ind\u00edgenas de Roraima recebeu a not\u00edcia do ataque\u00a0por garimpeiros de dois yanomami, com mortes,\u00a0do grupo isolado Moxihatetea que vive na Serra da Estrutura, na Terra Ind\u00edgena Yanomami (TI Y), Roraima, de acordo com a CARTA\/HAY [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repam.net\/es\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\/\" \/>\n<meta property=\"og:site_name\" content=\"REPAM\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-30T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/cir.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"310\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"repam@adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repam@adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\\\/\"},\"author\":{\"name\":\"repam@adm\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\"},\"headline\":\"CIR repudia ataque de garimpeiros ao povo Yanomami do grupo isolado Moxihat\u00e9t\u00e9a e pede provid\u00eancias urgentes \u00e0s autoridades brasileiras\",\"datePublished\":\"2018-07-30T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\\\/\"},\"wordCount\":914,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cir.jpg\",\"keywords\":[\"matanza a grupo isolado\"],\"articleSection\":[\"Denuncia\",\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\\\/\",\"name\":\"CIR repudia ataque de garimpeiros ao povo Yanomami do grupo isolado Moxihat\u00e9t\u00e9a e pede provid\u00eancias urgentes \u00e0s autoridades brasileiras - REPAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cir.jpg\",\"datePublished\":\"2018-07-30T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repam.net\\\/es\\\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cir.jpg\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cir.jpg\",\"width\":600,\"height\":310},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CIR repudia ataque de garimpeiros ao povo Yanomami do grupo isolado Moxihat\u00e9t\u00e9a e pede provid\u00eancias urgentes \u00e0s autoridades brasileiras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"name\":\"REPAM\",\"description\":\"Red Eclesial Panamaz\u00f3nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repam.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\",\"name\":\"REPAM\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"REPAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\",\"name\":\"repam@adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"caption\":\"repam@adm\"},\"sameAs\":[\"http:\\\/\\\/repam.net\"],\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/author\\\/repamadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CIR repudia ataque de garimpeiros ao povo Yanomami do grupo isolado Moxihat\u00e9t\u00e9a e pede provid\u00eancias urgentes \u00e0s autoridades brasileiras - REPAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repam.net\/es\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\/","og_locale":"es_ES","og_type":"article","og_title":"CIR repudia ataque de garimpeiros ao povo Yanomami do grupo isolado Moxihat\u00e9t\u00e9a e pede provid\u00eancias urgentes \u00e0s autoridades brasileiras - REPAM","og_description":"Com preocupa\u00e7\u00e3o e indigna\u00e7\u00e3o, o Conselho Ind\u00edgena de Roraima (CIR), organiza\u00e7\u00e3o ind\u00edgena de defesa dos direitos e interesses dos povos ind\u00edgenas de Roraima recebeu a not\u00edcia do ataque\u00a0por garimpeiros de dois yanomami, com mortes,\u00a0do grupo isolado Moxihatetea que vive na Serra da Estrutura, na Terra Ind\u00edgena Yanomami (TI Y), Roraima, de acordo com a CARTA\/HAY [&hellip;]","og_url":"https:\/\/www.repam.net\/es\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\/","og_site_name":"REPAM","article_published_time":"2018-07-30T05:00:00+00:00","og_image":[{"width":600,"height":310,"url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/cir.jpg","type":"image\/jpeg"}],"author":"repam@adm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"repam@adm","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repam.net\/es\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\/#article","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\/"},"author":{"name":"repam@adm","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033"},"headline":"CIR repudia ataque de garimpeiros ao povo Yanomami do grupo isolado Moxihat\u00e9t\u00e9a e pede provid\u00eancias urgentes \u00e0s autoridades brasileiras","datePublished":"2018-07-30T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repam.net\/es\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\/"},"wordCount":914,"publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"image":{"@id":"https:\/\/www.repam.net\/es\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/cir.jpg","keywords":["matanza a grupo isolado"],"articleSection":["Denuncia","Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.repam.net\/es\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\/","url":"https:\/\/www.repam.net\/es\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\/","name":"CIR repudia ataque de garimpeiros ao povo Yanomami do grupo isolado Moxihat\u00e9t\u00e9a e pede provid\u00eancias urgentes \u00e0s autoridades brasileiras - REPAM","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repam.net\/es\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\/#primaryimage"},"image":{"@id":"https:\/\/www.repam.net\/es\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/cir.jpg","datePublished":"2018-07-30T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.repam.net\/es\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repam.net\/es\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\/#primaryimage","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/cir.jpg","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/cir.jpg","width":600,"height":310},{"@type":"BreadcrumbList","@id":"https:\/\/www.repam.net\/es\/cir-repudia-ataque-de-garimpeiros-ao-povo-yanomami-do-grupo-isolado-moxihatetea-e-pede-providencias-urgentes-as-autoridades-brasileiras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repam.net\/es\/"},{"@type":"ListItem","position":2,"name":"CIR repudia ataque de garimpeiros ao povo Yanomami do grupo isolado Moxihat\u00e9t\u00e9a e pede provid\u00eancias urgentes \u00e0s autoridades brasileiras"}]},{"@type":"WebSite","@id":"https:\/\/www.repam.net\/es\/#website","url":"https:\/\/www.repam.net\/es\/","name":"REPAM","description":"Red Eclesial Panamaz\u00f3nica","publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repam.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.repam.net\/es\/#organization","name":"REPAM","url":"https:\/\/www.repam.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","width":512,"height":512,"caption":"REPAM"},"image":{"@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033","name":"repam@adm","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","caption":"repam@adm"},"sameAs":["http:\/\/repam.net"],"url":"https:\/\/www.repam.net\/es\/author\/repamadm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/3525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/comments?post=3525"}],"version-history":[{"count":0,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/3525\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media\/3526"}],"wp:attachment":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media?parent=3525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/categories?post=3525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/tags?post=3525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}