{"id":3689,"date":"2018-04-27T00:00:00","date_gmt":"2018-04-27T05:00:00","guid":{"rendered":"http:\/\/repam.net\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\/"},"modified":"2018-04-27T00:00:00","modified_gmt":"2018-04-27T05:00:00","slug":"voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion","status":"publish","type":"post","link":"https:\/\/www.repam.net\/es\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\/","title":{"rendered":"Voces por la defensa de las culturas y la selva: Caminos Amaz\u00f3nicos de Formaci\u00f3n"},"content":{"rendered":"<p>El encuentro que congreg\u00f3 a m\u00e1s de 30 j\u00f3venes de la Pan Amazon\u00eda, dej\u00f3 muchas proyecciones y sentires, que juntos en una sola voz, hablan de:\u00a0 <strong>defender la vida, que es defender la selva amaz\u00f3nica y sus culturas.\u00a0<\/strong><\/p>\n<p><strong>Diego &#8211; Santarem Par\u00e1:<\/strong> Soy ind\u00edgena en este encuentro de la Repam Juventudes, estamos conociendo nuevas personas, las realidades de los pa\u00edses pan amaz\u00f3nicos.\u00a0 Esta siendo muy importante, trazar estrategias para ver como enfrentar el gran capital que esta devastando nuestra tierra, con grandes proyectos, necesitamos articularnos m\u00e1s como juventud, para defender nuestro territorio. Todo lo que nosotros nos alimentamos viene de lo que nos da la tierra. No podemos ver a nuestra amazonia que se est\u00e1 acabando y sin hacer nada.<\/p>\n<p><strong>Exon Marupa &#8211; Bolivia:<\/strong>\u00a0 Este encuentro nos ha abierto la mirada hacia rescatar\u00a0las culturas que tenemos como Amazon\u00eda e impulsar el cuidado de la casa com\u00fan, impuslar a los j\u00f3venes a cuidar lo que nos pertenece.<\/p>\n<p><strong>Silverio &#8211; Guyana<\/strong>: Me anima que exista una posibilidad para la juventud de la pan amazon\u00eda,\u00a0 porque tenemos que ser protagonista de nuevos comienzos. A veces la juventud dejan a lado, no tiene una posici\u00f3n para decidir lo que nos afecta, pero este momento es correcto, un momento para enfrentar y confrontar lo que nos afecta:\u00a0 Ser protagonista de nuestro propio destino. Las juventudes,\u00a0 tenemos que tener conciencia sobre la naturaleza y participar en esos momentos hist\u00f3ricos. Este proceso me da una visi\u00f3n de que un mundo mejor es posible en conjunto con los j\u00f3venes.<\/p>\n<p><strong>Artele &#8211; Brasil:<\/strong> Este es el\u00a0\u00a0momento para contribuir en la historia de la Amazon\u00eda.<\/p>\n<p><strong>Omar Alvarado &#8211; Colombia<\/strong>:\u00a0 Ha sido muy interesante para compartir y conocer como podemos trabajar y fundamentarlos en la religi\u00f3n y fortalecernos en nuestras creencias y as\u00ed encontrar un camino en la defensa de recursos naturales.<\/p>\n<p><strong>Soni Luis Torres &#8211; Tikuna- Colombia:<\/strong> La importancia de este encuentro es importante para mi como joven ind\u00edgena, se esta perdiendo nuestra cultura y nuestra identidad, es muy importante para la conservaci\u00f3n y concientizar a las personas sobre la importancia de nuestras culturas, nuestra selva, nuestra forma de pensar. Ha sido muy lindo\u00a0 encontrarnos con otros pa\u00edses y saber implementar de una buena forma el cuidado de\u00a0 la Amazon\u00eda en su conjunto.<\/p>\n<p><strong>Adriana &#8211; Venezuela:<\/strong> Queremos llevarnos una soluci\u00f3n real y preventiva para el problema de la Pan Amazonia, tanto para la floresta, como para los pueblos ind\u00edgenas y la problem\u00e1tica tan fuerte sobre la migraci\u00f3n.<\/p>\n<p><strong>Doralice Macuxi &#8211; Roraima:<\/strong> Es\u00a0importante la uni\u00f3n de todos los pueblos para trabajar en la protecci\u00f3n de nuestra Amazon\u00eda, la importancia que podamos trabajar en la preservaci\u00f3n de nuestras culturas, tener ese lazo con la Repam Juventudes, las bases, los niveles locales, nuestro desarrollo como j\u00f3venes, con otros pueblos que necesitan las mismas cosas que nosotros.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El encuentro que congreg\u00f3 a m\u00e1s de 30 j\u00f3venes de la Pan Amazon\u00eda, dej\u00f3 muchas proyecciones y sentires, que juntos en una sola voz, hablan de:\u00a0 defender la vida, que es defender la selva amaz\u00f3nica y sus culturas.\u00a0 Diego &#8211; Santarem Par\u00e1: Soy ind\u00edgena en este encuentro de la Repam Juventudes, estamos conociendo nuevas personas, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3690,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[281,4],"tags":[56,57,33,35,16],"class_list":["post-3689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-extractivismo","category-noticias","tag-80-por-ciento","tag-accion-de-proteccion","tag-amazonia","tag-coica","tag-pueblos-indigenas"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Voces por la defensa de las culturas y la selva: Caminos Amaz\u00f3nicos de Formaci\u00f3n - REPAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repam.net\/es\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voces por la defensa de las culturas y la selva: Caminos Amaz\u00f3nicos de Formaci\u00f3n - REPAM\" \/>\n<meta property=\"og:description\" content=\"El encuentro que congreg\u00f3 a m\u00e1s de 30 j\u00f3venes de la Pan Amazon\u00eda, dej\u00f3 muchas proyecciones y sentires, que juntos en una sola voz, hablan de:\u00a0 defender la vida, que es defender la selva amaz\u00f3nica y sus culturas.\u00a0 Diego &#8211; Santarem Par\u00e1: Soy ind\u00edgena en este encuentro de la Repam Juventudes, estamos conociendo nuevas personas, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repam.net\/es\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\/\" \/>\n<meta property=\"og:site_name\" content=\"REPAM\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-27T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/29178084_418696528565381_5275750729041051648_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"719\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"repam@adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repam@adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\\\/\"},\"author\":{\"name\":\"repam@adm\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\"},\"headline\":\"Voces por la defensa de las culturas y la selva: Caminos Amaz\u00f3nicos de Formaci\u00f3n\",\"datePublished\":\"2018-04-27T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\\\/\"},\"wordCount\":506,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/29178084_418696528565381_5275750729041051648_n.jpg\",\"keywords\":[\"80 por ciento\",\"acci\u00f3n de protecci\u00f3n\",\"Amazon\u00eda\",\"Coica\",\"pueblos ind\u00edgenas\"],\"articleSection\":[\"Extractivismo\",\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\\\/\",\"name\":\"Voces por la defensa de las culturas y la selva: Caminos Amaz\u00f3nicos de Formaci\u00f3n - REPAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/29178084_418696528565381_5275750729041051648_n.jpg\",\"datePublished\":\"2018-04-27T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repam.net\\\/es\\\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/29178084_418696528565381_5275750729041051648_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/29178084_418696528565381_5275750729041051648_n.jpg\",\"width\":960,\"height\":719},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Voces por la defensa de las culturas y la selva: Caminos Amaz\u00f3nicos de Formaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"name\":\"REPAM\",\"description\":\"Red Eclesial Panamaz\u00f3nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repam.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\",\"name\":\"REPAM\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"REPAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\",\"name\":\"repam@adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"caption\":\"repam@adm\"},\"sameAs\":[\"http:\\\/\\\/repam.net\"],\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/author\\\/repamadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Voces por la defensa de las culturas y la selva: Caminos Amaz\u00f3nicos de Formaci\u00f3n - REPAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repam.net\/es\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\/","og_locale":"es_ES","og_type":"article","og_title":"Voces por la defensa de las culturas y la selva: Caminos Amaz\u00f3nicos de Formaci\u00f3n - REPAM","og_description":"El encuentro que congreg\u00f3 a m\u00e1s de 30 j\u00f3venes de la Pan Amazon\u00eda, dej\u00f3 muchas proyecciones y sentires, que juntos en una sola voz, hablan de:\u00a0 defender la vida, que es defender la selva amaz\u00f3nica y sus culturas.\u00a0 Diego &#8211; Santarem Par\u00e1: Soy ind\u00edgena en este encuentro de la Repam Juventudes, estamos conociendo nuevas personas, [&hellip;]","og_url":"https:\/\/www.repam.net\/es\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\/","og_site_name":"REPAM","article_published_time":"2018-04-27T05:00:00+00:00","og_image":[{"width":960,"height":719,"url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/29178084_418696528565381_5275750729041051648_n.jpg","type":"image\/jpeg"}],"author":"repam@adm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"repam@adm","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repam.net\/es\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\/#article","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\/"},"author":{"name":"repam@adm","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033"},"headline":"Voces por la defensa de las culturas y la selva: Caminos Amaz\u00f3nicos de Formaci\u00f3n","datePublished":"2018-04-27T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repam.net\/es\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\/"},"wordCount":506,"publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"image":{"@id":"https:\/\/www.repam.net\/es\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/29178084_418696528565381_5275750729041051648_n.jpg","keywords":["80 por ciento","acci\u00f3n de protecci\u00f3n","Amazon\u00eda","Coica","pueblos ind\u00edgenas"],"articleSection":["Extractivismo","Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.repam.net\/es\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\/","url":"https:\/\/www.repam.net\/es\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\/","name":"Voces por la defensa de las culturas y la selva: Caminos Amaz\u00f3nicos de Formaci\u00f3n - REPAM","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repam.net\/es\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\/#primaryimage"},"image":{"@id":"https:\/\/www.repam.net\/es\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/29178084_418696528565381_5275750729041051648_n.jpg","datePublished":"2018-04-27T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.repam.net\/es\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repam.net\/es\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\/#primaryimage","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/29178084_418696528565381_5275750729041051648_n.jpg","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/29178084_418696528565381_5275750729041051648_n.jpg","width":960,"height":719},{"@type":"BreadcrumbList","@id":"https:\/\/www.repam.net\/es\/voces-por-la-defensa-de-las-culturas-y-la-selva-caminos-amazonicos-de-formacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repam.net\/es\/"},{"@type":"ListItem","position":2,"name":"Voces por la defensa de las culturas y la selva: Caminos Amaz\u00f3nicos de Formaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.repam.net\/es\/#website","url":"https:\/\/www.repam.net\/es\/","name":"REPAM","description":"Red Eclesial Panamaz\u00f3nica","publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repam.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.repam.net\/es\/#organization","name":"REPAM","url":"https:\/\/www.repam.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","width":512,"height":512,"caption":"REPAM"},"image":{"@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033","name":"repam@adm","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","caption":"repam@adm"},"sameAs":["http:\/\/repam.net"],"url":"https:\/\/www.repam.net\/es\/author\/repamadm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/3689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/comments?post=3689"}],"version-history":[{"count":0,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/3689\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media\/3690"}],"wp:attachment":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media?parent=3689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/categories?post=3689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/tags?post=3689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}