{"id":3719,"date":"2018-04-25T00:00:00","date_gmt":"2018-04-25T05:00:00","guid":{"rendered":"http:\/\/repam.net\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\/"},"modified":"2021-09-29T19:01:22","modified_gmt":"2021-09-30T00:01:22","slug":"mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica","status":"publish","type":"post","link":"https:\/\/www.repam.net\/es\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\/","title":{"rendered":"Mensaje del Encuentro de Congregaciones Religiosas con proyectos en Perspectiva Panamaz\u00f3nica"},"content":{"rendered":"<p><p>&nbsp;<\/p>\n<p>Con la prontitud de Mar&iacute;a, acogimos la invitaci&oacute;n de la CLAR y la REPAM, para participar del Encuentro de Congregaciones Religiosas con Proyectos en Perspectiva Panamaz&oacute;nica, en el que reflexionamos sobre &ldquo;La misionariedad Panamaz&oacute;nica en la &oacute;ptica de la ecolog&iacute;a integral&rdquo;. Somos noventa participantes de treinta congregaciones, religiosas, religiosos, laicos, laicas y padres diocesanos de los pa&iacute;ses de la Panamazonia, en Tabatinga (Brasil), regi&oacute;n transfronteriza, de 20 a 24 de abril del 2018.<\/p>\n<p>Desde una mirada amorosa, cuidadosa y esperanzadora, hemos compartido la diversidad social, cultural, espiritual y ambiental, nacida de la sabidur&iacute;a de los pueblos originarios con los que compartimos nuestra vida y misi&oacute;n, que nace de una actitud de encuentro que va transformando nuestra vida y la de nuestras instituciones para dejar aparecer los nuevos caminos para la Iglesia y la ecolog&iacute;a integral a los que nuestro S&iacute;nodo Panamaz&oacute;nico nos invita y que surgir&aacute;n en la medida en que se d&eacute; un proceso de escucha.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  \" src=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/IMG-20180424-WA0053.jpg\" alt=\"\" width=\"616\" height=\"462\"><\/p>\n<p>En un escenario constantemente amenazado por un capitalismo que mata, la Vida Religiosa es llamada a ser se&ntilde;al de esperanza para una Iglesia con rostro amaz&oacute;nico e ind&iacute;gena, inspirada en la Laudato S&iacute; y el Evangelio de la Creaci&oacute;n, saliendo de f&oacute;rmulas preestablecidas y abri&eacute;ndose a los signos de vida que encontramos en una regi&oacute;n donde Dios est&aacute; presente en todas las realidades.<\/p>\n<p>Somos llamados a entrar en una din&aacute;mica constante de conversi&oacute;n profunda, que nos lleve a corazonarnos con la Amazonia y sus pueblos, a atravesar las fronteras geogr&aacute;ficas, simb&oacute;licas, culturales, personales y congregacionales. Intensificar nuestra dimensi&oacute;n itinerante, que nos ponga en camino para ser una Iglesia en salida y misionera, que nos lleve a hacernos presentes en los lugares donde la vida est&aacute; m&aacute;s amenazada, en las periferias, con una actitud de escucha, convivencia demorada, cuidado y compartir, acogiendo los diferentes modos de vida y compartiendo experiencias que ayudan en el mutuo crecimiento.<\/p>\n<p>Nunca olvidemos que cuanto m&aacute;s dif&iacute;cil es el tiempo y las circunstancias en que vivimos, m&aacute;s fuerte tiene que ser nuestra esperanza. Por eso, nos solidarizamos con un mensaje a las hermanas de Notre Dame de Namur y al Padre Jos&eacute; Amaro Lopes Sousa, preso como consecuencia de su lucha en la defensa de la Amazonia y sus pueblos en la regi&oacute;n brasile&ntilde;a del Xing&uacute;, v&iacute;ctima de un complot de los poderes pol&iacute;ticos y econ&oacute;micos, situaci&oacute;n sufrida por muchos l&iacute;deres en la regi&oacute;n amaz&oacute;nica.<\/p>\n<p>Conocer la vida de algunas comunidades de Brasil, Colombia y Per&uacute;, donde hicimos una misi&oacute;n durante el encuentro, nos ayud&oacute; a descubrir la resistencia en medio de las dificultades y como el pueblo alimenta su fe y esperanza, fortalecidas por una destacada presencia de ni&ntilde;os y j&oacute;venes. Conocer el modo de celebrar de los pueblos de la regi&oacute;n, basada en el encuentro festivo y el compartir, es un ejemplo que puede ayudar a la vida religiosa en la Panamazonia a entrar en la din&aacute;mica de los moradores de la regi&oacute;n, como algunas congregaciones, en su compartir sobre los proyectos con perspectiva Panamaz&oacute;nica, muestran que van consiguiendo, esperando un mayor apoyo de los Superiores Mayores de las Congregaciones.<\/p>\n<p>Como Vida Religiosa en la Panamazonia nos comprometemos a: releer nuestros carismas desde la Laudato Si, buscando nuevas relaciones y encuentros desde una espiritualidad inculturada; reorganizarnos para recuperar el sentido vocacional y misionero, fortaleciendo nuestras ra&iacute;ces; trabajar con instituciones y organismos que defiendan la vida y los derechos de los pueblos y de la tierra; itinerar hacia las periferias, transcendiendo las diferentes fronteras; configurar una identidad con rostro amaz&oacute;nico desde una &eacute;tica del cuidado que genera hospitalidad, unidad en la diversidad y comuni&oacute;n; mirar y escuchar con profec&iacute;a, en un compromiso con la justicia, la paz y la integridad de la Creaci&oacute;n; rescatar lo sagrado y las cosmovisiones locales para celebrar la vida en conexi&oacute;n con las culturas amaz&oacute;nicas y el Creador; promover la ecolog&iacute;a integral con una educaci&oacute;n y espiritualidad ecol&oacute;gica que provoque incidencia pol&iacute;tica; hacer realidad una nueva eclesialidad Panamaz&oacute;nica.<\/p>\n<p>Que la Vida Religiosa de la Panamazonia haga suyas las palabras del Papa Francisco, con quien nos sentimos profundamente unidos, a los pueblos ind&iacute;genas en Puerto Maldonado: &ldquo;ayudad a vuestros misioneros y misioneras a hacerse uno s&oacute;lo con vosotros y as&iacute;, dialogando con todos, podr&eacute;is plasmar una Iglesia con rostro amaz&oacute;nico y una Iglesia con rostro ind&iacute;gena&rdquo;.<\/p>\n<p style=\"text-align: right\">Tabatinga &ndash; Brasil, 24 de abril de 2018<\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><em>&nbsp;(Fotos: cortes&iacute;a de Luis Miguel Mondino)<\/em><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Con la prontitud de Mar&iacute;a, acogimos la invitaci&oacute;n de la CLAR y la REPAM, para participar del Encuentro de Congregaciones Religiosas con Proyectos en Perspectiva Panamaz&oacute;nica, en el que reflexionamos sobre &ldquo;La misionariedad Panamaz&oacute;nica en la &oacute;ptica de la ecolog&iacute;a integral&rdquo;. Somos noventa participantes de treinta congregaciones, religiosas, religiosos, laicos, laicas y padres diocesanos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3720,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[4,55],"tags":[56,57,33,35,16],"class_list":["post-3719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-pueblos-amazonicos","tag-80-por-ciento","tag-accion-de-proteccion","tag-amazonia","tag-coica","tag-pueblos-indigenas"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mensaje del Encuentro de Congregaciones Religiosas con proyectos en Perspectiva Panamaz\u00f3nica - REPAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repam.net\/es\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mensaje del Encuentro de Congregaciones Religiosas con proyectos en Perspectiva Panamaz\u00f3nica - REPAM\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Con la prontitud de Mar&iacute;a, acogimos la invitaci&oacute;n de la CLAR y la REPAM, para participar del Encuentro de Congregaciones Religiosas con Proyectos en Perspectiva Panamaz&oacute;nica, en el que reflexionamos sobre &ldquo;La misionariedad Panamaz&oacute;nica en la &oacute;ptica de la ecolog&iacute;a integral&rdquo;. Somos noventa participantes de treinta congregaciones, religiosas, religiosos, laicos, laicas y padres diocesanos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repam.net\/es\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\/\" \/>\n<meta property=\"og:site_name\" content=\"REPAM\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-25T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-30T00:01:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/IMG-20180424-WA0047.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"repam@adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repam@adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\\\/\"},\"author\":{\"name\":\"repam@adm\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\"},\"headline\":\"Mensaje del Encuentro de Congregaciones Religiosas con proyectos en Perspectiva Panamaz\u00f3nica\",\"datePublished\":\"2018-04-25T05:00:00+00:00\",\"dateModified\":\"2021-09-30T00:01:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\\\/\"},\"wordCount\":880,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/IMG-20180424-WA0047.jpg\",\"keywords\":[\"80 por ciento\",\"acci\u00f3n de protecci\u00f3n\",\"Amazon\u00eda\",\"Coica\",\"pueblos ind\u00edgenas\"],\"articleSection\":[\"Noticias\",\"Pueblos Amaz\u00f3nicos\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\\\/\",\"name\":\"Mensaje del Encuentro de Congregaciones Religiosas con proyectos en Perspectiva Panamaz\u00f3nica - REPAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/IMG-20180424-WA0047.jpg\",\"datePublished\":\"2018-04-25T05:00:00+00:00\",\"dateModified\":\"2021-09-30T00:01:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repam.net\\\/es\\\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/IMG-20180424-WA0047.jpg\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/IMG-20180424-WA0047.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mensaje del Encuentro de Congregaciones Religiosas con proyectos en Perspectiva Panamaz\u00f3nica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"name\":\"REPAM\",\"description\":\"Red Eclesial Panamaz\u00f3nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repam.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\",\"name\":\"REPAM\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"REPAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\",\"name\":\"repam@adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"caption\":\"repam@adm\"},\"sameAs\":[\"http:\\\/\\\/repam.net\"],\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/author\\\/repamadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mensaje del Encuentro de Congregaciones Religiosas con proyectos en Perspectiva Panamaz\u00f3nica - REPAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repam.net\/es\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\/","og_locale":"es_ES","og_type":"article","og_title":"Mensaje del Encuentro de Congregaciones Religiosas con proyectos en Perspectiva Panamaz\u00f3nica - REPAM","og_description":"&nbsp; Con la prontitud de Mar&iacute;a, acogimos la invitaci&oacute;n de la CLAR y la REPAM, para participar del Encuentro de Congregaciones Religiosas con Proyectos en Perspectiva Panamaz&oacute;nica, en el que reflexionamos sobre &ldquo;La misionariedad Panamaz&oacute;nica en la &oacute;ptica de la ecolog&iacute;a integral&rdquo;. Somos noventa participantes de treinta congregaciones, religiosas, religiosos, laicos, laicas y padres diocesanos [&hellip;]","og_url":"https:\/\/www.repam.net\/es\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\/","og_site_name":"REPAM","article_published_time":"2018-04-25T05:00:00+00:00","article_modified_time":"2021-09-30T00:01:22+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/IMG-20180424-WA0047.jpg","type":"image\/jpeg"}],"author":"repam@adm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"repam@adm","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repam.net\/es\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\/#article","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\/"},"author":{"name":"repam@adm","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033"},"headline":"Mensaje del Encuentro de Congregaciones Religiosas con proyectos en Perspectiva Panamaz\u00f3nica","datePublished":"2018-04-25T05:00:00+00:00","dateModified":"2021-09-30T00:01:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repam.net\/es\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\/"},"wordCount":880,"publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"image":{"@id":"https:\/\/www.repam.net\/es\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/IMG-20180424-WA0047.jpg","keywords":["80 por ciento","acci\u00f3n de protecci\u00f3n","Amazon\u00eda","Coica","pueblos ind\u00edgenas"],"articleSection":["Noticias","Pueblos Amaz\u00f3nicos"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.repam.net\/es\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\/","url":"https:\/\/www.repam.net\/es\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\/","name":"Mensaje del Encuentro de Congregaciones Religiosas con proyectos en Perspectiva Panamaz\u00f3nica - REPAM","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repam.net\/es\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\/#primaryimage"},"image":{"@id":"https:\/\/www.repam.net\/es\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/IMG-20180424-WA0047.jpg","datePublished":"2018-04-25T05:00:00+00:00","dateModified":"2021-09-30T00:01:22+00:00","breadcrumb":{"@id":"https:\/\/www.repam.net\/es\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repam.net\/es\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\/#primaryimage","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/IMG-20180424-WA0047.jpg","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/IMG-20180424-WA0047.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.repam.net\/es\/mensaje-del-encuentro-de-congregaciones-religiosas-con-proyectos-en-perspectiva-panamazonica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repam.net\/es\/"},{"@type":"ListItem","position":2,"name":"Mensaje del Encuentro de Congregaciones Religiosas con proyectos en Perspectiva Panamaz\u00f3nica"}]},{"@type":"WebSite","@id":"https:\/\/www.repam.net\/es\/#website","url":"https:\/\/www.repam.net\/es\/","name":"REPAM","description":"Red Eclesial Panamaz\u00f3nica","publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repam.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.repam.net\/es\/#organization","name":"REPAM","url":"https:\/\/www.repam.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","width":512,"height":512,"caption":"REPAM"},"image":{"@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033","name":"repam@adm","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","caption":"repam@adm"},"sameAs":["http:\/\/repam.net"],"url":"https:\/\/www.repam.net\/es\/author\/repamadm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/3719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/comments?post=3719"}],"version-history":[{"count":1,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/3719\/revisions"}],"predecessor-version":[{"id":3730,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/3719\/revisions\/3730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media\/3720"}],"wp:attachment":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media?parent=3719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/categories?post=3719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/tags?post=3719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}