{"id":3743,"date":"2018-04-09T00:00:00","date_gmt":"2018-04-09T05:00:00","guid":{"rendered":"http:\/\/repam.net\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\/"},"modified":"2018-04-09T00:00:00","modified_gmt":"2018-04-09T05:00:00","slug":"declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global","status":"publish","type":"post","link":"https:\/\/www.repam.net\/es\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\/","title":{"rendered":"DECLARACI\u00d3N DE QUITO PUEBLOS IND\u00cdGENAS DE LA CUENCA AMAZ\u00d3NICA EN DEFENSA DE SUS DERECHOS Y SUS TERRITORIOS PARA LA VIDA PLENA Y SU APORTE PARA ENFRENTAR EL CAMBIO CLIM\u00c1TICO GLOBAL"},"content":{"rendered":"<p><em>La Coordinadora de las Organizaciones Ind\u00edgenas de la Cuenca Amaz\u00f3nica (COICA)<\/em>\u00a0y sus organizaciones miembros de los nueve pa\u00edses de la cuenca amaz\u00f3nica: COIAB (Coordinadora de las Organizaciones Ind\u00edgenas de la Amazon\u00eda Brasile\u00f1a) de Brasil, CIDOB (Confederaci\u00f3n de Pueblos Ind\u00edgenas de Bolivia) Bolivia, AIDESEP (Asociaci\u00f3n Inter\u00e9tnica de desarrollo de la Selva Peruana) Per\u00fa, CONFENIAE (Confederaci\u00f3n de las Nacionalidades de la Amazon\u00eda Ecuatoriana) de Ecuador, OPIAC (Organizaci\u00f3n Nacional de los pueblos ind\u00edgenas de la Amazon\u00eda Colombiana) Colombia, ORPIA (Organizaci\u00f3n Regional de Pueblos Ind\u00edgenas del Amazonas) de Venezuela, APA (Asociaci\u00f3n de Pueblos Amerindios de Guayana) de Guyana, OIS (Organizaciones Ind\u00edgenas de Surinam) Surinam y FOAG (Federaci\u00f3n de Organizaciones Aut\u00f3ctonas de Guayana Francesa) Guyana Francesa, reunidos en la ciudad de Quito, del 16 al 19 de marzo de 2018, en el marco del Consejo de Coordinaci\u00f3n y Consejo Directivo de la COICA, acuerdan emitir la presente Declaraci\u00f3n de Quito:<\/p>\n<p>Considerando:<\/p>\n<p>Que, la cuenca amaz\u00f3nica ha sido el hogar de pueblos ind\u00edgenas por m\u00e1s de 10 mil a\u00f1os, y actualmente habitan en esta regi\u00f3n 390 pueblos ind\u00edgenas, m\u00e1s 66 pueblos en aislamiento voluntario, y m\u00e1s de 2,5 millones de ind\u00edgenas con una diversidad cultural \u00fanica, basada en una relaci\u00f3n hol\u00edstica con su territorio, que ha llevado a mantener conservados el 28,3% de territorios ind\u00edgenas dentro de la cuenca amaz\u00f3nica, abarcando 175 millones de hect\u00e1reas tituladas y m\u00e1s de 100 millones de hect\u00e1reas que faltan titular.<\/p>\n<p>Que, los bosques tropicales de la Amazon\u00eda son un ecosistema estrat\u00e9gico para enfrentar el cambio clim\u00e1tico, por sus m\u00faltiples funciones ecosist\u00e9micas, como la de mega diversidad biol\u00f3gica, regulaci\u00f3n h\u00eddrica de los \u201cr\u00edos voladores\u201d y los millones de toneladas de biomasa de carbono forestal depositado en los bosques tropicales de los territorios ind\u00edgenas.<\/p>\n<p>Que, esta regi\u00f3n estrat\u00e9gica global de diversidad biol\u00f3gica y cultural, a la vez tiene una presi\u00f3n enorme por las actividades extractivas de empresas nacionales y extranjeras, mineras y de hidrocarburos, infraestructura y monocultivos, as\u00ed como por la presencia de otros agentes externos que generan impactos ambientales y sociales irreversibles para los pueblos ind\u00edgenas y sus territorios.<\/p>\n<p>Que, es importante la consulta previa y la aplicaci\u00f3n aplique seg\u00fan en el Convenio 169 de la OIT, en el art\u00edculo 2 establece que \u201c\u2026los gobiernos deber\u00e1n asumir la responsabilidad de desarrollar, con la participaci\u00f3n de los pueblos interesados, una acci\u00f3n coordinada y sistem\u00e1tica con miras a proteger los derechos de esos pueblos y a garantizar el respeto de su integridad\u2026\u201d<\/p>\n<p>Que, existe una presi\u00f3n de inversiones chinas que no cumple con est\u00e1ndares m\u00ednimos internacionales y que causan graves impactos ambientales y sociales con una consecuenta flexibilizaci\u00f3n de las normas nacionales.<\/p>\n<p>Los representantes de las organizaciones ind\u00edgenas nacionales amaz\u00f3nicas miembros de la COICA, de los 9 pa\u00edses de la cuenca amaz\u00f3nica, ponen de manifiesto denuncias y preocupaciones para consideraci\u00f3n p\u00fablica nacional e internacional, en especial de los Estados nacionales amaz\u00f3nicos:<\/p>\n<p><em><strong>En Colombia<\/strong><\/em>, la OPIAC denuncia que, (1) con el Acuerdo de Paz, sus territorios contin\u00faan amenazados con la presencia de los mismos actores armados al margen de la Ley, y del propio Estado, que se derivan en persecuci\u00f3n y asesinatos a los l\u00edderes ind\u00edgenas en sus propios territorios, y se exigen garant\u00edas constitucionales plenas para que exista participaci\u00f3n de los pueblos ind\u00edgenas en el marco de la implementaci\u00f3n del acuerdo de paz con las FARC, respetando el derecho fundamental al consentimiento previo, libre e informado; (2) la presi\u00f3n en los territorios ind\u00edgenas por la presencia de empresas mineras legales e ilegales, ha generado un problema de salud p\u00fablica en la regi\u00f3n, contaminando con mercurio las fuentes h\u00eddricas, as\u00ed mismo la exploraci\u00f3n y explotaci\u00f3n de hidrocarburos en los territorios ind\u00edgenas, vulnerando el derecho fundamental al consentimiento libre, previo e informado, por lo que se exige una soluci\u00f3n; (3) la constante vulneraci\u00f3n del derecho fundamental a la consulta previa y a la participaci\u00f3n de los pueblos ind\u00edgenas en la aprobaci\u00f3n de leyes y pol\u00edticas p\u00fablicas en temas que les afectan, por lo que se exige proteger de manera m\u00e1s efectiva el derecho fundamental a la consulta previa.<\/p>\n<p><em><strong>En el Ecuador<\/strong><\/em>, si bien es cierto se reconoce el proceso de di\u00e1logo establecido entre el gobierno nacional y las organizaciones ind\u00edgenas representadas por la CONAIE y la CONFENIAE, en mesas nacionales tem\u00e1ticas de trabajo; sin embargo (1) la nueva ronda petrolera y concesiones mineras son una amenaza permanente a los territorios ind\u00edgenas de la Amazon\u00eda ecuatoriana, y a su forma de vida; (2) la persecuci\u00f3n a l\u00edderes ind\u00edgenas, reflejada en los procesos judiciales iniciados por al anterior gobierno, a\u00fan no se han cancelado y las demandas de amnist\u00eda e indulto para los presos pol\u00edticos no son atendidos; (3) se pide a las autoridades de gobierno, el respeto a los derechos ancestrales de las comunidades, en ese sentido se respalda a la nacionalidad Siekopai por su derecho ancestral territorial, cultural y espiritual para la construcci\u00f3n de una casa ceremonial en el punto denominado laguna de KOSA DOP\u00cb, dentro de la Reserva de Cuyabeno en la zona de Lagarto Cocha, que fue parte del territorio ancestral de esta nacionalidad.<\/p>\n<p><em><strong>En Per\u00fa<\/strong><\/em>, los territorios ind\u00edgenas sufren una permanente amenaza por (1) las concesiones forestales, mineras, de monocultivos, infraestructura, bloques petroleros, tr\u00e1fico de tierras y trata de personas, y cultivos il\u00edcitos de coca, (2) las demandas de titulaci\u00f3n de sus territorios no son atendidos, y al contrario el Estado peruano, de manera inconsulta y arbitraria contin\u00faa declarando \u00e1reas protegidas en superposici\u00f3n de los territorios ind\u00edgenas como el caso Yaguas en el Departamento de Loreto, que atenta contra el uso ancestral de los recursos del bosque por parte de los propios pueblos ind\u00edgenas.<\/p>\n<p><em><strong>En Bolivia,<\/strong><\/em>\u00a0la CIDOB (Confederaci\u00f3n de Pueblos Ind\u00edgenas de Bolivia), menciona que el Ministerio P\u00fablico rechaz\u00f3 en marzo 2018 la querella penal contra el presidente de la CIDOB, hermano Adolfo Ch\u00e1vez Beyuma y l\u00edderes ind\u00edgenas, por presuntas irregularidades, sin embargo esta acci\u00f3n demuestra que la demanda fue un instrumento de venganza y persecuci\u00f3n pol\u00edtica del gobierno nacional contra la CIDOB org\u00e1nica -que es la \u00fanica reconocida por la COICA-, por su resistencia y su lucha por los derechos de los pueblos ind\u00edgenas. La CIDOB denuncia que contin\u00faa la persecuci\u00f3n y divisi\u00f3n del movimiento ind\u00edgena, por parte del gobierno nacional, con la criminalizaci\u00f3n de la protesta social por la defensa de los territorios. Adem\u00e1s, los territorios ind\u00edgenas sufren una permanente amenaza por las concesiones forestales, mineras, de monocultivos, infraestructura, bloques petroleros, tr\u00e1fico de tierras, y cultivos il\u00edcitos de coca.<\/p>\n<p><em><strong>En Venezuela<\/strong><\/em>, se reconoce en la legislaci\u00f3n nacional los derechos de los pueblos ind\u00edgenas y se ha ratificado acuerdos y normas internacionales como el Acuerdo 169 de la OIT, que garantiza la consulta libre previa e informada y la participaci\u00f3n de los pueblos ind\u00edgenas en asuntos que les afecte. Por lo que se hace un llamado al gobierno nacional, para que el cumplimiento de dichos instrumentos legales, se abran mesas de di\u00e1logo con las organizaciones nacionales de pueblos ind\u00edgenas, para analizar los impactos de proyectos de inter\u00e9s estrat\u00e9gico como en el llamado Arco Minero, cuya aplicaci\u00f3n podr\u00eda afectar de forma directa a los pueblos ind\u00edgenas, a su forma de vida y a sus territorios; y buscar alternativas viables; as\u00ed mismo es importante avanzar con la demarcaci\u00f3n y titulaci\u00f3n de tierras ind\u00edgenas que con su visi\u00f3n hol\u00edstica, aportar\u00e1n en la conservaci\u00f3n y manejo adecuado de los recursos naturales. Es importante que el gobierno comprenda la importancia de los territorios para los pueblos ind\u00edgenas, que lleva a la lucha por la misma y se de cumplimiento al Plan de la Patria que en su contenido hace referencia a la protecci\u00f3n del bosque para la salvaci\u00f3n del planeta y la humanidad.<\/p>\n<p><em><strong>En Brasil,<\/strong><\/em>\u00a0la COIAB denuncia que (1) no se ha terminado con la legalizaci\u00f3n de los territorios ind\u00edgenas, y se denuncia tambi\u00e9n la pol\u00edtica gubernamental Marco Temporal que coarta las iniciativas de legalizaci\u00f3n de tierras ind\u00edgenas, (2) se atraviesa por una situaci\u00f3n preocupante en los territorios, por las constantes amenazas por los garimpeiros, expansi\u00f3n de la frontera ganadera y agropecuaria, y explotaci\u00f3n maderera, que atenta contra los pueblos y su forma de vida. (3) Se denuncia las acciones legislativas que atentan contra los derechos de los pueblos ind\u00edgenas, como son las leyes PEC215, PLP 227, PEC 419y PL 1610\/96. (4) Adem\u00e1s se denuncia que se han incrementado los proyectos de infraestructura sin consulta, as\u00ed como la construcci\u00f3n de carreteras, hidroel\u00e9ctricas, y monocultivos. (5) Se ha cortado el presupuesto, se ha desestructurado la FUNAI (Fundaci\u00f3n Nacional del Indio). (6) La amenaza constante y persecuci\u00f3n al movimiento ind\u00edgenas, l\u00edderes y lideresas. (7) Tentativa de gobierna nacional y de los estados federales, por invalidar la Convenci\u00f3n 169 de la OIT como en el caso de Roraima. (8) El gobierno debe atender tambi\u00e9n, en coordinaci\u00f3n con Venezuela, la situaci\u00f3n social del pueblo Warao por la crisis en Venezuela.<\/p>\n<p><em><strong>En Guyana Francesa,<\/strong><\/em>\u00a0la lucha por la titulaci\u00f3n de los territorios ind\u00edgenas ha sido un proceso frente a las autoridades del gobierno franc\u00e9s, que de forma progresiva ha titularizado tierra ind\u00edgena tradicional, dicho proceso debe continuar para asegurar los derechos territoriales y su gesti\u00f3n hol\u00edstica impulsada por la COICA. Por otro lado, la miner\u00eda es una amenaza a los territorios, con el mega proyecto planificado, los impactos por uso de explosivos y de cianuro traer\u00edan graves afectaciones a la vida de los pueblos ind\u00edgenas y a los recursos naturales, por lo que se insta al gobierno a analizar conjuntamente con FOAG los impactos, y aplicar la consulta y la participaci\u00f3n, adem\u00e1s se exige una moratoria sobre la miner\u00eda. Se pide el cumplimiento del Acuerdo de Cayanne, espec\u00edficamente el punto con la posici\u00f3n de la ratificaci\u00f3n de la Convenio 169 de OIT.<\/p>\n<p><em><strong>En Surinam<\/strong><\/em>, se ha seguido un proceso para el reconocimiento nacional de los pueblos ind\u00edgenas, sin embargo, queda un camino por seguir para que se aplique la consulta y participaci\u00f3n de los pueblos ind\u00edgenas, que lleven al pleno reconocimiento de sus derechos, en casos como la miner\u00eda que es una actividad de presi\u00f3n sobre los territorios.<br \/>OIS denuncia que, en el noreste de Surinam, el gobierno est\u00e1 haciendo una exploraci\u00f3n minera y se est\u00e1n contaminando los r\u00edos con mercurio.<br \/>En cuanto al derecho de la tierra, se ha conformado una comisi\u00f3n, en la que los pueblos ind\u00edgenas deben participar. Adem\u00e1s, se han detenido los procesos de concesi\u00f3n de tierras ind\u00edgenas por la Comisi\u00f3n de asuntos de tierras.<\/p>\n<p><em><strong>En Guyana<\/strong><\/em>, la APA declara que las concesiones forestales y mineras que el gobierno ha concedido en o cerca de tierras ind\u00edgenas constituyen una amenaza para los territorios ind\u00edgenas y el medio ambiente. Esto ha llevado a la violaci\u00f3n de los derechos territoriales y de otro tipo debido a la inadecuada, o en algunos casos, la falta de participaci\u00f3n en las decisiones que afectan a los pueblos y sus territorios. Por lo tanto, se insta al gobierno nacional a entablar un di\u00e1logo constructivo para comprender plenamente la importancia de las tierras y los territorios para los pueblos ind\u00edgenas de Guyana.<\/p>\n<p>En Guyana, Surinam y Francia, se presenta el agravante de que en estos tres pa\u00edses no se ha ratificado a\u00fan el Convenio 169 de la OIT sobre consulta previa libre e informada a los Pueblos Ind\u00edgenas y Tribales en Pa\u00edses Independientes de la OIT, es importante que estos tres pa\u00edses lo ratifiquen.<\/p>\n<p>Por lo tanto, la COICA y sus organizaciones ind\u00edgenas amaz\u00f3nicas miembros, en uso de sus competencias y atribuciones, emiten las siguientes<\/p>\n<p><strong>Resoluciones:<\/strong><\/p>\n<p>Demandar a los respectivos gobiernos nacionales de la cuenca amaz\u00f3nica, la coherencia en sus pol\u00edticas de desarrollo, respetando los derechos de los pueblos ind\u00edgenas y sus territorios, tomando en cuenta que la Amazon\u00eda y su diversidad biol\u00f3gica y cultural son estrat\u00e9gicas a nivel global para enfrentar el cambio clim\u00e1tico.<\/p>\n<p>Demandar de manera firme y consistente, a los gobiernos nacionales que se respete el cumplimiento del derecho al consentimiento libre, previo e informado, y el derecho a la participaci\u00f3n en todas las decisiones, pol\u00edticas y leyes que les afecte de manera directa o indirecta.<\/p>\n<p>Denunciar a la opini\u00f3n p\u00fablica la persecuci\u00f3n y criminalizaci\u00f3n de las y los defensores de los derechos ind\u00edgenas; y demandar a los estados el cumplimiento de la Declaraci\u00f3n Universal de los Derechos Humanos con la erradicaci\u00f3n total de la criminalizaci\u00f3n de la protesta social por parte de l\u00edderes y lideresas de las organizaciones ind\u00edgenas, que luchan por la defensa de sus derechos y sus territorios; y llamar a articular una amplia red de defensa de defensores de la Vida Amaz\u00f3nica<\/p>\n<p>Exigir a los estados nacionales y capitales extranjeros la indemnizaci\u00f3n, derechos de servidumbre, compensaci\u00f3n y remediaci\u00f3n por las afectaciones y los impactos socio ambientales que han sufrido los territorios ind\u00edgenas, por causa de la explotaci\u00f3n minera, de hidrocarburos, infraestructura, megaproyectos y otros.<\/p>\n<p>Exigir a los gobiernos nacionales el respeto por la vida y la intangibilidad de los m\u00e1s de 66 pueblos ind\u00edgenas en aislamiento voluntario en la cuenca amaz\u00f3nica; con pol\u00edticas de protecci\u00f3n efectivas y el establecimiento de corredores binacionales y trinacionales, seg\u00fan corresponda para la defensa efectiva de su sobrevivencia<\/p>\n<p>Demandan que los gobiernos nacionales de forma coordinada con los pueblos ind\u00edgenas a trav\u00e9s de sus respectivas organizaciones nacionales amaz\u00f3nicas, inicien y\/o retomen la delimitaci\u00f3n y legalizaci\u00f3n de m\u00e1s de 100 millones de hect\u00e1reas, en los 9 pa\u00edses de la cuenca amaz\u00f3nica. Los territorios en poder de los pueblos ind\u00edgenas constituyen un freno a la deforestaci\u00f3n y con ello se garantizar una enorme contribuci\u00f3n a la lucha global contra el cambio clim\u00e1tico.<\/p>\n<p>Impulsar la organizaci\u00f3n de las plataformas nacionales ind\u00edgenas de cambio clim\u00e1tico, en aplicaci\u00f3n del p\u00e1rrafo 135 del Acuerdo de Par\u00eds, y que est\u00e9n basadas en las organizaciones territoriales y representativas de los pueblos ind\u00edgenas.<\/p>\n<p>Solicitar el apoyo de (1) los gobiernos nacionales de los 9 pa\u00edses de la cuenca amaz\u00f3nica, (2) las organizaciones nacionales e internacionales, (3) la opini\u00f3n p\u00fablica; a las iniciativas que lleva adelante la COICA y sus 9 miembros, como el Corredor Andes-Amazonas-Atl\u00e1ntico, el Programa de Defensa de Defensores, Programa de titulaci\u00f3n de tierras ind\u00edgenas amaz\u00f3nicas, Redd+ Ind\u00edgena Amaz\u00f3nico; y a nivel nacional iniciativas como Cuencas Sagradas del Ecuador y Per\u00fa enfocados en la conservaci\u00f3n de los territorios, defensa de los derechos, titulaci\u00f3n de tierras ind\u00edgenas, alternativas econ\u00f3micas y valoraci\u00f3n de los servicios ecosist\u00e9micos; que incluye el enfoque de g\u00e9nero e intergeneracional (mujeres, j\u00f3venes y ancianos sabios).<br \/>Convocar a las organizaciones ind\u00edgenas aliadas de COICA, a los gobiernos nacionales amaz\u00f3nicos, agencias y programas de Naciones Unidas, organizaciones multilaterales, entidades acad\u00e9micas, entre otros, a participar en la IV Cumbre Amaz\u00f3nica, II Congreso de Mujeres y Congreso de COICA que se realizar\u00e1 del 18 al 22 de Junio del 2018, en Macap\u00e1 \u2013 Brasil, donde se articular\u00e1n alianzas y estrategias para avanzar en la deuda hist\u00f3rica de titulaci\u00f3n de al menos 100 millones de hect\u00e1reas pendientes, defensa de los defensores amaz\u00f3nicos, la participaci\u00f3n efectiva de las mujeres amaz\u00f3nicas, desarrollar econom\u00edas comunitarias de Vida Plena que avancen en el cambio del modelo extractivista y desarrollista; as\u00ed como tambi\u00e9n impulsar la aplicaci\u00f3n efectiva del Acuerdo de Par\u00eds, en especial las alternativas ind\u00edgenas para cumplir con las metas de reducci\u00f3n de emisiones de los NDC nacionales.<\/p>\n<p>Para constancia de lo resuelto, en la ciudad de Quito, a 19 de marzo de 2018, firman:<\/p>\n<p>Consejo de Coordinaci\u00f3n de la COICA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Coordinadora de las Organizaciones Ind\u00edgenas de la Cuenca Amaz\u00f3nica (COICA)\u00a0y sus organizaciones miembros de los nueve pa\u00edses de la cuenca amaz\u00f3nica: COIAB (Coordinadora de las Organizaciones Ind\u00edgenas de la Amazon\u00eda Brasile\u00f1a) de Brasil, CIDOB (Confederaci\u00f3n de Pueblos Ind\u00edgenas de Bolivia) Bolivia, AIDESEP (Asociaci\u00f3n Inter\u00e9tnica de desarrollo de la Selva Peruana) Per\u00fa, CONFENIAE (Confederaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3744,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[384,4],"tags":[33,35],"class_list":["post-3743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-denuncia","category-noticias","tag-amazonia","tag-coica"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DECLARACI\u00d3N DE QUITO PUEBLOS IND\u00cdGENAS DE LA CUENCA AMAZ\u00d3NICA EN DEFENSA DE SUS DERECHOS Y SUS TERRITORIOS PARA LA VIDA PLENA Y SU APORTE PARA ENFRENTAR EL CAMBIO CLIM\u00c1TICO GLOBAL - REPAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repam.net\/es\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DECLARACI\u00d3N DE QUITO PUEBLOS IND\u00cdGENAS DE LA CUENCA AMAZ\u00d3NICA EN DEFENSA DE SUS DERECHOS Y SUS TERRITORIOS PARA LA VIDA PLENA Y SU APORTE PARA ENFRENTAR EL CAMBIO CLIM\u00c1TICO GLOBAL - REPAM\" \/>\n<meta property=\"og:description\" content=\"La Coordinadora de las Organizaciones Ind\u00edgenas de la Cuenca Amaz\u00f3nica (COICA)\u00a0y sus organizaciones miembros de los nueve pa\u00edses de la cuenca amaz\u00f3nica: COIAB (Coordinadora de las Organizaciones Ind\u00edgenas de la Amazon\u00eda Brasile\u00f1a) de Brasil, CIDOB (Confederaci\u00f3n de Pueblos Ind\u00edgenas de Bolivia) Bolivia, AIDESEP (Asociaci\u00f3n Inter\u00e9tnica de desarrollo de la Selva Peruana) Per\u00fa, CONFENIAE (Confederaci\u00f3n de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repam.net\/es\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\/\" \/>\n<meta property=\"og:site_name\" content=\"REPAM\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-09T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/coica-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"repam@adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repam@adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\\\/\"},\"author\":{\"name\":\"repam@adm\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\"},\"headline\":\"DECLARACI\u00d3N DE QUITO PUEBLOS IND\u00cdGENAS DE LA CUENCA AMAZ\u00d3NICA EN DEFENSA DE SUS DERECHOS Y SUS TERRITORIOS PARA LA VIDA PLENA Y SU APORTE PARA ENFRENTAR EL CAMBIO CLIM\u00c1TICO GLOBAL\",\"datePublished\":\"2018-04-09T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\\\/\"},\"wordCount\":2810,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/coica-2.jpg\",\"keywords\":[\"Amazon\u00eda\",\"Coica\"],\"articleSection\":[\"Denuncia\",\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\\\/\",\"name\":\"DECLARACI\u00d3N DE QUITO PUEBLOS IND\u00cdGENAS DE LA CUENCA AMAZ\u00d3NICA EN DEFENSA DE SUS DERECHOS Y SUS TERRITORIOS PARA LA VIDA PLENA Y SU APORTE PARA ENFRENTAR EL CAMBIO CLIM\u00c1TICO GLOBAL - REPAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/coica-2.jpg\",\"datePublished\":\"2018-04-09T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repam.net\\\/es\\\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/coica-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/coica-2.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DECLARACI\u00d3N DE QUITO PUEBLOS IND\u00cdGENAS DE LA CUENCA AMAZ\u00d3NICA EN DEFENSA DE SUS DERECHOS Y SUS TERRITORIOS PARA LA VIDA PLENA Y SU APORTE PARA ENFRENTAR EL CAMBIO CLIM\u00c1TICO GLOBAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"name\":\"REPAM\",\"description\":\"Red Eclesial Panamaz\u00f3nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repam.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\",\"name\":\"REPAM\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"REPAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\",\"name\":\"repam@adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"caption\":\"repam@adm\"},\"sameAs\":[\"http:\\\/\\\/repam.net\"],\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/author\\\/repamadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DECLARACI\u00d3N DE QUITO PUEBLOS IND\u00cdGENAS DE LA CUENCA AMAZ\u00d3NICA EN DEFENSA DE SUS DERECHOS Y SUS TERRITORIOS PARA LA VIDA PLENA Y SU APORTE PARA ENFRENTAR EL CAMBIO CLIM\u00c1TICO GLOBAL - REPAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repam.net\/es\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\/","og_locale":"es_ES","og_type":"article","og_title":"DECLARACI\u00d3N DE QUITO PUEBLOS IND\u00cdGENAS DE LA CUENCA AMAZ\u00d3NICA EN DEFENSA DE SUS DERECHOS Y SUS TERRITORIOS PARA LA VIDA PLENA Y SU APORTE PARA ENFRENTAR EL CAMBIO CLIM\u00c1TICO GLOBAL - REPAM","og_description":"La Coordinadora de las Organizaciones Ind\u00edgenas de la Cuenca Amaz\u00f3nica (COICA)\u00a0y sus organizaciones miembros de los nueve pa\u00edses de la cuenca amaz\u00f3nica: COIAB (Coordinadora de las Organizaciones Ind\u00edgenas de la Amazon\u00eda Brasile\u00f1a) de Brasil, CIDOB (Confederaci\u00f3n de Pueblos Ind\u00edgenas de Bolivia) Bolivia, AIDESEP (Asociaci\u00f3n Inter\u00e9tnica de desarrollo de la Selva Peruana) Per\u00fa, CONFENIAE (Confederaci\u00f3n de [&hellip;]","og_url":"https:\/\/www.repam.net\/es\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\/","og_site_name":"REPAM","article_published_time":"2018-04-09T05:00:00+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/coica-2.jpg","type":"image\/jpeg"}],"author":"repam@adm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"repam@adm","Tiempo de lectura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repam.net\/es\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\/#article","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\/"},"author":{"name":"repam@adm","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033"},"headline":"DECLARACI\u00d3N DE QUITO PUEBLOS IND\u00cdGENAS DE LA CUENCA AMAZ\u00d3NICA EN DEFENSA DE SUS DERECHOS Y SUS TERRITORIOS PARA LA VIDA PLENA Y SU APORTE PARA ENFRENTAR EL CAMBIO CLIM\u00c1TICO GLOBAL","datePublished":"2018-04-09T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repam.net\/es\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\/"},"wordCount":2810,"publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"image":{"@id":"https:\/\/www.repam.net\/es\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/coica-2.jpg","keywords":["Amazon\u00eda","Coica"],"articleSection":["Denuncia","Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.repam.net\/es\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\/","url":"https:\/\/www.repam.net\/es\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\/","name":"DECLARACI\u00d3N DE QUITO PUEBLOS IND\u00cdGENAS DE LA CUENCA AMAZ\u00d3NICA EN DEFENSA DE SUS DERECHOS Y SUS TERRITORIOS PARA LA VIDA PLENA Y SU APORTE PARA ENFRENTAR EL CAMBIO CLIM\u00c1TICO GLOBAL - REPAM","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repam.net\/es\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\/#primaryimage"},"image":{"@id":"https:\/\/www.repam.net\/es\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/coica-2.jpg","datePublished":"2018-04-09T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.repam.net\/es\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repam.net\/es\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\/#primaryimage","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/coica-2.jpg","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/coica-2.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.repam.net\/es\/declaracion-de-quito-pueblos-indigenas-de-la-cuenca-amazonica-en-defensa-de-sus-derechos-y-sus-territorios-para-la-vida-plena-y-su-aporte-para-enfrentar-el-cambio-climatico-global\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repam.net\/es\/"},{"@type":"ListItem","position":2,"name":"DECLARACI\u00d3N DE QUITO PUEBLOS IND\u00cdGENAS DE LA CUENCA AMAZ\u00d3NICA EN DEFENSA DE SUS DERECHOS Y SUS TERRITORIOS PARA LA VIDA PLENA Y SU APORTE PARA ENFRENTAR EL CAMBIO CLIM\u00c1TICO GLOBAL"}]},{"@type":"WebSite","@id":"https:\/\/www.repam.net\/es\/#website","url":"https:\/\/www.repam.net\/es\/","name":"REPAM","description":"Red Eclesial Panamaz\u00f3nica","publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repam.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.repam.net\/es\/#organization","name":"REPAM","url":"https:\/\/www.repam.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","width":512,"height":512,"caption":"REPAM"},"image":{"@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033","name":"repam@adm","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","caption":"repam@adm"},"sameAs":["http:\/\/repam.net"],"url":"https:\/\/www.repam.net\/es\/author\/repamadm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/3743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/comments?post=3743"}],"version-history":[{"count":0,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/3743\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media\/3744"}],"wp:attachment":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media?parent=3743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/categories?post=3743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/tags?post=3743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}