{"id":4460,"date":"2016-09-30T00:00:00","date_gmt":"2016-09-30T05:00:00","guid":{"rendered":"http:\/\/repam.net\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\/"},"modified":"2016-09-30T00:00:00","modified_gmt":"2016-09-30T05:00:00","slug":"comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano","status":"publish","type":"post","link":"https:\/\/www.repam.net\/es\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\/","title":{"rendered":"Comunicado de la Red \u201cIglesias y Miner\u00eda\u201d  sobre el an\u00e1lisis del contexto latinoamericano"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">La Red \u201cIglesias y Miner\u00eda\u201d, que reuni\u00f3 a 50 de sus miembros, provenientes de las Am\u00e9ricas, y a algunos aliados europeos, en el III Encuentro continental en Bogot\u00e1, del 2 al 6 de septiembre de 2016, profundiz\u00f3 su an\u00e1lisis y debate sobre el contexto pol\u00edtico regional y por ello, considera necesario hacer p\u00fablica su preocupaci\u00f3n y su llamado a la justicia y la paz, fundadas en el respeto a la Madre Tierra, el &#8220;principio del bien com\u00fan&#8221; y &#8220;inmensa dignidad de los pobres&#8221; (Laudato Si &#8216;, n. 158).<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Crece en el mundo y en Am\u00e9rica Latina, la concentraci\u00f3n de la riqueza. En nuestro continente, el 0,5% de la poblaci\u00f3n econ\u00f3micamente activa posee el 43% de la riqueza de la regi\u00f3n y el 8% m\u00e1s rico tiene el 87% de la misma. El capital de las grandes corporaciones influye decisivamente en las l\u00edneas econ\u00f3micas y pol\u00edticas de los estados nacionales. La concentraci\u00f3n de la propiedad de los medios en varios pa\u00edses del continente responde a sus intereses.<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Constatamos, por tanto,\u00a0 la &#8220;privatizaci\u00f3n de la democracia&#8221; en Am\u00e9rica Latina, lo que determina un proceso de restauraci\u00f3n conservadora preocupante, afirmada desde la imposici\u00f3n cada vez m\u00e1s frecuente del &#8220;estado de excepci\u00f3n&#8221;. Con esto, las autoridades gubernamentales imponen proyectos impactantes y discriminan a las comunidades tradicionales y formas de vida, criminalizan a los movimientos sociales y manifestaciones populares en el campo y en las ciudades,\u00a0 flexibilizan las\u00a0 leyes para facilitar la inversi\u00f3n al servicio del gran capital.<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Los tratados comerciales internacionales, incluyendo el TPP, dise\u00f1ado para favorecer a las grandes empresas, pueden tornar irreversibles las violaciones de los derechos contra las comunidades que acompa\u00f1amos.<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">La Red \u201cIglesias y Miner\u00eda\u201d apoya firmemente el proceso de paz en Colombia y a las muchas personas y organizaciones que la est\u00e1n promoviendo activamente. Las esperanzas de que este proceso pueda instaurar en el pa\u00eds una cultura de la reconciliaci\u00f3n y la justicia restaurativa, una justicia social basada en la distribuci\u00f3n de bienes y el derecho a tierra, techo y trabajo para todos y todas.<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Por otro lado, denunciamos las omisiones e ineficacia de los estados frente a los cada vez m\u00e1s numerosos asesinatos de l\u00edderes de las comunidades que critican este sistema de muerte en Honduras, Guatemala, Per\u00fa, Colombia, Ecuador, entre otros.<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Seguimos con preocupaci\u00f3n la crisis econ\u00f3mica, pol\u00edtica e institucional en Venezuela. Entre otras razones, vemos en ella la confirmaci\u00f3n de la insostenibilidad de cualquier econom\u00eda basada en la extracci\u00f3n.<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Denunciamos el golpe de Estado en Brasil, al servicio de los intereses corporativos y de los pa\u00edses con mayor ambici\u00f3n de control geopol\u00edtico mundial, los bienes naturales y las materias primas de esa hermana naci\u00f3n. Por otro lado, el distanciamiento de la agenda del gobierno progresista brasile\u00f1o de los movimientos populares, de las causas de las comunidades tradicionales y los desaf\u00edos ambientales, nos lleva a reflexionar profundamente sobre el papel de la izquierda en Am\u00e9rica Latina. Apoyamos las fuerzas populares brasile\u00f1as, j\u00f3venes, movimientos ind\u00edgenas y otros sectores de la sociedad civil para expresar su indignaci\u00f3n por la violaci\u00f3n de la democracia y el desmantelamiento del sistema de garant\u00eda de derechos que se est\u00e1 anunciando en el pa\u00eds.<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">El reflejo de la agresi\u00f3n contra la democracia y los pobres es a\u00fan m\u00e1s indignante por la cruel criminalizaci\u00f3n de l\u00edderes de la comunidad que se rebelan ante este modelo pol\u00edtico-econ\u00f3mico. \u201cIglesias y Miner\u00eda\u201d se solidariza con las familias de N\u00e9stor Iv\u00e1n Mart\u00ednez, dirigente social de la cuenca minera del departamento de Cesar, en el norte de Colombia (muerto el domingo 11 de septiembre) y do\u00f1a M\u00e1xima Acu\u00f1a y su esposo Jaime, atacados violentamente en su casa por los empleados de la minera Yanacocha, el domingo, 18 de septiembre, en Cajamarca, Per\u00fa.<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Llamamos a todas las personas de buena voluntad, los movimientos sociales y comunidades de fe a no perder la esperanza en ese momento tan delicado en la historia de Am\u00e9rica Latina y el Caribe, luchando con creatividad y obstinaci\u00f3n en la defensa de la democracia, los pobres y la Madre Tierra y la construcci\u00f3n de espacios de ciudadan\u00eda independientes, auto-gestionados y cuidadores de las culturas y territorios.<\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p><strong>19 de septiembre de, 2016, Red \u201cIglesias y Miner\u00eda\u201d<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u00a0 La Red \u201cIglesias y Miner\u00eda\u201d, que reuni\u00f3 a 50 de sus miembros, provenientes de las Am\u00e9ricas, y a algunos aliados europeos, en el III Encuentro continental en Bogot\u00e1, del 2 al 6 de septiembre de 2016, profundiz\u00f3 su an\u00e1lisis y debate sobre el contexto pol\u00edtico regional y por ello, considera necesario hacer p\u00fablica [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[384,4],"tags":[878,276],"class_list":["post-4460","post","type-post","status-publish","format-standard","hentry","category-denuncia","category-noticias","tag-iym","tag-mineria"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comunicado de la Red \u201cIglesias y Miner\u00eda\u201d sobre el an\u00e1lisis del contexto latinoamericano - REPAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repam.net\/es\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunicado de la Red \u201cIglesias y Miner\u00eda\u201d sobre el an\u00e1lisis del contexto latinoamericano - REPAM\" \/>\n<meta property=\"og:description\" content=\"&nbsp; \u00a0 La Red \u201cIglesias y Miner\u00eda\u201d, que reuni\u00f3 a 50 de sus miembros, provenientes de las Am\u00e9ricas, y a algunos aliados europeos, en el III Encuentro continental en Bogot\u00e1, del 2 al 6 de septiembre de 2016, profundiz\u00f3 su an\u00e1lisis y debate sobre el contexto pol\u00edtico regional y por ello, considera necesario hacer p\u00fablica [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repam.net\/es\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\/\" \/>\n<meta property=\"og:site_name\" content=\"REPAM\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-30T05:00:00+00:00\" \/>\n<meta name=\"author\" content=\"repam@adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repam@adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\\\/\"},\"author\":{\"name\":\"repam@adm\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\"},\"headline\":\"Comunicado de la Red \u201cIglesias y Miner\u00eda\u201d sobre el an\u00e1lisis del contexto latinoamericano\",\"datePublished\":\"2016-09-30T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\\\/\"},\"wordCount\":763,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"keywords\":[\"IYM\",\"Miner\u00eda\"],\"articleSection\":[\"Denuncia\",\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\\\/\",\"name\":\"Comunicado de la Red \u201cIglesias y Miner\u00eda\u201d sobre el an\u00e1lisis del contexto latinoamericano - REPAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\"},\"datePublished\":\"2016-09-30T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repam.net\\\/es\\\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicado de la Red \u201cIglesias y Miner\u00eda\u201d sobre el an\u00e1lisis del contexto latinoamericano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"name\":\"REPAM\",\"description\":\"Red Eclesial Panamaz\u00f3nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repam.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\",\"name\":\"REPAM\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"REPAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\",\"name\":\"repam@adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"caption\":\"repam@adm\"},\"sameAs\":[\"http:\\\/\\\/repam.net\"],\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/author\\\/repamadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunicado de la Red \u201cIglesias y Miner\u00eda\u201d sobre el an\u00e1lisis del contexto latinoamericano - REPAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repam.net\/es\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\/","og_locale":"es_ES","og_type":"article","og_title":"Comunicado de la Red \u201cIglesias y Miner\u00eda\u201d sobre el an\u00e1lisis del contexto latinoamericano - REPAM","og_description":"&nbsp; \u00a0 La Red \u201cIglesias y Miner\u00eda\u201d, que reuni\u00f3 a 50 de sus miembros, provenientes de las Am\u00e9ricas, y a algunos aliados europeos, en el III Encuentro continental en Bogot\u00e1, del 2 al 6 de septiembre de 2016, profundiz\u00f3 su an\u00e1lisis y debate sobre el contexto pol\u00edtico regional y por ello, considera necesario hacer p\u00fablica [&hellip;]","og_url":"https:\/\/www.repam.net\/es\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\/","og_site_name":"REPAM","article_published_time":"2016-09-30T05:00:00+00:00","author":"repam@adm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"repam@adm","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repam.net\/es\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\/#article","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\/"},"author":{"name":"repam@adm","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033"},"headline":"Comunicado de la Red \u201cIglesias y Miner\u00eda\u201d sobre el an\u00e1lisis del contexto latinoamericano","datePublished":"2016-09-30T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repam.net\/es\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\/"},"wordCount":763,"publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"keywords":["IYM","Miner\u00eda"],"articleSection":["Denuncia","Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.repam.net\/es\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\/","url":"https:\/\/www.repam.net\/es\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\/","name":"Comunicado de la Red \u201cIglesias y Miner\u00eda\u201d sobre el an\u00e1lisis del contexto latinoamericano - REPAM","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/#website"},"datePublished":"2016-09-30T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.repam.net\/es\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repam.net\/es\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.repam.net\/es\/comunicado-la-red-iglesias-mineria-analisis-del-contexto-latinoamericano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repam.net\/es\/"},{"@type":"ListItem","position":2,"name":"Comunicado de la Red \u201cIglesias y Miner\u00eda\u201d sobre el an\u00e1lisis del contexto latinoamericano"}]},{"@type":"WebSite","@id":"https:\/\/www.repam.net\/es\/#website","url":"https:\/\/www.repam.net\/es\/","name":"REPAM","description":"Red Eclesial Panamaz\u00f3nica","publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repam.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.repam.net\/es\/#organization","name":"REPAM","url":"https:\/\/www.repam.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","width":512,"height":512,"caption":"REPAM"},"image":{"@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033","name":"repam@adm","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","caption":"repam@adm"},"sameAs":["http:\/\/repam.net"],"url":"https:\/\/www.repam.net\/es\/author\/repamadm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/4460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/comments?post=4460"}],"version-history":[{"count":0,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/4460\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media?parent=4460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/categories?post=4460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/tags?post=4460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}