{"id":4564,"date":"2016-05-20T00:00:00","date_gmt":"2016-05-20T05:00:00","guid":{"rendered":"http:\/\/repam.net\/radio-ucamara-premio-nacional-promover-lengua-kukama\/"},"modified":"2021-09-29T19:14:46","modified_gmt":"2021-09-30T00:14:46","slug":"radio-ucamara-premio-nacional-promover-lengua-kukama","status":"publish","type":"post","link":"https:\/\/www.repam.net\/es\/radio-ucamara-premio-nacional-promover-lengua-kukama\/","title":{"rendered":"Radio Ucamara: Premio Nacional por promover lengua Kukama"},"content":{"rendered":"<p><strong><a href=\"https:\/\/redamazonica.org\/wp-content\/uploads\/2016\/05\/Ucamara1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium \" src=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Ucamara1-300x225-1.jpg\" alt=\"Ucamara1\" width=\"300\" height=\"225\"><\/a>Nauta, Loreto &ndash; Per&uacute; 20-05-2016 (REPAM).-<\/strong> En la Amazon&iacute;a peruana, el pueblo ind&iacute;gena Kukama, estaba perdiendo su idioma. Muy pocas personas hablaban o quer&iacute;an hablar su lengua Kukama. Luego de varios siglos en los que sufrieron el despojo o la invasi&oacute;n de sus tierras por las empresas del caucho y luego por las madereras y petroleras, la juventud y ni&ntilde;ez Kukama no le encontraba sentido a seguir hablando su idioma propio.<\/p>\n<p>Pero gracias al trabajo de Radio Ucamara, en alianza con los ancianos y sabios Kukamas, con las organizaciones locales, con algunos profesores y la Iglesia Cat&oacute;lica, hoy ni&ntilde;os y j&oacute;venes han vuelto a sentir el orgullo de expresarse en su propia lengua, tienen una escuela, grupos de m&uacute;sica, diccionario propio, videos, recuperaci&oacute;n de su tradici&oacute;n y cultura oral, etc.<\/p>\n<p>Por este esfuerzo constante de m&aacute;s de 10 a&ntilde;os de trabajo, Radio Ucamara recibir&aacute; el Premio Nacional como &ldquo;Personalidad meritoria de la cultura&rdquo;, otorgado por el Ministerio de Cultura del Per&uacute;. La ceremonia se efectuar&aacute; en la capital peruana el 27 de mayo, d&iacute;a nacional de las lenguas originarias.<\/p>\n<p><a href=\"https:\/\/redamazonica.org\/wp-content\/uploads\/2016\/05\/kukama.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium \" src=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/kukama-300x225.jpg\" alt=\"kukama\" width=\"300\" height=\"225\"><\/a>Leonardo Tello, director de Radio Ucamara, nos cuenta que la radio naci&oacute; en 1992, en Nauta, a las riberas del r&iacute;o Mara&ntilde;&oacute;n, el coraz&oacute;n del Territorio Kukama. La emisora pertenece al Instituto de Promoci&oacute;n Social Amaz&oacute;nica del Vicariato Apost&oacute;lico de Iquitos. En la &uacute;ltima d&eacute;cada la emisora se ha destacado por la participaci&oacute;n de los ind&iacute;genas y por ser una radio &ldquo;que vive en carne propia el aplastamiento y la apropiaci&oacute;n de los territorios de los Pueblos Ind&iacute;genas&hellip; y por ellos es una radio pensada y proyectada desde el pensamiento ind&iacute;gena Kukama&rdquo;.<\/p>\n<p>Actualmente la emisora premiada realiza diversos trabajos, como por ejemplo: investigaciones sobre la memoria individual y colectiva del pueblo Kukama, publicaciones de libros en lengua kukama, producciones radiof&oacute;nicas con la participaci&oacute;n de las comunidades, producci&oacute;n de documentales sobre temas ind&iacute;genas. Han incursionado tambi&eacute;n en la producci&oacute;n de video y cine comunitario: producciones de v&iacute;deo clips con fusiones de lenguas y ritmos, con apoyo de voluntarios como Create your Voice, J&oacute;venes esperanza Amazon&iacute;a; producci&oacute;n de animaciones y pel&iacute;cula sobre &ldquo;Karuara, la gente del r&iacute;o&rdquo; con el apoyo de Quisca Producciones.<\/p>\n<p><a href=\"https:\/\/redamazonica.org\/wp-content\/uploads\/2016\/05\/Ucamara.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium \" src=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Ucamara-300x202.jpg\" alt=\"Ucamara\" width=\"300\" height=\"202\"><\/a>Destaca en el campo educativo, la Escuela IKUARI para la revitalizaci&oacute;n de la casi desaparecida lengua Kukama. Con abuelas y abuelos ense&ntilde;ando tradicionalmente a los ni&ntilde;os su lengua propia. Realizan tambi&eacute;n ciclos de cine documental ind&iacute;gena, elaboraci&oacute;n de mapas pol&iacute;ticos culturales, fotograf&iacute;a, talleres de dibujos sobre mitos Kukama, murales sobre el r&iacute;o en alianza &ldquo;Arte y comunicaci&oacute;n ind&iacute;gena&rdquo; con la Escuela Nyi Escuela de Arte del r&iacute;o Yarapa; entre otras iniciativas. Un nuevo modelo de radio, que se construye desde y con la gente. Una radio que no se limita a la difusi&oacute;n de noticias o a los programas hechos en la cabina. Una radio que trabaja por una transformaci&oacute;n social y que como un ciudadano kukama m&aacute;s, participa y act&uacute;a en todas las esferas de la vida de su pueblo. &ldquo;Una radio que avanza despacio &ldquo;Sin prisa, pero sin pausa&rdquo;, trabajando desde las &ldquo;fronteras&rdquo;, transmitiendo esperanza y buscando el bien para todas y todos&rdquo;.<\/p>\n<p><a href=\"https:\/\/redamazonica.org\/wp-content\/uploads\/2016\/05\/Kukama1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium \" src=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Kukama1-300x200.jpg\" alt=\"Kukama1\" width=\"300\" height=\"200\"><\/a>&ldquo;Este trabajo, no podr&iacute;a ser posible sin el apoyo de muchas entidades y personas que creen y colaboran con el esfuerzo de esta peque&ntilde;a emisora. Gracias a todos ellos, gracia al equipo de Radio Ucamara&hellip; gracias infinitamente al Pueblo KUKAMA. Este Galard&oacute;n lo recibimos con humildad y lo dedicamos a nuestro pueblo y a todos los pueblos ind&iacute;genas que luchan por la vida y la vida de todas las generaciones venideras&rdquo;,, se&ntilde;ala Leonardo Tello.<\/p>\n<p>Por este trabajo, reconocido en los &aacute;mbitos, local, nacional e internacional, este 27 de mayo en el Gran Teatro Nacional, en la Av. Javier Prado Este N&deg; 2465, San Borja, Lima, Per&uacute;, en horas de la ma&ntilde;ana. Radio Ucamara recibir&aacute; el Galard&oacute;n de: &ldquo;PERSONALIDAD MERITORIA DE LA CULTURA&rdquo;.<\/p>\n<p>Desde la Red Eclesial Panamaz&oacute;nica, nuestras felicitaciones y tambi&eacute;n nuestro reconocimiento por este esfuerzo y aporte desde la comunicaci&oacute;n, la educaci&oacute;n y la cultura de Radio Ucamara.<\/p>\n<p><strong>Fuentes:<\/strong><em> Radio Ucamara y entrevista a Leonardo Tello, realizada por Radio Kampagkis &ndash; CNR<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nauta, Loreto &ndash; Per&uacute; 20-05-2016 (REPAM).- En la Amazon&iacute;a peruana, el pueblo ind&iacute;gena Kukama, estaba perdiendo su idioma. Muy pocas personas hablaban o quer&iacute;an hablar su lengua Kukama. Luego de varios siglos en los que sufrieron el despojo o la invasi&oacute;n de sus tierras por las empresas del caucho y luego por las madereras y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4565,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[285,4],"tags":[606,355],"class_list":["post-4564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales","category-noticias","tag-kukama","tag-radio-ucamara"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Radio Ucamara: Premio Nacional por promover lengua Kukama - REPAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repam.net\/es\/radio-ucamara-premio-nacional-promover-lengua-kukama\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Radio Ucamara: Premio Nacional por promover lengua Kukama - REPAM\" \/>\n<meta property=\"og:description\" content=\"Nauta, Loreto &ndash; Per&uacute; 20-05-2016 (REPAM).- En la Amazon&iacute;a peruana, el pueblo ind&iacute;gena Kukama, estaba perdiendo su idioma. Muy pocas personas hablaban o quer&iacute;an hablar su lengua Kukama. Luego de varios siglos en los que sufrieron el despojo o la invasi&oacute;n de sus tierras por las empresas del caucho y luego por las madereras y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repam.net\/es\/radio-ucamara-premio-nacional-promover-lengua-kukama\/\" \/>\n<meta property=\"og:site_name\" content=\"REPAM\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-20T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-30T00:14:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Ucamara1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"repam@adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repam@adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/radio-ucamara-premio-nacional-promover-lengua-kukama\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/radio-ucamara-premio-nacional-promover-lengua-kukama\\\/\"},\"author\":{\"name\":\"repam@adm\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\"},\"headline\":\"Radio Ucamara: Premio Nacional por promover lengua Kukama\",\"datePublished\":\"2016-05-20T05:00:00+00:00\",\"dateModified\":\"2021-09-30T00:14:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/radio-ucamara-premio-nacional-promover-lengua-kukama\\\/\"},\"wordCount\":844,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/radio-ucamara-premio-nacional-promover-lengua-kukama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Ucamara1.jpg\",\"keywords\":[\"kukama\",\"Radio Ucamara\"],\"articleSection\":[\"Internacionales\",\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/radio-ucamara-premio-nacional-promover-lengua-kukama\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/radio-ucamara-premio-nacional-promover-lengua-kukama\\\/\",\"name\":\"Radio Ucamara: Premio Nacional por promover lengua Kukama - REPAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/radio-ucamara-premio-nacional-promover-lengua-kukama\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/radio-ucamara-premio-nacional-promover-lengua-kukama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Ucamara1.jpg\",\"datePublished\":\"2016-05-20T05:00:00+00:00\",\"dateModified\":\"2021-09-30T00:14:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/radio-ucamara-premio-nacional-promover-lengua-kukama\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repam.net\\\/es\\\/radio-ucamara-premio-nacional-promover-lengua-kukama\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/radio-ucamara-premio-nacional-promover-lengua-kukama\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Ucamara1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Ucamara1.jpg\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/radio-ucamara-premio-nacional-promover-lengua-kukama\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Radio Ucamara: Premio Nacional por promover lengua Kukama\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"name\":\"REPAM\",\"description\":\"Red Eclesial Panamaz\u00f3nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repam.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\",\"name\":\"REPAM\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"REPAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\",\"name\":\"repam@adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"caption\":\"repam@adm\"},\"sameAs\":[\"http:\\\/\\\/repam.net\"],\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/author\\\/repamadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Radio Ucamara: Premio Nacional por promover lengua Kukama - REPAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repam.net\/es\/radio-ucamara-premio-nacional-promover-lengua-kukama\/","og_locale":"es_ES","og_type":"article","og_title":"Radio Ucamara: Premio Nacional por promover lengua Kukama - REPAM","og_description":"Nauta, Loreto &ndash; Per&uacute; 20-05-2016 (REPAM).- En la Amazon&iacute;a peruana, el pueblo ind&iacute;gena Kukama, estaba perdiendo su idioma. Muy pocas personas hablaban o quer&iacute;an hablar su lengua Kukama. Luego de varios siglos en los que sufrieron el despojo o la invasi&oacute;n de sus tierras por las empresas del caucho y luego por las madereras y [&hellip;]","og_url":"https:\/\/www.repam.net\/es\/radio-ucamara-premio-nacional-promover-lengua-kukama\/","og_site_name":"REPAM","article_published_time":"2016-05-20T05:00:00+00:00","article_modified_time":"2021-09-30T00:14:46+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Ucamara1.jpg","type":"image\/jpeg"}],"author":"repam@adm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"repam@adm","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repam.net\/es\/radio-ucamara-premio-nacional-promover-lengua-kukama\/#article","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/radio-ucamara-premio-nacional-promover-lengua-kukama\/"},"author":{"name":"repam@adm","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033"},"headline":"Radio Ucamara: Premio Nacional por promover lengua Kukama","datePublished":"2016-05-20T05:00:00+00:00","dateModified":"2021-09-30T00:14:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repam.net\/es\/radio-ucamara-premio-nacional-promover-lengua-kukama\/"},"wordCount":844,"publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"image":{"@id":"https:\/\/www.repam.net\/es\/radio-ucamara-premio-nacional-promover-lengua-kukama\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Ucamara1.jpg","keywords":["kukama","Radio Ucamara"],"articleSection":["Internacionales","Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.repam.net\/es\/radio-ucamara-premio-nacional-promover-lengua-kukama\/","url":"https:\/\/www.repam.net\/es\/radio-ucamara-premio-nacional-promover-lengua-kukama\/","name":"Radio Ucamara: Premio Nacional por promover lengua Kukama - REPAM","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repam.net\/es\/radio-ucamara-premio-nacional-promover-lengua-kukama\/#primaryimage"},"image":{"@id":"https:\/\/www.repam.net\/es\/radio-ucamara-premio-nacional-promover-lengua-kukama\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Ucamara1.jpg","datePublished":"2016-05-20T05:00:00+00:00","dateModified":"2021-09-30T00:14:46+00:00","breadcrumb":{"@id":"https:\/\/www.repam.net\/es\/radio-ucamara-premio-nacional-promover-lengua-kukama\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repam.net\/es\/radio-ucamara-premio-nacional-promover-lengua-kukama\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/radio-ucamara-premio-nacional-promover-lengua-kukama\/#primaryimage","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Ucamara1.jpg","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/09\/Ucamara1.jpg","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.repam.net\/es\/radio-ucamara-premio-nacional-promover-lengua-kukama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repam.net\/es\/"},{"@type":"ListItem","position":2,"name":"Radio Ucamara: Premio Nacional por promover lengua Kukama"}]},{"@type":"WebSite","@id":"https:\/\/www.repam.net\/es\/#website","url":"https:\/\/www.repam.net\/es\/","name":"REPAM","description":"Red Eclesial Panamaz\u00f3nica","publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repam.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.repam.net\/es\/#organization","name":"REPAM","url":"https:\/\/www.repam.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","width":512,"height":512,"caption":"REPAM"},"image":{"@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033","name":"repam@adm","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","caption":"repam@adm"},"sameAs":["http:\/\/repam.net"],"url":"https:\/\/www.repam.net\/es\/author\/repamadm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/4564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/comments?post=4564"}],"version-history":[{"count":1,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/4564\/revisions"}],"predecessor-version":[{"id":4579,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/4564\/revisions\/4579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media\/4565"}],"wp:attachment":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media?parent=4564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/categories?post=4564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/tags?post=4564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}