{"id":5848,"date":"2021-12-29T21:18:07","date_gmt":"2021-12-30T02:18:07","guid":{"rendered":"https:\/\/www.repam.net\/es\/?p=5848"},"modified":"2021-12-29T21:18:08","modified_gmt":"2021-12-30T02:18:08","slug":"avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras","status":"publish","type":"post","link":"https:\/\/www.repam.net\/es\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\/","title":{"rendered":"Avasalladores queman casas y atemorizan con armas a ind\u00edgenas tsimanes para quitarles sus tierras"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"420\" src=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/12\/indigenas-tsimanes.png\" alt=\"\" class=\"wp-image-5849\" srcset=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/12\/indigenas-tsimanes.png 750w, https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/12\/indigenas-tsimanes-300x168.png 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption>nd\u00edgenas tsimanes. Foto. Whitman Merena<\/figcaption><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Los ind\u00edgenas Tsimanes lamentan la indiferencia del Gobierno ante los abusos que sufren por parte de los avasalladores.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Por Agencia de Noticias Fides &#8211; ANF<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTenemos miedo\u201d, dice con tristeza don Ismael Cuata Cari, mientras relata que el pasado mes de octubre avasalladores de tierras invadieron su comunidad Jatatal en territorio Tsimane, en la Amazon\u00eda boliviana. A punta de escopeta y golpes, los amenazaron para que abandonen sus territorios que habitan y protegen desde hace muchos a\u00f1os.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el duro relato, don Ismael cuenta que los avasalladores prendieron fuego a sus viviendas, sin tener compasi\u00f3n de los ni\u00f1os ind\u00edgenas que lloraban al ver que sus pocas pertenencias se quemaban. Muchos perdieron todo, otros lograron escapar por miedo a que atenten contra sus vidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn octubre vinieron ellos, quemaron las casas, quemaron las camas. (Nosotros) ya no nos podemos cambiar, somos originarios tsimanes, tenemos miedo. Nos amenazan con escopetas, traen sus armas\u201d, afirma con tristeza, a tiempo de revelar que huyeron por temor a que da\u00f1en a sus hijos. \u201cMis wawitas, (los) hijitos de mi familia, hay miedo\u201d, dice.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indica que no pod\u00edan defenderse de las agresiones y se\u00f1ala que los maltratos por parte de los avasalladores son frecuentes. Admite que en otras oportunidades su comunidad ya fue desalojada a la fuerza de sus tierras y se asentaron en otras regiones para no seguir con los enfrentamientos, sin embargo ahora tambi\u00e9n pretenden despojarlos de sus hogares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pese al miedo y las humillaciones que sufren, los pobladores de la comunidad Jatatal ya no quieren ser desalojados de sus tierras y por eso piden al Gobierno que respete sus derechos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo se pod\u00eda discutir, nosotros solo mir\u00e1bamos (como se quemaban las casas). Nos empujan m\u00e1s all\u00e1, pero ya no queremos ir, hay cementerios, hay casas. Nosotros no queremos ir a otro lado, queremos quedarnos ah\u00ed (en nuestras tierras), queremos que nuestras familias y ni\u00f1os se queden en sus tierras. Ya estamos cansados\u201d, se\u00f1ala.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Don Ismael comenta que acudieron al Instituto Nacional de Reforma Agraria (INRA) para que los reconozca y se hagan prevalecer sus derechos. Incluso esa instituci\u00f3n visit\u00f3 la comunidad, verific\u00f3 que los ind\u00edgenas habitan desde hace varios a\u00f1os atr\u00e1s, pero hasta ahora los ind\u00edgenas est\u00e1n a la espera del informe de la inspecci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Don Ismael Cuata\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/mxoF3m9NKoA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La esposa de don Ismael, M\u00f3nica Ista implora al Gobierno que respete los derechos de los tsimanes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00bfD\u00f3nde van a vivir nuestros hijos, queremos nuestras tierras para nuestros hijos. Nosotros somos vivientes de la comunidad de Jatatal. Mi pap\u00e1, mi mam\u00e1 y mi hermano han vivido, han muerto y est\u00e1n enterrados en estas tierras. Pedimos al Estado que se respeten nuestros derechos, no vamos a salir porque es nuestra tierra\u201d, afirma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pasado 7 de octubre el pueblo ind\u00edgena Tsimane&#8217; present\u00f3, junto a organizaciones de la sociedad civil, el Informe Alternativo al Comit\u00e9 para la Eliminaci\u00f3n de la Discriminaci\u00f3n Racial (CERD) de la Organizaci\u00f3n de Naciones Unidas (ONU), en el que denuncia que es v\u00edctima del olvido y la discriminaci\u00f3n del Gobierno nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esa investigaci\u00f3n revel\u00f3 que una de las principales preocupaciones de las organizaciones del pueblo Tsimane es que las tierras que habitan est\u00e1n siendo avasalladas por otros actores socioecon\u00f3micos, quienes, \u201cbajo la complicidad del Estado, han generado el desplazamiento forzado de muchas familias y comunidades. Esta situaci\u00f3n, se relaciona con el impacto que ha tenido la imposici\u00f3n de proyectos de desarrollo en sus territorios, lo que ha provocado un agravamiento de la situaci\u00f3n de marginaci\u00f3n, derivada de la falta de acceso y control de sus tierras, territorios y recursos naturales\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, el informe revela que los ind\u00edgenas no acceden a la justicia en igualdad de condiciones con otros sectores sociales de la regi\u00f3n, sus denuncias y procesos penales son paralizados u obstaculizados por la discriminaci\u00f3n y el prejuicio que impera en las instituciones del pa\u00eds. Adem\u00e1s de ello, tambi\u00e9n se observan rasgos de discriminaci\u00f3n en el desconocimiento de las autoridades propias y sus mecanismos de resoluci\u00f3n de con\ufb02ictos; as\u00ed como en la violencia de la que son v\u00edctimas las mujeres ind\u00edgenas Tsimane\u2019, sobre todo en relaci\u00f3n con sus derechos sexuales y reproductivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EL INFORME<\/strong>:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-scribd wp-block-embed-scribd\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Informe Al CERD Discriminaci\u00f3n Al Pueblo Tsimane\" class=\"scribd_iframe_embed\" src=\"https:\/\/www.scribd.com\/embeds\/535674562\/content\" data-aspect-ratio=\"0.7729220222793488\" scrolling=\"no\" id=\"535674562\" width=\"500\" height=\"750\" frameborder=\"0\"><\/iframe><script type=\"text\/javascript\">          (function() { var scribd = document.createElement(\"script\"); scribd.type = \"text\/javascript\"; scribd.async = true; scribd.src = \"https:\/\/www.scribd.com\/javascripts\/embed_code\/inject.js\"; var s = document.getElementsByTagName(\"script\")[0]; s.parentNode.insertBefore(scribd, s); })()        <\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los ind\u00edgenas Tsimanes lamentan la indiferencia del Gobierno ante los abusos que sufren por parte de los avasalladores. Por Agencia de Noticias Fides &#8211; ANF \u201cTenemos miedo\u201d, dice con tristeza don Ismael Cuata Cari, mientras relata que el pasado mes de octubre avasalladores de tierras invadieron su comunidad Jatatal en territorio Tsimane, en la Amazon\u00eda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5850,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[46,4],"tags":[33,70,47,52,1034,16],"class_list":["post-5848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bolivia","category-noticias","tag-amazonia","tag-avasallamientos","tag-bolivia","tag-derechos-humanos","tag-pueblo-tsimane","tag-pueblos-indigenas"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avasalladores queman casas y atemorizan con armas a ind\u00edgenas tsimanes para quitarles sus tierras - REPAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repam.net\/es\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avasalladores queman casas y atemorizan con armas a ind\u00edgenas tsimanes para quitarles sus tierras - REPAM\" \/>\n<meta property=\"og:description\" content=\"Los ind\u00edgenas Tsimanes lamentan la indiferencia del Gobierno ante los abusos que sufren por parte de los avasalladores. Por Agencia de Noticias Fides &#8211; ANF \u201cTenemos miedo\u201d, dice con tristeza don Ismael Cuata Cari, mientras relata que el pasado mes de octubre avasalladores de tierras invadieron su comunidad Jatatal en territorio Tsimane, en la Amazon\u00eda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repam.net\/es\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\/\" \/>\n<meta property=\"og:site_name\" content=\"REPAM\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-30T02:18:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-30T02:18:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/12\/indigenas-tsimanes-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"repam@adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repam@adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\\\/\"},\"author\":{\"name\":\"repam@adm\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\"},\"headline\":\"Avasalladores queman casas y atemorizan con armas a ind\u00edgenas tsimanes para quitarles sus tierras\",\"datePublished\":\"2021-12-30T02:18:07+00:00\",\"dateModified\":\"2021-12-30T02:18:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\\\/\"},\"wordCount\":761,\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/indigenas-tsimanes-1.png\",\"keywords\":[\"Amazon\u00eda\",\"Avasallamientos\",\"Bolivia\",\"Derechos Humanos\",\"Pueblo Tsimane\",\"pueblos ind\u00edgenas\"],\"articleSection\":[\"Bolivia\",\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\\\/\",\"name\":\"Avasalladores queman casas y atemorizan con armas a ind\u00edgenas tsimanes para quitarles sus tierras - REPAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/indigenas-tsimanes-1.png\",\"datePublished\":\"2021-12-30T02:18:07+00:00\",\"dateModified\":\"2021-12-30T02:18:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.repam.net\\\/es\\\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/indigenas-tsimanes-1.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/indigenas-tsimanes-1.png\",\"width\":750,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avasalladores queman casas y atemorizan con armas a ind\u00edgenas tsimanes para quitarles sus tierras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"name\":\"REPAM\",\"description\":\"Red Eclesial Panamaz\u00f3nica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.repam.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#organization\",\"name\":\"REPAM\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.repam.net\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"REPAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.repam.net\\\/es\\\/#\\\/schema\\\/person\\\/0c828bf04cf1abe6016cbe752c76a033\",\"name\":\"repam@adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g\",\"caption\":\"repam@adm\"},\"sameAs\":[\"http:\\\/\\\/repam.net\"],\"url\":\"https:\\\/\\\/www.repam.net\\\/es\\\/author\\\/repamadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avasalladores queman casas y atemorizan con armas a ind\u00edgenas tsimanes para quitarles sus tierras - REPAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repam.net\/es\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\/","og_locale":"es_ES","og_type":"article","og_title":"Avasalladores queman casas y atemorizan con armas a ind\u00edgenas tsimanes para quitarles sus tierras - REPAM","og_description":"Los ind\u00edgenas Tsimanes lamentan la indiferencia del Gobierno ante los abusos que sufren por parte de los avasalladores. Por Agencia de Noticias Fides &#8211; ANF \u201cTenemos miedo\u201d, dice con tristeza don Ismael Cuata Cari, mientras relata que el pasado mes de octubre avasalladores de tierras invadieron su comunidad Jatatal en territorio Tsimane, en la Amazon\u00eda [&hellip;]","og_url":"https:\/\/www.repam.net\/es\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\/","og_site_name":"REPAM","article_published_time":"2021-12-30T02:18:07+00:00","article_modified_time":"2021-12-30T02:18:08+00:00","og_image":[{"width":750,"height":420,"url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/12\/indigenas-tsimanes-1.png","type":"image\/png"}],"author":"repam@adm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"repam@adm","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repam.net\/es\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\/#article","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\/"},"author":{"name":"repam@adm","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033"},"headline":"Avasalladores queman casas y atemorizan con armas a ind\u00edgenas tsimanes para quitarles sus tierras","datePublished":"2021-12-30T02:18:07+00:00","dateModified":"2021-12-30T02:18:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repam.net\/es\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\/"},"wordCount":761,"publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"image":{"@id":"https:\/\/www.repam.net\/es\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/12\/indigenas-tsimanes-1.png","keywords":["Amazon\u00eda","Avasallamientos","Bolivia","Derechos Humanos","Pueblo Tsimane","pueblos ind\u00edgenas"],"articleSection":["Bolivia","Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.repam.net\/es\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\/","url":"https:\/\/www.repam.net\/es\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\/","name":"Avasalladores queman casas y atemorizan con armas a ind\u00edgenas tsimanes para quitarles sus tierras - REPAM","isPartOf":{"@id":"https:\/\/www.repam.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repam.net\/es\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\/#primaryimage"},"image":{"@id":"https:\/\/www.repam.net\/es\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/12\/indigenas-tsimanes-1.png","datePublished":"2021-12-30T02:18:07+00:00","dateModified":"2021-12-30T02:18:08+00:00","breadcrumb":{"@id":"https:\/\/www.repam.net\/es\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repam.net\/es\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\/#primaryimage","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/12\/indigenas-tsimanes-1.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/12\/indigenas-tsimanes-1.png","width":750,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/www.repam.net\/es\/avasalladores-queman-casas-y-atemorizan-con-armas-a-indigenas-tsimanes-para-quitarles-sus-tierras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.repam.net\/es\/"},{"@type":"ListItem","position":2,"name":"Avasalladores queman casas y atemorizan con armas a ind\u00edgenas tsimanes para quitarles sus tierras"}]},{"@type":"WebSite","@id":"https:\/\/www.repam.net\/es\/#website","url":"https:\/\/www.repam.net\/es\/","name":"REPAM","description":"Red Eclesial Panamaz\u00f3nica","publisher":{"@id":"https:\/\/www.repam.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repam.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.repam.net\/es\/#organization","name":"REPAM","url":"https:\/\/www.repam.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","contentUrl":"https:\/\/www.repam.net\/es\/wp-content\/uploads\/2021\/11\/cropped-favicon.png","width":512,"height":512,"caption":"REPAM"},"image":{"@id":"https:\/\/www.repam.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.repam.net\/es\/#\/schema\/person\/0c828bf04cf1abe6016cbe752c76a033","name":"repam@adm","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b18234ea6de5d74563e52ca7bfdad9d2b029b514c935b38a2790717abf8f2e5f?s=96&d=mm&r=g","caption":"repam@adm"},"sameAs":["http:\/\/repam.net"],"url":"https:\/\/www.repam.net\/es\/author\/repamadm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/5848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/comments?post=5848"}],"version-history":[{"count":1,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/5848\/revisions"}],"predecessor-version":[{"id":5851,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/posts\/5848\/revisions\/5851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media\/5850"}],"wp:attachment":[{"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/media?parent=5848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/categories?post=5848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repam.net\/es\/wp-json\/wp\/v2\/tags?post=5848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}